{"id":1390311,"date":"2024-10-06T05:27:29","date_gmt":"2024-10-06T05:27:29","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-bundesliga-femenina-y-las-relaciones-de-poder-el-dominio-es-opresivo\/"},"modified":"2024-10-06T05:27:34","modified_gmt":"2024-10-06T05:27:34","slug":"la-bundesliga-femenina-y-las-relaciones-de-poder-el-dominio-es-opresivo","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-bundesliga-femenina-y-las-relaciones-de-poder-el-dominio-es-opresivo\/","title":{"rendered":"La Bundesliga femenina y las relaciones de poder: el dominio es opresivo"},"content":{"rendered":"\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"font-bold text-18 leading-17\"><strong class=\"font-bold\">Mientras que para el Bayern todo va seg\u00fan lo previsto, su mayor rival, el Wolfsburgo, tiene serias dificultades. \u00bfSe avecina un futuro aburrido para el f\u00fatbol femenino en Alemania?<\/strong><\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">2:0, 6:2, 5:1 y ahora 4:0 en desventaja: el FC Bayern contin\u00faa su racha de r\u00e9cords en la Bundesliga femenina. El campe\u00f3n alem\u00e1n sum\u00f3 doce puntos en cuatro partidos, est\u00e1 indiscutiblemente en lo m\u00e1s alto de la tabla y lleva 43 partidos de liga invicto. El equipo del entrenador Alexander Straus acert\u00f3 y es el claro favorito poco antes del choque contra su rival de toda la vida, el VfL Wolfsburg.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Porque cuando el equipo de M\u00fanich viaje al Volkswagen Arena del VfL el 12 de octubre, es posible que el primero de la clasificaci\u00f3n no se enfrente, como es habitual, al segundo clasificado. Esta temporada el l\u00edder se enfrentar\u00e1 a uno de varios perseguidores. Wolfsburg ocupa actualmente el quinto lugar.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Bayern y VfL ya est\u00e1n separados por cinco puntos. El Wolfsburgo comenz\u00f3 la temporada con un empate (3-3), luego consigui\u00f3 dos victorias y el fin de semana pasado sufri\u00f3 una derrota por 3-0 ante el Frankfurt. La capitana Alexandra Popp dio la alarma el mi\u00e9rcoles en una entrevista con el servicio de informaci\u00f3n deportiva: &#8220;Ya nos hemos dejado demasiados puntos atr\u00e1s. Esto no nos puede pasar a nosotros dadas nuestras exigencias&#8221;.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Sin embargo, estas demandas son a\u00fan menores que en a\u00f1os anteriores. El campeonato es ahora m\u00e1s un deseo que un objetivo. \u201cEl objetivo es al menos clasificarse para la Liga de Campeones\u201d, dej\u00f3 claro Popp.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Sin embargo, existe la esperanza de que el Wolfsburgo pueda hacer tropezar al Bayern en un duelo directo el 12 de octubre (a partir de las 17:45 en el teletipo en directo de t-online). Porque una victoria del Bayern podr\u00eda ser decisiva para el futuro de toda la liga. Si el equipo de Munich derrota a sus grandes rivales, el f\u00fatbol alem\u00e1n corre el riesgo de aburrirse en la carrera por el t\u00edtulo debido a la falta de competencia, lo que afectar\u00eda enormemente a la liga y a su atractivo.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El VfL Wolfsburg, que gan\u00f3 siete t\u00edtulos de liga entre 2012 y 2022, tuvo que despedirse este verano de tres jugadores famosos. El contrato de la especialista en defensa Dominique Janssen expir\u00f3 y se uni\u00f3 al Manchester United. La m\u00e1xima goleadora Ewa Pajor reforz\u00f3 al FC Barcelona. Y Lena Oberdorf, la central de control en el mediocampo, se mud\u00f3 precisamente a M\u00fanich.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El problema: el derramamiento de sangre en la plantilla amenaza con continuar el a\u00f1o que viene. La jefa de Defensa, Marina Hegering, pondr\u00e1 fin a su carrera el pr\u00f3ximo verano. Los contratos de Merle Frohms, Jule Brand, Kathrin Hendrich, Lena Lattwein, Alexandra Popp, Sveind\u00eds J\u00f3nsd\u00f3ttir, Lynn Wilms, Svenja Huth y Vivien Endemann est\u00e1n a punto de expirar. Todos los mejores jugadores del equipo del entrenador Tommy Stroot, que se hizo cargo del equipo en 2021 y supo estabilizarlo y desarrollarlo despu\u00e9s de un per\u00edodo inicial dif\u00edcil. Despu\u00e9s de todo, Stroot lo ampli\u00f3 recientemente hasta 2026, para sorpresa de muchos observadores. Tendr\u00e1 que pensar en ello en los pr\u00f3ximos meses.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Se han ocupado de varios sucesores, pero las nuevas incorporaciones, como las jugadoras nacionales Janina Minge, Sarai Linder y la ex jugadora del Bayern Lineth Beerensteyn, a\u00fan no han podido ayudar como se deseaba inicialmente. Las irregularidades y los peque\u00f1os errores obligan a las \u201clobas\u201d a quedarse atr\u00e1s una y otra vez. Un problema al que Stroot necesita urgentemente encontrar una soluci\u00f3n.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">La situaci\u00f3n es algo diferente para los otros \u201ccazadores del Bayern\u201d de Frankfurt, Leverkusen y Leipzig. Todos ellos se encuentran en medio de un fuerte desarrollo y no han tenido que aceptar ninguna salida de liderazgo. Esto tambi\u00e9n se refleja en el cuadro actual. El Eintracht Frankfurt ocupa el segundo lugar despu\u00e9s de cuatro partidos de liga con tres victorias y un empate. Lo m\u00e1s destacado: la confiada victoria por 3-0 contra el Wolfsburgo.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El Bayer Leverkusen (tercer puesto) y el Rasenballsport Leipzig (cuarto puesto), que ascendi\u00f3 hace apenas un a\u00f1o, son m\u00e1s equipos sorpresa que verdaderos competidores para el Bayern femenino. La instant\u00e1nea le parece buena. Pero sigue siendo cuestionable si podr\u00e1n mantener su desempe\u00f1o de manera consistente.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/fussball\/frauenfussball\/id_100501314\/frauen-bundesliga-und-machtverhaeltnisse-die-dominanz-ist-erdrueckend.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras que para el Bayern todo va seg\u00fan lo previsto, su mayor rival, el Wolfsburgo, tiene serias dificultades.<\/p>\n","protected":false},"author":1,"featured_media":1390312,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[230997,1407,34449,1532,81,3562,200957,4240,8762,1155,171365,39424,246,4434,46279,169836,99313,534,399,233576,47453,34450,225698,226026,48628,1643,225687,9154],"class_list":["post-1390311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-alejandro-straus","tag-alemania","tag-alexandra-popp","tag-baviera","tag-bundesliga","tag-dominio","tag-fc-bayern-de-munich","tag-femenina","tag-francfort-del-meno","tag-futbol-femenino","tag-georgia-stanway","tag-julia-gwinn","tag-las","tag-leipzig","tag-lena-oberdorf","tag-opresivo","tag-partido-de-liga","tag-poder","tag-relaciones","tag-servicio-de-informacion-deportiva","tag-supercopa","tag-svenja-huth","tag-t-en-linea","tag-titulo-de-maestro","tag-tommy-stroot","tag-vfl-wolfsburgo","tag-vw","tag-wolfsburgo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390311"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390312"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}