{"id":1390306,"date":"2024-10-06T05:16:32","date_gmt":"2024-10-06T05:16:32","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-actual-campeon-esta-bajo-ataque-barkov-y-lundell-pintaron-habilmente\/"},"modified":"2024-10-06T05:16:37","modified_gmt":"2024-10-06T05:16:37","slug":"el-actual-campeon-esta-bajo-ataque-barkov-y-lundell-pintaron-habilmente","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-actual-campeon-esta-bajo-ataque-barkov-y-lundell-pintaron-habilmente\/","title":{"rendered":"El actual campe\u00f3n est\u00e1 bajo ataque: Barkov y Lundell pintaron h\u00e1bilmente"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>El campe\u00f3n de la Copa Stanley actu\u00f3 ante el p\u00fablico canadiense. <\/p>\n<div itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:63.24999999999999%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1728191792_784_El-actual-campeon-esta-bajo-ataque-Barkov-y-Lundell-pintaron.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1728191792_784_El-actual-campeon-esta-bajo-ataque-Barkov-y-Lundell-pintaron.jpg\"\/><meta itemprop=\"width\" content=\"2000\"\/><meta itemprop=\"height\" content=\"1265\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Aleksander Barkov aloittaa 12:nnen kautensa NHL:ss\u00e4. \"\/><span class=\"caption-text\" itemprop=\"description\">Aleksander Barkov comienza su duod\u00e9cima temporada en la NHL. <!-- --> <\/span><span class=\"media-source\">ZumaWire \/ MVFOTOS<\/span><\/p>\n<\/div>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">Los Florida Panthers, actuales campeones de la Copa Stanley, terminaron la temporada de entrenamiento con una victoria por 4-2 sobre Los Angeles Kings.<\/p>\n<p class=\"paragraph\">El primer set del partido vio algunos \u00e9xitos finlandeses, cuando <strong>Alejandro Barkov<\/strong> y <strong>Ant\u00f3n Lundell<\/strong> habilidad para poner el disco en la mochila durante los juegos de poder.<\/p>\n<p class=\"paragraph\">Barkov anot\u00f3 para empatar el partido a 1-1 tras eliminar al portero de los Kings. <strong>por Darcy Kuemper<\/strong> para caf\u00e9. La ventaja de Lundell por 2-1 lleg\u00f3 desde la esquina de la porter\u00eda directamente desde el aire. El segundo pase lo acert\u00f3 Mark. <strong>Eetu Luostarinen<\/strong>.<\/p>\n<p class=\"paragraph\">El partido se disput\u00f3 en la ciudad de Quebec, Canad\u00e1.<\/p>\n<p class=\"paragraph\">&#8211; Fue una gran experiencia, elogi\u00f3 Barkov a los aficionados.<\/p>\n<p class=\"paragraph\">&#8211; S\u00e9 que ahora es s\u00f3lo la temporada de entrenamiento y a veces no querr\u00edas volar durante horas a alg\u00fan lugar, pero definitivamente para esto. Lo recordar\u00e9 durante mucho tiempo.<\/p>\n<p class=\"paragraph\">La cuenta Panthers PR se\u00f1al\u00f3 durante el partido que Barkov est\u00e1 a s\u00f3lo 34 goles de alcanzar la marca de 300 goles en la temporada regular de la NHL. Cuatro jugadores finlandeses de la NHL han alcanzado ese equilibrio.<\/p>\n<p class=\"paragraph\">La temporada de Florida comienza la noche anterior al mi\u00e9rcoles, hora finlandesa, con un partido en casa contra los Boston Bruins.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/nhl\/a\/6700840a-dcf8-4ee1-934b-d6f7a900843e\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-49<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El campe\u00f3n de la Copa Stanley actu\u00f3 ante el p\u00fablico canadiense. Aleksander Barkov comienza su duod\u00e9cima temporada en<\/p>\n","protected":false},"author":1,"featured_media":1390307,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[84803,2108,1247,5200,33004,2226,2223,3819,97,14313,1967,84914,85079,18872,138238],"class_list":["post-1390306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-24-horas","tag-actual","tag-ataque","tag-bajo","tag-barkov","tag-campeon","tag-deportes-de-invierno","tag-ejercicio-y-deportes","tag-esta","tag-habilmente","tag-hockey","tag-hockey-sobre-hielo-masculino","tag-hockey-sobre-hielo-profesional","tag-lundell","tag-pintaron"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390306"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390307"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}