{"id":1390294,"date":"2024-10-06T05:09:29","date_gmt":"2024-10-06T05:09:29","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-elegancia-esta-en-el-centro-de-muchos-aforismos-especialmente-en-la-literatura-y-el-cine\/"},"modified":"2024-10-06T05:09:36","modified_gmt":"2024-10-06T05:09:36","slug":"la-elegancia-esta-en-el-centro-de-muchos-aforismos-especialmente-en-la-literatura-y-el-cine","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-elegancia-esta-en-el-centro-de-muchos-aforismos-especialmente-en-la-literatura-y-el-cine\/","title":{"rendered":"La elegancia est\u00e1 en el centro de muchos aforismos, especialmente en la literatura y el cine."},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong><span class=\"first-letter\">do<\/span>Este es un concepto muy abstracto, por lo que abundan los aforismos y frases sobre la elegancia.<\/strong> Y hay muchas personas que han expresado su opini\u00f3n sobre el tema a lo largo del tiempo.<strong> \u00bfLa cita m\u00e1s famosa? Quiz\u00e1s el &#8220;La moda pasa, el estilo permanece&#8221; de Coco Chanel<\/strong>. Porque elegancia es precisamente estar siempre adecuado y a gusto en cada situaci\u00f3n y contexto.<\/p>\n<div id=\"wrapper_video_embed\" class=\"player_single_video_component\">\n<div id=\"divVideoPlayer\" class=\"video-sticky-box privacyAccettata\">\n<div class=\"video-sticky-box-inner\">\n<div class=\"video-sticky-box-frame-cont\">\n<div class=\"player player_video_rcs player_shortcode custom-video-sticky\" data-config=\"{&quot;newspaper&quot;:&quot;rcs&quot;,&quot;uuid&quot;:&quot;iodonna-0002411237&quot;,&quot;muted&quot;:true,&quot;blockAdv&quot;:false,&quot;ovlLogo&quot;:false,&quot;autoplay&quot;:true,&quot;watermark&quot;:false,&quot;scale&quot;:&quot;with-parent&quot;,&quot;poster&quot;:{&quot;pre&quot;:{&quot;type&quot;:&quot;bySelector&quot;,&quot;container&quot;:&quot;.player_preview&quot;,&quot;play&quot;:&quot;.play&quot;,&quot;playByContainer&quot;:true}},&quot;playerPage&quot;:&quot;tvSticky&quot;,&quot;tipo_video&quot;:&quot;articolo_ancorato&quot;}\">\n<div class=\"player_preview\">\n                                    <img decoding=\"async\" class=\"\" alt=\"Vuelve el negro: la elegancia de Letizia di Spagna, en el teatro con un vestido reciclado y low cost\" title=\"Vuelve el negro: la elegancia de Letizia di Spagna, en el teatro con un vestido reciclado y low cost\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/La-elegancia-esta-en-el-centro-de-muchos-aforismos-especialmente.webp.webp\"\/>                                    <span class=\"player_button play\"\/>\n                                <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2>Elegancia, un concepto que merece muchas frases y aforismos<\/h2>\n<p>para buscar en <strong>Treccani<\/strong>la definici\u00f3n de es \u201cLa cualidad de una persona que tiene gracia y sencillez, y que muestra cuidado y buen gusto sin caer en un refinamiento excesivo\u201d. No es casualidad que a lo largo de los siglos los personajes lo hayan personalizado. En particular los estilistas, que tienen un punto de vista muy espec\u00edfico, como <strong>Armani<\/strong> quien siempre ha sostenido que &#8220;Elegancia no es llamar la atenci\u00f3n sino ser recordada&#8221; o c\u00f3mo<strong> Crist\u00f3bal Balenciaga<\/strong> que siempre se ha centrado en &#8220;La elegancia es eliminaci\u00f3n&#8221;, as\u00ed como <strong>Enamorado<\/strong> quien afirma que \u201cla elegancia est\u00e1 hecha de inteligencia\u201d.<\/p>\n<article class=\"id-vda-article box_ed_hp_02-article eltdf-item-space hentry-pos-i hentry-home_section-i post-iiiii post type-post status-publish format-standard hentry\">\n<\/article>\n<p>Pero el tema no s\u00f3lo ha involucrado a los estilistas a lo largo de los a\u00f1os. <strong>Incluso en libros y pel\u00edculas el tema ha sido debatido a menudo, con frases que r\u00e1pidamente se volvieron ic\u00f3nicas.<\/strong><\/p>\n<h2>Frases sobre la elegancia, en libros<\/h2>\n<p>\u201c<strong>Para lograr estilo, comience por buscar claridad<\/strong>&#8220;Walt Whitman<br \/>&#8220;Una corbata bien atada es el primer paso serio en la vida&#8221;. \u00d3scar ancho<br \/>\u201c<strong>El hombre bien vestido es aquel cuya ropa nunca se nota<\/strong>William Somerset Maugham<br \/>\u201cEl estilo es la respuesta a todo\u201d Charles Bukowski<\/p>\n<p>\u201cEl estilo no se trata s\u00f3lo de lo que te pones, sino de c\u00f3mo vives\u201d Lilly Pulitzer<br \/>\u201cS\u00ed\u201d, respondi\u00f3 el Conde, aunque con un poco de vacilaci\u00f3n, \u201ca su manera. Una postura encorvada tiende a sugerir cierta pereza de car\u00e1cter, as\u00ed como falta de inter\u00e9s por los dem\u00e1s. Una postura erguida, sin embargo, confirma un sentido de autodominio y capacidad de compromiso, los cuales son propios de una princesa.&#8221; Amor Towles, <em>Un caballero en Mosc\u00fa<br \/><\/em>\u201cEs a la vez ilusorio y est\u00fapido pensar que la ropa no importa y que todos deber\u00edamos usar lo que queramos. La mayor\u00eda de la gente no se toma la ropa lo suficientemente en serio, pero nos guste o no, la ropa nos habla y tomamos decisiones basadas en el aspecto de la gente\u201d. Bruce Boyer<em><br \/><\/em><\/p>\n<p>\u201c<strong>El hombre rudo se cubre, el rico o el tonto se adorna, y el hombre elegante se viste.<\/strong>.\u201d Honor\u00e9 de Balzac<br \/>&#8220;Los modales de un hombre son un espejo en el que muestra su retrato&#8221;. Johann Wolfgang von Goethe<br \/>\u201cCualquiera puede ser heroico de vez en cuando, pero un caballero es algo que siempre debes ser\u201d. Luigi Pirandello<br \/>\u201c<strong>Uno deber\u00eda ser una obra de arte o vestir una obra de arte.<\/strong>.\u201d \u00d3scar Wilde, <em>El retrato de Dorian Gray<\/em><\/p>\n<h2>Elegancia en pel\u00edculas y series de televisi\u00f3n. Aforismos de la gran pantalla.<\/h2>\n<p>\u201cLa ropa no hace al hombre, el hombre hace la ropa\u201d. Harvey Specter en <em>Trajes<\/em><br \/>&#8220;Un caballero nunca puede tener demasiadas pajaritas&#8221;. Justin Timberlake como Sean Parker en<em> La Red Social<\/em><br \/>\u201c<strong>Un traje es la armadura del caballero moderno.<\/strong>&#8221; <em>Kingsman &#8211; El servicio secreto<\/em><br \/>&#8220;Lo que pasa con un evento de gala es que si usas corbata negra, nadie se dar\u00e1 cuenta de que est\u00e1s mal vestido&#8221;. Barney Stinson en <em>C\u00f3mo conoc\u00ed a vuestra madre<\/em><\/p>\n<p>&#8220;El estilo es una manera f\u00e1cil de decir cosas complicadas&#8221;. Jean Cocteau<br \/>&#8220;Uno finge hacer algo, o copia a alguien o a alg\u00fan maestro, hasta que puede hacerlo con confianza y facilidad en lo que se convierte en su propio estilo&#8221;. Gary Grant<\/p>\n<p class=\"all-rights-reserved\">iO Donna \u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iodonna.it\/spettacoli\/libri\/2024\/10\/06\/cose-leleganza-frasi-e-aforismi-che-la-raccontano\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>doEste es un concepto muy abstracto, por lo que abundan los aforismos y frases sobre la elegancia. Y<\/p>\n","protected":false},"author":1,"featured_media":1390295,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[135231,3365,1003,37963,15727,97,1001,5433],"class_list":["post-1390294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-aforismos","tag-centro","tag-cine","tag-elegancia","tag-especialmente","tag-esta","tag-literatura","tag-muchos"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390294"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390295"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}