{"id":1390250,"date":"2024-10-06T03:47:31","date_gmt":"2024-10-06T03:47:31","guid":{"rendered":"https:\/\/teknomers.com\/es\/trabajo-de-luto-en-la-curva-del-abanico\/"},"modified":"2024-10-06T03:47:37","modified_gmt":"2024-10-06T03:47:37","slug":"trabajo-de-luto-en-la-curva-del-abanico","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/trabajo-de-luto-en-la-curva-del-abanico\/","title":{"rendered":"Trabajo de luto en la curva del abanico"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"b-image-figure u-space-bottom-xl\">\n<div class=\"b-image image-figure u-content-separator-xxs-1-xxs-1 has-full-width\">\n<div class=\"image-wrapper\"><\/div>\n<\/p><\/div><figcaption class=\"caption-figure is-left\">Los aficionados del Werder Bremen recordaron al aficionado israel\u00ed del Werder Hersh Goldberg-Polin antes del inicio del partido contra el FC Bayern de M\u00fanich. Los aficionados decidieron conscientemente no guardar un minuto de silencio y, sobre todo, recordaron la valent\u00eda de vivir del joven de 23 a\u00f1os. (dpa\/Picture Alliance\/Sina Schuldt)<\/figcaption><\/figure>\n<p>El estadio Weser de Bremen a principios de septiembre. Los aficionados del SV Werder presentan una gran coreograf\u00eda antes del partido en casa contra el FC Bayern. En pancartas rojas y verdes se lee el mensaje: \u201cShalom, Salam, Paz. Que tu memoria sea una revoluci\u00f3n\u201d. <\/p>\n<p>En el centro, el rostro de Hersh Goldberg-Polin est\u00e1 representado en pancartas. El activista por la paz estadounidense-israel\u00ed se encontraba entre los alrededor de 240 rehenes secuestrados por Ham\u00e1s en Gaza el 7 de octubre de 2023. A finales de agosto de este a\u00f1o, casi once meses despu\u00e9s, los soldados israel\u00edes encontraron seis rehenes muertos en Rafah, entre ellos Hersh Goldberg-Polin. Ten\u00eda 23 a\u00f1os. Los aficionados en el Weserstadion recuerdan a su amigo. Hersh Goldberg-Polin era fan\u00e1tico del Hapoel Jerusalem y del Werder Bremen.<\/p>\n<h2 class=\"article-details-title\">Cuando el gran conflicto se vuelve tangible<\/h2>\n<p>&#8220;Se trataba m\u00e1s bien de celebrar la vida, celebrar a Hersh y su alegr\u00eda de vivir&#8221;, dice Arne Scholz, empleado del Werder Bremen, con especial atenci\u00f3n a los aficionados. \u201cNo guardar un minuto de silencio, sino dejar que el estadio hiciera ruido durante 90 minutos, tal como Hersh hubiera querido\u201d.<\/p>\n<p>La asociaci\u00f3n llama la atenci\u00f3n sobre los rehenes desde el 7 de octubre. Con mensajes en la pantalla del estadio y en las redes sociales. Los fan\u00e1ticos agitaron pancartas con mensajes como &#8220;Mantente fuerte, Hersh&#8221;. Se pusieron en contacto con organizaciones de derechos humanos e hicieron campa\u00f1a para obtener donaciones para las familias de las v\u00edctimas de Ham\u00e1s. <\/p>\n<p>A principios de septiembre, alrededor de 150 aficionados se reunieron frente al estadio Weser para conmemorarlo, informa Arne Scholz: \u201cEs sorprendente c\u00f3mo este conflicto tan grande y trascendental de repente se vuelve completamente humano. Que se trata simplemente de un amigo que muri\u00f3 y simplemente no volver\u00e1\u201d.<\/p>\n<h2 class=\"article-details-title\">Una delegaci\u00f3n de f\u00fatbol en Israel<\/h2>\n<p>Adem\u00e1s, el SV Werder pudo reaccionar con tanta rapidez porque su labor contra el antisemitismo est\u00e1 bien establecida. En 2007, un grupo de aficionados del Werder viaj\u00f3 a Israel para realizar una excursi\u00f3n. En los a\u00f1os siguientes, se hicieron amigos principalmente de los seguidores del Hapoel Jerusal\u00e9n. Se visitaron, organizaron talleres contra el racismo y organizaron torneos de f\u00fatbol, \u200b\u200bincluso en Cisjordania. <\/p>\n<p>Arne Scholz dice: &#8220;Y estas son relaciones que r\u00e1pidamente cobraron vida propia entre los grupos de fans, donde surgieron amistades muy duraderas&#8221;.<\/p>\n<p>Despu\u00e9s del 7 de octubre, varios grupos de aficionados de clubes alemanes expresaron su solidaridad con el Estado jud\u00edo. Varios clubes de la Bundesliga invitaron a familiares de los rehenes. Una delegaci\u00f3n alemana viaj\u00f3 a Israel con el Congreso Jud\u00edo Mundial y el DFL. <\/p>\n<h2 class=\"article-details-title\">Cooperaci\u00f3n con la comunidad jud\u00eda.<\/h2>\n<p>Sin embargo, muchas acciones tuvieron lugar fuera del ojo p\u00fablico. Por ejemplo, en el Borussia Dortmund, Daniel L\u00f6rcher, empleado del club, informa: \u201cDesarrollamos relativamente r\u00e1pido un formato en el que celebramos eventos informativos pr\u00e1cticamente privados con un activista por la paz de Israel y expertos sobre la situaci\u00f3n all\u00ed y, m\u00e1s tarde, con las familias de los rehenes. . Donde los empleados, fans y empleados de los patrocinadores pod\u00edan simplemente llamar y hacer preguntas. Y, sobre todo, pudimos hacer preguntas sin ser juzgados\u201d. <\/p>\n<p>Desde el 7 de octubre, el club ha intensificado su cooperaci\u00f3n con el monumento conmemorativo del Holocausto Yad Vashem en Jerusal\u00e9n y con los sindicatos israel\u00edes. El BVB invit\u00f3 tres veces a grupos de Israel a Dortmund y organiz\u00f3 eventos contra el antisemitismo y, desde el 7 de octubre, de forma a\u00fan m\u00e1s intensa con la comunidad jud\u00eda, afirma Daniel L\u00f6rcher: <\/p>\n<p>\u201cBueno, ya ten\u00edamos una estrecha colaboraci\u00f3n antes, pero desde entonces hemos hecho muchas cosas juntos. A peque\u00f1a escala, lo que no es p\u00fablico, no es visible. Y eso es extremadamente importante para nosotros. Porque son personas de nuestra ciudad que tienen que justificarse por algo con lo que en realidad no tienen nada que ver directamente. Y que son simplemente hostiles por el antisemitismo\u201d.<\/p>\n<h2 class=\"article-details-title\">Banderas palestinas en Dortmund<\/h2>\n<p>Pero el compromiso tambi\u00e9n genera desconfianza. En el panorama internacional de aficionados, muchos aficionados acusan al BVB de tener una postura unilateral hacia Israel. Algunos de ellos distribuyeron las im\u00e1genes de la Liga de Campeones el pasado mi\u00e9rcoles. Los seguidores del Celtic de Glasgow ondearon banderas palestinas durante su partido en Dortmund. <\/p>\n<figure class=\"b-image-figure u-space-bottom-xl\">\n<div class=\"b-image image-figure u-content-separator-xxs-1-xxs-1 has-full-width\">\n<div class=\"image-wrapper\"><img decoding=\"async\" loading=\"lazy\" class=\"internal-image\" title=\"Los aficionados del Celtic encendieron pirotecnia en el bloque de invitados de Dortmund y mostraron camisetas y banderas de Palestina Libre.\" alt=\"Los aficionados del Celtic encendieron pirotecnia en el bloque de invitados de Dortmund y mostraron camisetas y banderas de Palestina Libre.\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1728186451_744_Trabajo-de-luto-en-la-curva-del-abanico.jpg\" \/><\/div>\n<\/p><\/div><figcaption class=\"caption-figure is-left\">Algunos aficionados del Celtic escoc\u00e9s utilizaron el partido de la Liga de Campeones en Dortmund como protesta pol\u00edtica. (dpa\/Picture Alliance\/Martin Meissner)<\/figcaption><\/figure>\n<p>El recuerdo de Hersh Goldberg-Polin en Bremen tambi\u00e9n estuvo presente en las redes sociales. Los activistas pro palestinos lo demonizaron como un \u201cenemigo jud\u00edo\u201d. Y los partidarios del gobierno israel\u00ed celebraron a Goldberg-Polin como un patriota, informa el autor Monty Ott: \u201cEsto es guerra, requiere ambivalencia, requiere complejidad. Creo que mucha gente comparti\u00f3 las coreograf\u00edas de duelo de los aficionados del Werder para continuar con este sencillo posicionamiento. Si, por ejemplo, las instituciones afiliadas al gobierno israel\u00ed ahora comparten la memoria de Hersh, entonces lo encuentro notable. Hersh fue socializado como antifascista y activista por la paz. \u201cEso no encaja con los valores que sostienen gran parte del gobierno israel\u00ed\u201d.<\/p>\n<h2 class=\"article-details-title\">El estadio brinda apoyo<\/h2>\n<p>Monty Ott ha escrito junto con el periodista Ruben Gerczikow un libro sobre la pol\u00edtica de los j\u00f3venes jud\u00edos en Alemania. El t\u00edtulo: \u201cNo nos defraudaremos\u201d. En sus lecturas tambi\u00e9n hablan a los aficionados del f\u00fatbol sobre las amenazas antisemitas.<\/p>\n<p>Pero no quieren simplemente ser vistos como v\u00edctimas sin influencia, dice Ott: \u201cDesde hace a\u00f1os, el antisemitismo se ha vuelto cada vez m\u00e1s abierto y violento. Pero tengo que decir que esta sala del estadio me dio m\u00e1s apoyo. Me dio m\u00e1s oportunidades de salir. Donde tengo la sensaci\u00f3n: aqu\u00ed estoy rodeado de amigos, aqu\u00ed, en mi peque\u00f1o entorno, estoy rodeado de gente sensible al antisemitismo y al racismo.<\/p>\n<p>El f\u00fatbol seguir\u00e1 proporcionando una plataforma para conmemorar a las v\u00edctimas del 7 de octubre en los a\u00f1os venideros. Hace unos meses se fund\u00f3 en Israel un club de fans del Werder Bremen. Y podr\u00edan seguir m\u00e1s.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.deutschlandfunk.de\/israel-hamas-fussball-solidaritaet-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los aficionados del Werder Bremen recordaron al aficionado israel\u00ed del Werder Hersh Goldberg-Polin antes del inicio del partido<\/p>\n","protected":false},"author":1,"featured_media":1390251,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[63466,81,208958,19711,38,4999,29269,1602],"class_list":["post-1390250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-abanico","tag-bundesliga","tag-conflicto-de-medio-oriente","tag-curva","tag-del","tag-luto","tag-palestina","tag-trabajo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390250"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390250\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390251"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}