{"id":1390224,"date":"2024-10-06T02:59:31","date_gmt":"2024-10-06T02:59:31","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-petulante-ruso-se-quedo-con-juuse-saros-y-cambio-de-palo-ahora-me-bajo-mas-agua-al-cuello\/"},"modified":"2024-10-06T02:59:37","modified_gmt":"2024-10-06T02:59:37","slug":"el-petulante-ruso-se-quedo-con-juuse-saros-y-cambio-de-palo-ahora-me-bajo-mas-agua-al-cuello","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-petulante-ruso-se-quedo-con-juuse-saros-y-cambio-de-palo-ahora-me-bajo-mas-agua-al-cuello\/","title":{"rendered":"El petulante ruso se qued\u00f3 con Juuse Saros y cambi\u00f3 de palo &#8211; Ahora me baj\u00f3 m\u00e1s agua al cuello"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>Jaroslav Askarov acab\u00f3 en una granja. <\/p>\n<div itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:66.66666666666666%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1728183571_33_El-petulante-ruso-se-quedo-con-Juuse-Saros-y-cambio.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1728183571_33_El-petulante-ruso-se-quedo-con-Juuse-Saros-y-cambio.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2000\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Jaroslav Askarov vaihtoi Nashville Predatorsin San Jose Sharksiin. \"\/><span class=\"caption-text\" itemprop=\"description\">Jaroslav Askarov cambi\u00f3 de los Nashville Predators a los San Jose Sharks. <!-- --> <\/span><span class=\"media-source\">AOP \/ USA HOY DEPORTES<\/span><\/p>\n<\/div>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">Los San Jose Sharks enviaron al portero ruso Jaroslav Askarov a la AHL, informa el Club.<\/p>\n<p class=\"paragraph\">Los Sharks tienen dos porteros experimentados en la NHL: Mackenzie Blackwood y Vitek Van\u011b\u010dek. <a rel=\"noopener nofollow\" href=\"https:\/\/www.sportsnet.ca\/nhl\/article\/san-jose-sharks-send-goalie-yaroslav-askarov-to-ahl\/\" target=\"_blank\">Seg\u00fan Sportsnet<\/a> La lesi\u00f3n de Askarov en septiembre puede haber influido en la decisi\u00f3n de los Sharks de enviar al jugador a San Jos\u00e9 Barracuda en la AHL. Askarov ha sufrido una lesi\u00f3n en un miembro inferior.<\/p>\n<p class=\"paragraph\">Askarov se uni\u00f3 a los Sharks esta temporada procedente de los Nashville Predators. Askarov es considerado uno de los porteros m\u00e1s prometedores de la NHL, pero en los Predators el camino hacia el papel de primer portero qued\u00f3 bloqueado por culpa de Juuse Saros.<\/p>\n<p class=\"paragraph\">Askarov decidi\u00f3 decirle al Club que quiere pasar a otro Club. Nashville lo traspas\u00f3 a San Jos\u00e9 y consigui\u00f3 un delantero a cambio <strong>por David Edstrom<\/strong>19 a\u00f1os, portero <strong>Magnus Chronan<\/strong>23, y una selecci\u00f3n condicional de primera ronda para el draft de 2025.<\/p>\n<p class=\"paragraph\">Tras el traspaso, los Sharks firmaron con el jugador un contrato de dos a\u00f1os por valor de cuatro millones de d\u00f3lares. El acuerdo de pr\u00f3rroga entra en vigor en la temporada 2025-2026.<\/p>\n<p class=\"paragraph\">El portero jug\u00f3 para los Predators en dos partidos de la NHL la temporada pasada. Sud\u00f3 en 44 partidos de la temporada regular en la AHL y salv\u00f3 discos con un porcentaje de salvamento del 91,1.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/nhl\/a\/84dba9e4-1c22-4581-8d9b-44b1adcf2982\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-49<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jaroslav Askarov acab\u00f3 en una granja. Jaroslav Askarov cambi\u00f3 de los Nashville Predators a los San Jose Sharks.<\/p>\n","protected":false},"author":1,"featured_media":1390225,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[84803,552,191,5200,1571,99,8637,2223,3819,1967,84914,86890,63091,16,37103,173987,2700,865,63092],"class_list":["post-1390224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-24-horas","tag-agua","tag-ahora","tag-bajo","tag-cambio","tag-con","tag-cuello","tag-deportes-de-invierno","tag-ejercicio-y-deportes","tag-hockey","tag-hockey-sobre-hielo-masculino","tag-jugadores-de-hockey-sobre-hielo-hombres","tag-juuse","tag-mas","tag-palo","tag-petulante","tag-quedo","tag-ruso","tag-saros"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390224"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390225"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}