{"id":1383662,"date":"2024-10-01T09:34:29","date_gmt":"2024-10-01T09:34:29","guid":{"rendered":"https:\/\/teknomers.com\/es\/johan-derksen-defiende-a-wim-hof-vi-debe-intervenir-momento-de-zap\/"},"modified":"2024-10-01T09:34:34","modified_gmt":"2024-10-01T09:34:34","slug":"johan-derksen-defiende-a-wim-hof-vi-debe-intervenir-momento-de-zap","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/johan-derksen-defiende-a-wim-hof-vi-debe-intervenir-momento-de-zap\/","title":{"rendered":"Johan Derksen defiende a Wim Hof: &#8220;VI debe intervenir, momento de zap&#8221;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Como no pod\u00eda ser de otra manera: Johan Derksen defiende al mal comedor de cubitos de hielo Wim Hof. \u00bfPor qu\u00e9 Wilfred Genee siquiera le pide su opini\u00f3n? &#8220;Un verdadero momento de zapping&#8221;.<\/p>\n<div class=\"entry__thumb\">\n <span class=\"entry__thumb-description\">\u00a9 SBS<\/span> <\/div>\n<p>Johan Derksen empieza a perder importancia en el debate social sobre comportamientos inadecuados y, en el caso de Wim Hof, sobre violencia dom\u00e9stica. Johan retrata constantemente a las v\u00edctimas femeninas como vengativas. Doloroso, sobre todo porque Today Inside tiene un alcance enorme. Sin embargo, Wilfred Genee sigue pidiendo su opini\u00f3n.<\/p>\n<h2 class=\"wp-block-heading\">cubitos de hielo<\/h2>\n<p>Es blanco y negro que Wim fue condenado por agredir al hijo de su ex novia: recibi\u00f3 servicios comunitarios y una multa por ello. A Johan no le basta. \u201cEsos peri\u00f3dicos se est\u00e1n convirtiendo en una especie de canales de jugo. All\u00ed puedes llorar y te lo escriben todo\u201d, suspira. <a rel=\"nofollow noopener\" href=\"https:\/\/www.kijk.nl\/programmas\/vandaag-inside\/7fVextMmFfb\" target=\"_blank\">Hoy dentro<\/a>.<\/p>\n<p>\u201cLo vuelvo a ver con ese se\u00f1or que siempre yace en esos cubitos de hielo. Esa se\u00f1ora se ha portado mal en casa, violencia dom\u00e9stica, lo odio absolutamente, pero esa se\u00f1ora debe denunciar la violencia dom\u00e9stica a la polic\u00eda y no al Volkskrant&#8221;, afirm\u00f3 el experto en f\u00fatbol. \u00a1\u00bfEsa se\u00f1ora se port\u00f3 mal?! El mundo se puso patas arriba.<\/p>\n<h2 class=\"wp-block-heading\">llorar historia<\/h2>\n<p>Wilfred corrige a Johan, pero no est\u00e1 claro por qu\u00e9 sigue haci\u00e9ndolo sentir tan desanimado por este tipo de temas. Es extremadamente doloroso para las v\u00edctimas. Sobre esa declaraci\u00f3n dice: \u201cElla ya lo hizo, cierto, para que quede claro\u201d.<\/p>\n<p>Johan: \u201cEntonces De Volkskrant tendr\u00e1 que esperar a que se presente la demanda y hacer un informe al respecto\u201d.<\/p>\n<p>Wilfred: &#8220;No, no, ya hubo una condena en 2010&#8221;.<\/p>\n<p>Johan: \u201cS\u00ed, pero ahora toda la historia del llanto, toda la historia privada, est\u00e1 de vuelta en el Volkskrant. Hacen exactamente lo mismo que Priv\u00e9\u201d.<\/p>\n<h2 class=\"wp-block-heading\">&#8216;Es una locura&#8217;<\/h2>\n<p>Cuando Wilfred enumera todas las pruebas, Johan dice: \u201cS\u00ed, lo he le\u00eddo, Wilfred, pero al final creo que es una locura que hoy en d\u00eda la gente acuda a los medios de comunicaci\u00f3n para hacer estallar el caso\u201d.<\/p>\n<p>Wilfred: \u201cElla no quer\u00eda hacerlo hasta que se hizo la pel\u00edcula. Se enfrent\u00f3 al hecho de que hab\u00eda una pel\u00edcula sobre su vida y result\u00f3 ser una historia muy bonita sobre el loco Wim que se acuesta bajo el hielo\u201d.<\/p>\n<p>Johan: \u201cQuieres decir: simplemente tira toda tu historia a la calle en el Volkskrant, \u00a1lo escribir\u00e1n todo!\u201d<\/p>\n<h2 class=\"wp-block-heading\">Entretenimiento privado<\/h2>\n<p>Una vez m\u00e1s, Johan est\u00e1 m\u00e1s preocupado por el perpetrador que por la v\u00edctima. \u201c\u00bfNo es entretenimiento privado, jugo y chismes? (\u2026) Hay tanto odio y rencor en la gente. Se est\u00e1n cosiendo las orejas, incre\u00edble\u201d.<\/p>\n<p>En todos los dem\u00e1s medios, Wim Hof \u200b\u200b\u200b\u200bes tratado con dureza. Por ejemplo, Evert Santegoeds lo llama &#8220;polla helada&#8221; en Shownieuws y Renze Klamer considera bueno que la pel\u00edcula sobre Wim <em>en espera<\/em> ha sido establecido.<\/p>\n<h2 class=\"wp-block-heading\">momento de descarga<\/h2>\n<p>Victor Vlam, un experto en temas relacionados con VI, no entiende por qu\u00e9 Wilfred contin\u00faa planteando este tipo de temas a Johan. \u201cCada vez que Johan defiende a alguien que ha sido acusado de mala conducta, es un momento de zapping. Extremadamente aburrido y predecible\u201d, escribe. <a rel=\"nofollow\" href=\"https:\/\/x.com\/VictorVlam\/status\/1840847369828745374\">inc\u00f3gnita<\/a>.<\/p>\n<p>\u201cSi yo fuera el editor, me saltar\u00eda este tipo de temas. No es una televisi\u00f3n interesante\u201d.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.mediacourant.nl\/2024\/10\/johan-derksen-verdedigt-wim-hof-vi-moet-ingrijpen-zapmoment\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-48<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como no pod\u00eda ser de otra manera: Johan Derksen defiende al mal comedor de cubitos de hielo Wim<\/p>\n","protected":false},"author":1,"featured_media":1383663,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[1389,2188,11698,28503,6134,11697,145617,2602,17381,255849,168522],"class_list":["post-1383662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-debe","tag-defiende","tag-derksen","tag-hof","tag-intervenir","tag-johan","tag-johan-derksen","tag-momento","tag-wim","tag-wim-hof","tag-zap"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1383662"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1383663"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1383662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1383662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1383662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}