{"id":1383656,"date":"2024-10-01T09:23:41","date_gmt":"2024-10-01T09:23:41","guid":{"rendered":"https:\/\/teknomers.com\/es\/bvb-gros-piensa-en-una-carrera-como-entrenador-paralelo-a-sahin\/"},"modified":"2024-10-01T09:23:57","modified_gmt":"2024-10-01T09:23:57","slug":"bvb-gros-piensa-en-una-carrera-como-entrenador-paralelo-a-sahin","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/bvb-gros-piensa-en-una-carrera-como-entrenador-paralelo-a-sahin\/","title":{"rendered":"BVB: Gro\u00df piensa en una carrera como entrenador \u2013 paralelo a \u015eahin"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>&#8220;Sigue escribiendo cosas&#8221;. <\/p>\n<div class=\"newsBild\">\n<p>\n                                       <span>\u00a9IMAGO<\/span>\n                                    <\/p>\n<\/p><\/div>\n<p>Pascal Gro\u00df piensa en formarse como entrenador al final de su carrera profesional. \u201cEstoy muy conectado con el deporte. Por eso en alg\u00fan momento ya estoy interesado en el puesto de entrenador&#8221;, dijo el nuevo fichaje procedente del Borussia Dortmund antes del duelo de la Liga de Campeones contra el Celtic de Glasgow el martes por la tarde (21:00 horas).<\/p>\n<p><\/p>\n<p>El jugador de 33 a\u00f1os, que anteriormente jug\u00f3 en TSG Hoffenheim, Karlsruher SC, FC Ingolstadt y Brighton &#038; Hove Albion, dice que lleva mucho tiempo tomando precauciones: \u201cSigo escribiendo cosas porque, de lo contrario, las olvidas. Soy alguien que quiere aprender y trata de llevarlo todo conmigo. B\u00e1sicamente, ante todo como jugador. Pero, por supuesto, te preocupa c\u00f3mo seguir\u00e1 la vida\u201d. Su contrato con el BVB dura hasta 2026.<\/p>\n<div class=\"img-news-container\">\n<div class=\"img-news\"><img loading=\"lazy\" decoding=\"async\" class=\"innews\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/09\/1725575662_303_DFB-Gros-no-quiere-ser-el-doble-de-Kroos-Muller.jpg\" alt=\"\u00a1D\u00e9 su opini\u00f3n en el foro sobre el Borussia Dortmund!\" width=\"503\" height=\"148\"\/><\/div>\n<\/p><\/div>\n<\/p>\n<p>Incluso en el campo, el nativo de Mannheim es considerado un estratega que no teme a la responsabilidad. &#8220;Soy responsable de garantizar que tengamos el equilibrio adecuado entre defensa y ataque&#8221;, afirm\u00f3 Gro\u00df. Seg\u00fan el entrenador Nuri \u015eahin, al poco tiempo ya se ha convertido en un jugador destacado del BVB: \u201cEstoy muy feliz de que est\u00e9 con nosotros. Su influencia en nuestro juego es evidente\u201d. Los negros y amarillos pagaron 7 millones de euros por los servicios del veterano; el club nunca ha gastado tanto en un jugador mayor de 32 a\u00f1os.<\/p>\n<h2>Al igual que Gro\u00df, el entrenador del BVB, \u015eahin, tambi\u00e9n pens\u00f3 desde el principio en la carrera como entrenador<\/h2>\n<p>Existen paralelos en la planificaci\u00f3n futura con \u015eahin. Durante su activa carrera tambi\u00e9n pens\u00f3 en el trabajo de entrenador y tom\u00f3 notas desde el principio. Incluso despu\u00e9s de entrenar con Brendan Rodgers en el Liverpool FC, con quien ahora se enfrentar\u00e1 nuevamente en el duelo contra el Celtic, esta vez como colega. <\/p>\n<p><\/p>\n<p>\u201cEs un entrenador originario de Irlanda del Norte pero que tiene un toque espa\u00f1ol. Su idea del f\u00fatbol es la posesi\u00f3n del bal\u00f3n. Disfrut\u00e9 mucho de sus entrenamientos, su f\u00fatbol es muy interesante. \u00a1En aquel entonces escrib\u00ed muchas cosas para mi carrera como entrenador! Ahora nos volvemos a ver despu\u00e9s de doce a\u00f1os\u201d, inform\u00f3 \u015eahin (citado a trav\u00e9s de \u201c<a rel=\"nofollow noopener\" href=\"https:\/\/www.bild.de\/sport\/fussball\/bvb-nuri-sahin-trifft-auf-brendan-rodgers-mit-24-dachte-er-schon-an-den-trainer-job-66faad4031ae523822214f96\" target=\"_blank\">Imagen<\/a>&#8220;).<\/p>\n<p><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.transfermarkt.de\/gross-peilt-trainerlaufbahn-nach-profikarriere-an-parallelen-zu-sahin\/view\/news\/444476\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-38<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Sigue escribiendo cosas&#8221;. \u00a9IMAGO Pascal Gro\u00df piensa en formarse como entrenador al final de su carrera profesional. \u201cEstoy<\/p>\n","protected":false},"author":1,"featured_media":1383657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[3480,91533,81,83,1455,21127,440,752,22355,38197,23643,203435,4386,40625,158],"class_list":["post-1383656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-borussia-dortmund","tag-brendan-rodgers","tag-bundesliga","tag-bvb","tag-carrera","tag-celta-de-glasgow","tag-como","tag-entrenador","tag-gros","tag-nuri-sahin","tag-paralelo","tag-pascal-bruto","tag-piensa","tag-sahin","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1383656"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1383657"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1383656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1383656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1383656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}