{"id":1383359,"date":"2024-10-01T04:12:30","date_gmt":"2024-10-01T04:12:30","guid":{"rendered":"https:\/\/teknomers.com\/es\/los-motivos-de-la-nueva-estabilidad-de-la-defensa-del-bayern\/"},"modified":"2024-10-01T04:12:36","modified_gmt":"2024-10-01T04:12:36","slug":"los-motivos-de-la-nueva-estabilidad-de-la-defensa-del-bayern","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/los-motivos-de-la-nueva-estabilidad-de-la-defensa-del-bayern\/","title":{"rendered":"Los motivos de la nueva estabilidad de la defensa del Bayern"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"seitenkopf\">\n<div class=\"seitenkopf__data columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"seitenkopf__title\">\n<p class=\"metatextline\">A partir de: 30 de septiembre de 2024 16:14<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n        <strong>Mientras que al inicio de la temporada la defensa del FC Bayern era todav\u00eda una obra de construcci\u00f3n importante, ahora el campe\u00f3n r\u00e9cord se encuentra muy estable defensivamente. Pero eso no es tanto culpa de los defensores.<\/strong>\n    <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>En los \u00faltimos a\u00f1os, la estabilidad defensiva ha sido el mayor problema del FC Bayern. Esta temporada tampoco la defensa parec\u00eda nada s\u00f3lida al principio. Pero la estructura de Minjae Kim y Dayot Upamecano se ha encontrado. Esto lo demuestra el impecable desempe\u00f1o. <a rel=\"nofollow noopener\" href=\"https:\/\/www.br.de\/nachrichten\/sport\/bundesliga-topspiel-fc-bayern-bayer-leverkusen,UPfaolz\" title=\"1:1 im Topspiel gegen Bayer Leverkusen\" class=\"textlink--extern\" target=\"_blank\">1:1 en el partido principal contra el Bayer Leverkusen<\/a>.<\/p>\n<h2 id=\"FC-Bayern-Abwehr-deutlich-stabiler-als-zu-Saisonbeginn\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">La defensa del Bayern es mucho m\u00e1s estable que al inicio de la temporada<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Resumen del inicio de temporada: el Bayern tuvo uno en la primera jornada <a rel=\"nofollow noopener\" href=\"https:\/\/www.br.de\/nachrichten\/sport\/fussball-bundesliga-vfl-wolfsburg-gegen-fc-bayern-achterbahn-debuet-fuer-vincent-kompany,UMTKu6p\" title=\"1:0-F\u00fchrung beim VfL Wolfsburg aus der Hand gegeben, um letztendlich doch noch 3:2 zu gewinnen\" class=\"textlink--extern\" target=\"_blank\">El 1-0 ante el VfL Wolfsburg se perdi\u00f3 y finalmente se impuso por 3-2.<\/a>. En <a rel=\"nofollow noopener\" href=\"https:\/\/www.br.de\/nachrichten\/sport\/upamecano-und-kim-fc-bayern-hat-wieder-ein-abwehrproblem,UMXxBCg\" title=\"beiden Gegentoren sahen Minjae Kim und Dayot Upamecano\" class=\"textlink--extern\" target=\"_blank\">Ambos goles los encajaron Minjae Kim y Dayot Upamecano.<\/a> todo menos bueno, hubo otros fallos, pero no fueron castigados. El nuevo entrenador Vincent Kompany tampoco parec\u00eda haber conseguido controlar la defensa.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Thomas Tuchel y Julian Nagelsmann ya lo hab\u00edan fracasado anteriormente. Con Tuchel, Munich encaj\u00f3 un total de 45 goles. La \u00faltima vez que se permitieron m\u00e1s goles fue hace 28 a\u00f1os. Pero la primera jornada con Kompany parece haber sido s\u00f3lo un problema pasajero. En los partidos siguientes, la defensa se mantuvo firme. O los goles encajados (un total de cuatro en los \u00faltimos cinco partidos) no fueron tan importantes por la avalancha de goles (23 en total).<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>\u00bfPero por qu\u00e9 es eso? En comparaci\u00f3n con la temporada pasada, cuando Munich estaba con Tuchel, Kompany-Bayern ahora presiona mucho m\u00e1s. Quien pensaba que las grandes victorias contra Kiel, Zagreb y Bremen, es decir, contra equipos supuestamente peque\u00f1os, no ten\u00edan importancia, se equivocaba a m\u00e1s tardar en el partido principal. <a rel=\"nofollow noopener\" href=\"https:\/\/www.br.de\/nachrichten\/sport\/bundesliga-topspiel-fc-bayern-bayer-leverkusen,UPfaolz\" title=\"Denn auch gegen Bayer Leverkusen schoben die M\u00fcnchner fr\u00fch vorne drauf\" class=\"textlink--extern\" target=\"_blank\">El equipo de M\u00fanich tambi\u00e9n se adelant\u00f3 temprano ante el Bayer Leverkusen<\/a>atac\u00f3 inmediatamente despu\u00e9s de perder el bal\u00f3n y apenas permiti\u00f3 que los actuales campeones realizaran un juego ofensivo.<\/p>\n<h2 id=\"Pavlovic-und-Quarterback-Kimmich-sichern-ab\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Pavlovic y el mariscal de campo Kimmich protegen<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Mientras que en el pasado el centro del campo del FCB a veces ten\u00eda una posici\u00f3n demasiado ofensiva o simplemente no ofrec\u00eda apoyo defensivo, bajo Kompany todos tienen que defender y recuperar el bal\u00f3n. Esto es especialmente cierto en el caso de Aleksandar Pavlovic, que no s\u00f3lo brill\u00f3 contra el campe\u00f3n alem\u00e1n con el gol de sus sue\u00f1os para poner el 1-1, sino que tambi\u00e9n trabaj\u00f3 incansablemente contra el bal\u00f3n. El joven internacional jug\u00f3 16 duelos contra el Werkself y solo perdi\u00f3 cinco de ellos.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Valores que no indican autom\u00e1ticamente una actuaci\u00f3n defensiva de primer nivel, pero Pavlovic muchas veces ni siquiera necesita un duelo para llegar al bal\u00f3n. El joven de 20 a\u00f1os entiende bien el espacio y reconoce desde el principio d\u00f3nde podr\u00eda ir el bal\u00f3n. Como todo el equipo de M\u00fanich, el s\u00e1bado siempre fue un paso m\u00e1s r\u00e1pido que Florian Wirtz y compa\u00f1\u00eda.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Pavlovic cuenta con el apoyo de su compa\u00f1ero Joshua Kimmich. El nuevo capit\u00e1n del equipo DFB, <a rel=\"nofollow noopener\" href=\"https:\/\/www.br.de\/nachrichten\/sport\/bundesliga-joshua-kimmich-soll-neuer-kapitaen-von-bayern-muenchens-werden,UOSGKrn\" title=\"f\u00fcr den diese Rolle auch in M\u00fcnchen in Zukunft angedacht ist\" class=\"textlink--extern\" target=\"_blank\">para quien este papel tambi\u00e9n est\u00e1 previsto en el futuro en Munich<\/a>A \u00e9l tambi\u00e9n le ha vuelto a gustar cada vez m\u00e1s el robo de balones. Adem\u00e1s, desempe\u00f1a un papel importante en la estructura del juego. Para ello, Kimmich a veces incluso se queda atr\u00e1s de los dos defensores centrales Minjae Kim y Dayot Upamecano. Como un quarterback, inicia los movimientos de los campeones r\u00e9cord.<\/p>\n<h2 id=\"Feinste-Guardiola-Schule\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">El mejor colegio de Guardiola<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>La nueva agresividad en las partes delanteras del equipo alivia la presi\u00f3n sobre la cadena trasera. El problema de la temporada pasada, los ni\u00f1os ya no est\u00e1n bajo tanta presi\u00f3n este a\u00f1o porque las pelotas se capturan a 30 metros de su territorio. La mejor escuela de Guardiola, de la que Kompany aprendi\u00f3 mucho como jugador en el Manchester City y que ahora tambi\u00e9n puedes ver en el FC Bayern.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Esta temporada, los atacantes contrarios, excepto el VfL Wolfsburg, apenas corrieron hacia la l\u00ednea defensiva de Munich. A ello tambi\u00e9n contribuye el posicionamiento de Kimmich, que estrecha el espacio delante de la l\u00ednea defensiva.<\/p>\n<h2 id=\"Gescheiterter-Tah-Transfer-faellt-aktuell-nicht-ins-Gewicht\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">La transferencia fallida de Tah actualmente no es significativa<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Por eso, el hecho de que Jonathan Tah llevara la camiseta con la cruz del Bayer en el pecho el s\u00e1bado por la noche en el Munich Arena y no la camiseta del Oktoberfest del FC Bayern no tiene importancia en este momento. Los campeones r\u00e9cord intentaron conseguir un traspaso en verano, pero fracasaron. Incluso cedieron a Matthijs de Ligt al Manchester United. El internacional holand\u00e9s sufri\u00f3 el fin de semana una segunda derrota con los &#8216;Red Devils&#8217; por 0-3, en el cuarto partido en el que era titular ante el Tottenham Hotspur.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Por eso, contrariamente a lo que se esperaba, De Ligt no falta actualmente en M\u00fanich, sobre todo porque el nuevo fichaje Hiroki Ito tambi\u00e9n regresar\u00e1 en las pr\u00f3ximas semanas tras su fractura de metatarsiano. La situaci\u00f3n en la defensa del FC Bayern hace tiempo que no es tan relajada como ahora.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\"><em>Liderazgo de la liga y batalla por el descenso, partidos actuales, resultados y ticker en vivo, listas de m\u00e1ximos goleadores, estad\u00edsticas de kilometraje y tackles y mucho m\u00e1s: <\/em><a rel=\"nofollow noopener\" href=\"https:\/\/www.br.de\/nachrichten\/sport\/das-livecenter-von-br24-sport-ergebnisse-tabellen-live-radio,SjugGyx\" title=\"Fu\u00dfball im Ergebniscenter von BR24Sport.\" class=\"textlink--extern\" target=\"_blank\">F\u00fatbol en el centro de resultados BR24Sport.<\/a><\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Fuente: BR24Sport 30 de septiembre de 2024 &#8211; 13:54<\/p>\n<div class=\"columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"backlink\">\n                                        <a rel=\"nofollow noopener\" class=\"backlink__link\" href=\"https:\/\/www.br.de\/nachrichten\/sport\/die-gruende-fuer-die-neue-stabilitaet-des-fc-bayern-in-der-abwehr,UPqqnk8\" target=\"_blank\"><\/p>\n<div class=\"backlink__img-wrapper\"><\/div>\n<p>                                        <\/a>\n                                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sportschau.de\/regional\/br\/br-die-gruende-fuer-die-neue-stabilitaet-der-fc-bayern-abwehr-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de: 30 de septiembre de 2024 16:14 Mientras que al inicio de la temporada la defensa<\/p>\n","protected":false},"author":1,"featured_media":1383360,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[615,3275,38,10174,200957,36,22993,212],"class_list":["post-1383359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-bayern","tag-defensa","tag-del","tag-estabilidad","tag-fc-bayern-de-munich","tag-los","tag-motivos","tag-nueva"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1383359"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1383360"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1383359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1383359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1383359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}