{"id":1383317,"date":"2024-10-01T03:18:29","date_gmt":"2024-10-01T03:18:29","guid":{"rendered":"https:\/\/teknomers.com\/es\/panico-en-volkswagen-esta-en-peligro-la-economia-alemana\/"},"modified":"2024-10-01T03:18:34","modified_gmt":"2024-10-01T03:18:34","slug":"panico-en-volkswagen-esta-en-peligro-la-economia-alemana","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/panico-en-volkswagen-esta-en-peligro-la-economia-alemana\/","title":{"rendered":"P\u00e1nico en Volkswagen: \u00bfest\u00e1 en peligro la econom\u00eda alemana?"},"content":{"rendered":"\n<div>\n<p>Las cosas van mal para Volkswagen, el s\u00edmbolo de la industria automovil\u00edstica alemana. El periodista Milo van Bokkum afirma que, de todos modos, el sector est\u00e1 pasando por momentos dif\u00edciles y esto tiene graves consecuencias para decenas de miles de empleados. \u00bfEst\u00e1n temblando los cimientos de la econom\u00eda alemana?<\/p>\n<dl class=\"dmt-podcast-credits\">\n<dt>Invitado:<\/dt>\n<dd>Milo van Bokkum<\/dd>\n<dt>Presentaci\u00f3n:<\/dt>\n<dd>Egbert Kalse<\/dd>\n<dt>Editorial:<\/dt>\n<dd>Ilse Eshuis<\/dd>\n<dt>Asamblea:<\/dt>\n<dd>Misja van Waterschoot<\/dd>\n<dt>Coordinaci\u00f3n:<\/dt>\n<dd>Henk Ruigrok van der Werven<\/dd>\n<dt>Foto:<\/dt>\n<dd>Moritz Frankenberg\/AP<\/dd>\n<\/dl>\n<p><dmt-util-bar article=\"4867716\" headline=\"Paniek bij Volkswagen: is de Duitse economie in gevaar?\" url=\"https:\/\/www.nrc.nl\/nieuws\/2024\/10\/01\/paniek-bij-volkswagen-is-de-duitse-economie-in-gevaar-a4867716\"><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"share\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">para compartir<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-share-web\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"contact\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Env\u00ede un correo electr\u00f3nico al editor<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-email\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<\/dmt-util-bar> <\/p>\n<aside data-article-id=\"4867716\" data-js-topic-preview=\"\" data-topic-id=\"176\" data-topic-name=\"Duitsland\"\/>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2024\/10\/01\/paniek-bij-volkswagen-is-de-duitse-economie-in-gevaar-a4867716\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las cosas van mal para Volkswagen, el s\u00edmbolo de la industria automovil\u00edstica alemana. El periodista Milo van Bokkum<\/p>\n","protected":false},"author":1,"featured_media":1383318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2884,563,97,10455,2175,10627],"class_list":["post-1383317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-alemana","tag-economia","tag-esta","tag-panico","tag-peligro","tag-volkswagen"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1383317"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1383318"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1383317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1383317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1383317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}