{"id":1383035,"date":"2024-09-30T21:59:31","date_gmt":"2024-09-30T21:59:31","guid":{"rendered":"https:\/\/teknomers.com\/es\/informes-propuesta-de-prohibicion-de-afd-en-el-bundestag\/"},"modified":"2024-09-30T21:59:36","modified_gmt":"2024-09-30T21:59:36","slug":"informes-propuesta-de-prohibicion-de-afd-en-el-bundestag","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/informes-propuesta-de-prohibicion-de-afd-en-el-bundestag\/","title":{"rendered":"Informes: propuesta de prohibici\u00f3n de AfD en el Bundestag"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div data-testid=\"text-module\">\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"byi3ftt\">\n<div class=\"r1f6k8yy\" style=\"--r1f6k8yy-0:16\/9\"><picture class=\"slrzex8\" style=\"--slrzex8-0:var(--surface-subtle)\"><source  \/><\/picture><\/div>\n<\/div>\n<p>La supuesta iniciativa de varios miembros del Bundestag de instaurar un procedimiento para prohibir al AfD suscita reacciones mixtas.<\/p>\n<p>Fuente: dpa<\/p>\n<hr class=\"l1uat3jy d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Seg\u00fan informes de los medios, una moci\u00f3n para prohibir el AfD cuenta con el apoyo de miembros del Bundestag de diferentes facciones y suscita reacciones encontradas. Como informan un\u00e1nimemente &#8220;Welt&#8221; y &#8220;Spiegel&#8221;, se han reunido bastantes m\u00e1s de los 37 diputados necesarios para tal moci\u00f3n, concretamente del SPD, la Uni\u00f3n, los Verdes y la izquierda.<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Por lo tanto, el objetivo es solicitar al Tribunal Constitucional Federal un procedimiento para prohibir la AfD. Seg\u00fan los informes, los diputados tambi\u00e9n piden que el AfD quede excluido de la financiaci\u00f3n estatal. Seg\u00fan informaci\u00f3n de dpa, los iniciadores quieren presentar la solicitud a los grupos parlamentarios despu\u00e9s del 8 de octubre.<\/div>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"El Tribunal Constitucional de Turingia. A petici\u00f3n del grupo parlamentario de la CDU en el parlamento estatal de Turingia, aqu\u00ed se decidir\u00e1 el procedimiento posterior para la constituci\u00f3n del parlamento.\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">La primera sesi\u00f3n del parlamento estatal de Turingia fue un esc\u00e1ndalo: el AfD impidi\u00f3 una votaci\u00f3n democr\u00e1tica y la CDU acudi\u00f3 al Tribunal Constitucional. \u00bfCu\u00e1l es la situaci\u00f3n jur\u00eddica?<\/span><span class=\"m211382\">27 de septiembre de 2024 | 2:32 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>Los diputados del SPD y BSW critican la supuesta propuesta de prohibici\u00f3n<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">La presidenta de la Comisi\u00f3n de Valores B\u00e1sicos del SPD, Gesine Schwan, critic\u00f3 el supuesto proyecto. &#8220;Una solicitud de prohibici\u00f3n ser\u00eda pol\u00edticamente contraproducente&#8221;, declar\u00f3 al Tagesspiegel. \u201cEsto empujar\u00eda a los brazos del AfD a a\u00fan m\u00e1s ciudadanos que est\u00e1n poco familiarizados con las condiciones y requisitos de la democracia pluralista y, por lo tanto, no pueden identificarse con ella\u201d, advirti\u00f3.<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">El diputado Frank Sch\u00e4ffler (FDP) declar\u00f3 al peri\u00f3dico Handelsblatt que hab\u00eda que luchar pol\u00edticamente contra AfD. Los debates sobre la prohibici\u00f3n s\u00f3lo hicieron da\u00f1o porque distrajeron la atenci\u00f3n de la discusi\u00f3n pol\u00edtica.<\/div>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Jueces del Tribunal Constitucional\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">La AfD present\u00f3 recientemente una demanda porque ninguno de sus candidatos pudo ganar un puesto en las anteriores elecciones presidenciales.  <\/span><span class=\"m211382\">18 de septiembre de 2024 | 1:41 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Sahra Wagenknecht, l\u00edder del partido BSW, critic\u00f3 duramente el supuesto plan: \u201cEsta es realmente la propuesta m\u00e1s est\u00fapida del a\u00f1o\u201d, dijo al portal de noticias \u201ct-online\u201d. Wagenknecht habl\u00f3 de un \u201cregalo de campa\u00f1a electoral\u201d para AfD y enfatiz\u00f3 que BSW rechaza todas las iniciativas de prohibici\u00f3n y aboga por un debate objetivo.<\/div>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>Kiesewetter: Estoy \u201cmuy agradecido\u201d al iniciador<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Por otro lado, el miembro del Bundestag de la CDU Roderich Kiesewetter se expres\u00f3 positivamente. \u201cEstoy muy agradecido a mi colega Marco Wanderwitz por haber iniciado esto\u201d, declar\u00f3 al canal Welt TV. <\/p>\n<\/div>\n<div class=\"bbqjgdv c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r80o15e\">\n<figure>\n<blockquote class=\"b1speu17\">\n<p class=\"tosa0j6 hhhtovw\">Ninguno de los partidos del Bundestag que representan el centro democr\u00e1tico se atreve a hacerlo solo.<\/p>\n<\/blockquote><figcaption>\n<p class=\"aley63f m1lnp037\">Roderich Kiesewetter, miembro del Bundestag de la CDU<\/p>\n<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Es necesario un debate sensible sobre c\u00f3mo tratar con el AfD en el Bundestag.<\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Un polic\u00eda detiene un coche en la frontera entre Alemania y Polonia.\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">En materia de migraci\u00f3n, el sem\u00e1foro y la Uni\u00f3n se han convertido en v\u00edctimas, no solo del AfD, sino tambi\u00e9n de ataques como el de Solingen. Se necesitan soluciones r\u00e1pidas, pero dif\u00edciles de implementar.<\/span><span class=\"m211382\">15 de septiembre de 2024 | 4:03 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>El miembro del Bundestag de la CDU y ex representante del Este, Wanderwitz, no quiso hacer comentarios sobre la candidatura del grupo cuando fue preguntado por la dpa. En junio anunci\u00f3 que quer\u00eda presentar una propuesta para prohibir el AfD en el Bundestag.<\/p>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>El gobierno federal reacciona con reservas ante planes sospechosos<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>El portavoz del gobierno, Steffen Hebestreit, reaccion\u00f3 con reservas a la noticia sobre la solicitud de un procedimiento de prohibici\u00f3n. Hebestreit se refiri\u00f3 a declaraciones anteriores en las que nada hab\u00eda cambiado. S\u00f3lo el viernes dijo que se trataba de un &#8220;paso de muy largo alcance&#8221; y que el gobierno federal no ten\u00eda planes de iniciar tal prohibici\u00f3n.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">El vicecanciller Robert Habeck (Verdes) dijo el domingo por la tarde a las emisoras \u201cRtl\u201d y \u201cNtv\u201d que era necesario presentar pruebas suficientes. Sin embargo, a\u00f1adi\u00f3: <\/div>\n<\/div>\n<div class=\"bbqjgdv c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r80o15e\">\n<figure>\n<blockquote class=\"b1speu17\">\n<p class=\"tosa0j6 hhhtovw\">Si las pruebas est\u00e1n ah\u00ed, entonces s\u00ed.<\/p>\n<\/blockquote><figcaption>\n<p class=\"aley63f m1lnp037\">Robert Habeck, Vicecanciller<\/p>\n<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<h2 class=\"h1sfxk1n\"><button type=\"button\" aria-controls=\":R7dr6r57rldqptkr:\" aria-expanded=\"true\" class=\"thgvjx9 b1dlieki\" style=\"--b1dlieki-0:100%\"><span>Seg\u00fan el art\u00edculo 21 de la Ley Fundamental&#8230;<\/span><\/button><\/h2>\n<div id=\":R7dr6r57rldqptkr:\" class=\"a1n89n1m eh6zb8z\" style=\"max-height:auto;visibility:visible;opacity:1\">\n<div data-testid=\"text-module\" class=\"s1am5zo f1uhhdhr\">\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">&#8230; un partido s\u00f3lo puede ser prohibido en Alemania si quiere alterar o eliminar el &#8220;orden fundamental libre y democr\u00e1tico&#8221;. <br \/>En una sentencia de 1956, Karlsruhe pidi\u00f3 una &#8220;actitud activamente combativa-agresiva&#8221; para eliminar este orden. <br \/>Adem\u00e1s, seg\u00fan el tribunal, deben existir pruebas concretas de que alcanzar los objetivos anticonstitucionales perseguidos no parece del todo imposible.<\/p>\n<p>Fuente: AFP<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr class=\"spw82ea d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>Los cr\u00edticos advierten: el resultado en los tribunales est\u00e1 abierto<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Los cr\u00edticos advierten que el proceso ser\u00eda muy largo y el resultado en Karlsruhe ser\u00eda abierto. Tambi\u00e9n existen preocupaciones sobre la prohibici\u00f3n de un partido con una alta aprobaci\u00f3n de los votantes.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<h2 class=\"h1sfxk1n\"><button type=\"button\" aria-controls=\":R7dsmr57rldqptkr:\" aria-expanded=\"true\" class=\"thgvjx9 b1dlieki\" style=\"--b1dlieki-0:100%\"><span>ZDFheute en WhatsApp<\/span><\/button><\/h2>\n<div id=\":R7dsmr57rldqptkr:\" class=\"a1n89n1m eh6zb8z\" style=\"max-height:auto;visibility:visible;opacity:1\">\n<div data-testid=\"text-module\" class=\"s1am5zo f1uhhdhr\">\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:0 &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"ff6tzbu\" style=\"--ff6tzbu-0:right;--ff6tzbu-1:var(--vertical-content-padding) 0 16px 24px\">\n<div class=\"b1v6qgyj\">\n<div class=\"r1f6k8yy\" style=\"--r1f6k8yy-0:16\/9\"><picture class=\"slrzex8\" style=\"--slrzex8-0:var(--surface-subtle)\"><source  \/><img src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/Baerbock-renuncia-a-su-candidatura-a-canciller.png\"  alt=\"Una persona sostiene un tel\u00e9fono inteligente en la mano. En \u00e9l se puede ver el canal de WhatsApp de ZDFheute.\" decoding=\"async\" loading=\"eager\"  style=\"object-fit:cover;object-position:center\" class=\"f1mqliu0\"\/><\/picture><\/div>\n<\/div>\n<p>Fuente: ZDF<\/p>\n<hr class=\"l1ekoa6b d19t6vpa\"\/><\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">\u00bfQuieres estar siempre actualizado? Entonces has venido al lugar correcto con nuestro canal de WhatsApp ZDFheute. Ya sea para tomar un caf\u00e9 por la ma\u00f1ana, para el almuerzo o al final del d\u00eda, lo conseguir\u00e1s. <strong>las noticias m\u00e1s importantes directamente en tu smartphone<\/strong>. Participa en encuestas o insp\u00edrate con nuestro minipodcast \u201cShort Time Out\u201d. Simplemente reg\u00edstrese en nuestro canal de WhatsApp aqu\u00ed: <a rel=\"nofollow noopener\" data-testid=\"richtext-link\" href=\"https:\/\/whatsapp.com\/channel\/0029VaDL1i89cDDZkGqJRr2S\" target=\"_blank\" class=\"b7kurox\">Canal WhatsApp de ZDFheute<\/a>.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr class=\"spw82ea d19t6vpa\"\/><\/div>\n<p><span class=\"t1fikfz9 tsdggcs\">Fuente: <!-- -->dpa, AFP, Reuters<\/span><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.zdf.de\/nachrichten\/politik\/deutschland\/afd-verbot-verfahren-bundestag-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-39<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La supuesta iniciativa de varios miembros del Bundestag de instaurar un procedimiento para prohibir al AfD suscita reacciones<\/p>\n","protected":false},"author":1,"featured_media":1383036,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[21024,19989,2932,814,862],"class_list":["post-1383035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-afd","tag-bundestag","tag-informes","tag-prohibicion","tag-propuesta"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1383035"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1383035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1383036"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1383035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1383035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1383035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}