{"id":1375240,"date":"2024-09-25T06:24:22","date_gmt":"2024-09-25T06:24:22","guid":{"rendered":"https:\/\/teknomers.com\/es\/abuso-infantil-en-la-escuela-helmond-asi-se-habla-con-su-hijo\/"},"modified":"2024-09-25T06:24:27","modified_gmt":"2024-09-25T06:24:27","slug":"abuso-infantil-en-la-escuela-helmond-asi-se-habla-con-su-hijo","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/abuso-infantil-en-la-escuela-helmond-asi-se-habla-con-su-hijo\/","title":{"rendered":"Abuso infantil en la escuela Helmond: as\u00ed se habla con su hijo"},"content":{"rendered":"\n<p>Los padres quieren mantener a sus hijos seguros, pero \u00bfqu\u00e9 hacer si hay abuso sexual por parte de un empleado en la escuela de su hijo o hija, como en el centro infantil Mondomijn en Helmond? \u201cDeje que sus emociones se calmen antes de hablar de ello con su hijo\u201d, aconseja la psic\u00f3loga Marielle Balledux del Instituto Holand\u00e9s de la Juventud (NJi).<\/p>\n<div>\n<p>El caso de Helmond sali\u00f3 a la luz recientemente tras una denuncia de padres sobre abuso sexual. Se dice que el profesor asistente, que hab\u00eda trabajado all\u00ed durante a\u00f1os, abus\u00f3 sexualmente de una ni\u00f1a menor de edad. Despu\u00e9s de eso, llegaron m\u00e1s informes de otros padres. <\/p>\n<p>El hombre fue arrestado a principios de este mes, pero los padres de los ni\u00f1os de la escuela, l\u00f3gicamente, est\u00e1n preocupados. \u201cEs l\u00f3gico que los padres tengan preguntas. Tambi\u00e9n es muy bueno iniciar una conversaci\u00f3n con tu hijo\u201d, afirma Balledux.<\/p>\n<p><strong>No ignores el tema<\/strong><br \/>\u201cNo se debe ignorar el tema. Al fin y al cabo, tambi\u00e9n se habla de ello en el colegio. Pero como padre, \u00bfes usted consciente de sus propias emociones? La primera reacci\u00f3n primaria suele ser p\u00e1nico o ira&#8221;, afirma el psic\u00f3logo. <\/p>\n<p>&#8220;Primero intenta controlar esas emociones hablando de ello con otros adultos, por ejemplo con tu pareja, tu novio o tu novia. S\u00f3lo entonces inicia la conversaci\u00f3n con tu hijo&#8221;.<\/p>\n<p>Puede decirles a sus hijos que est\u00e1 en shock, pero aseg\u00farese de que la primera emoci\u00f3n primaria desaparezca. \u201cDe lo contrario, su hijo podr\u00eda cerrarse. A menudo tratan de mantener el miedo alejado de sus padres, por lo que es menos probable que te lo cuenten\u201d.<\/p>\n<p><strong>Haga preguntas abiertas a su hijo<\/strong><br \/>Balledux aconseja hacer preguntas abiertas. Entonces no: &#8216;\u00bfTambi\u00e9n abusaste de ti?&#8217; Pero: &#8216;\u00bfC\u00f3mo estuvo la escuela hoy?&#8217; Balledux: &#8220;\u00bfO de qu\u00e9 hablaste en clase y qu\u00e9 escuchaste o viste? \u00bfReconoces lo que pas\u00f3? As\u00ed que haz preguntas en las que tu hijo te cuente lo que est\u00e1 pasando&#8221;. <\/p>\n<p>Si su hijo es una v\u00edctima, es importante que los padres no se enojen por sus emociones. \u201cEs posible que a menudo hayas advertido a tu hijo sobre los hombres extra\u00f1os, pero al final tu hijo no puede hacer nada al respecto. As\u00ed que apoye a su hijo. Trate de mantener sus emociones fuertes alejadas de ellos. Tambi\u00e9n observe atentamente el rostro de su hijo durante la conversaci\u00f3n. \u00bfC\u00f3mo reacciona? Si un ni\u00f1o evita las preguntas, a menudo es una se\u00f1al de que est\u00e1n sucediendo m\u00e1s cosas\u201d.<\/p>\n<p><strong>T\u00f3mate el tiempo para la conversaci\u00f3n.<br \/><\/strong>Es importante que se tome el tiempo para conversar y que le haga saber a su hijo que puede volver a ella m\u00e1s adelante. \u201cLos ni\u00f1os tienen un patr\u00f3n de tiempo diferente al de los adultos. Existe la posibilidad de que de repente quieran hablar de ello por la noche\u201d.<\/p>\n<p>Un ni\u00f1o de 7 a\u00f1os tambi\u00e9n tiene una experiencia diferente que un ni\u00f1o de 12 a\u00f1os, pero se les pueden hacer las mismas preguntas, seg\u00fan el psic\u00f3logo. &#8220;Ellos dar\u00e1n una respuesta apropiada para la edad&#8221;. <\/p>\n<p>Tambi\u00e9n es importante: la vida contin\u00faa. Atr\u00e9vete a dejar ir a tu hijo. \u201cNo los dejes en casa. D\u00e9jalos jugar afuera. No tienes que hablar del abuso todo el d\u00eda. Si sigue teniendo miedo como padre, busque ayuda usted mismo. Por ejemplo, a trav\u00e9s de la escuela, a trav\u00e9s del tel\u00e9fono de padres o a trav\u00e9s de la plataforma para v\u00edctimas Helpwanted\u201d.<\/p>\n<p><strong>ESCRIBIMOS ESTO ANTES:<\/strong><\/p>\n<p>  Comportamiento transgresor en el Centro Infantil: &#8216;Pon en marcha con la mayor normalidad posible&#8217;<\/p>\n<p>  La polic\u00eda investiga el comportamiento inapropiado de un asistente de ense\u00f1anza<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.omroepbrabant.nl\/nieuws\/4558093\/kindermisbruik-op-school-helmond-zo-praat-je-daarover-met-je-kind\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-32<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los padres quieren mantener a sus hijos seguros, pero \u00bfqu\u00e9 hacer si hay abuso sexual por parte de<\/p>\n","protected":false},"author":1,"featured_media":1375241,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3202,1656,99,2745,1364,2630,11599,1737,7093],"class_list":["post-1375240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-abuso","tag-asi","tag-con","tag-educacion","tag-escuela","tag-habla","tag-helmond","tag-hijo","tag-infantil"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1375240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1375240"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1375240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1375241"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1375240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1375240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1375240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}