{"id":1375145,"date":"2024-09-25T04:43:29","date_gmt":"2024-09-25T04:43:29","guid":{"rendered":"https:\/\/teknomers.com\/es\/enfermedades-raras-la-ataxia-de-friedreich-es-una-enfermedad-neurodegenerativa-hereditaria-que-en-el-75-de-los-casos-se-diagnostica-entre-los-5-y-los-18-anos\/"},"modified":"2024-09-25T04:43:34","modified_gmt":"2024-09-25T04:43:34","slug":"enfermedades-raras-la-ataxia-de-friedreich-es-una-enfermedad-neurodegenerativa-hereditaria-que-en-el-75-de-los-casos-se-diagnostica-entre-los-5-y-los-18-anos","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/enfermedades-raras-la-ataxia-de-friedreich-es-una-enfermedad-neurodegenerativa-hereditaria-que-en-el-75-de-los-casos-se-diagnostica-entre-los-5-y-los-18-anos\/","title":{"rendered":"Enfermedades raras, la Ataxia de Friedreich es una enfermedad neurodegenerativa hereditaria que en el 75% de los casos se diagnostica entre los 5 y los 18 a\u00f1os."},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><span class=\"first-letter\">EL<\/span>y enfermedades raras <strong>Hay aproximadamente 10.000 conocidos y diagnosticados.<\/strong>. Estos son los datos reportados por<a rel=\"nofollow noopener\" href=\"https:\/\/www.osservatoriomalattierare.it\/\" data-wpel-link=\"external\" target=\"_blank\">Observatorio de Enfermedades Raras<\/a>. Entre estos tambi\u00e9n hay <strong>la ataxia de Friedreich,<\/strong> una enfermedad neurodegenerativa rara y hereditaria, que <strong>en el 75% de los casos se diagnostica entre los 5 y 18 a\u00f1os<\/strong> y que afecta aproximadamente a 15.000 personas en todo el mundo.<\/p>\n<div id=\"wrapper_video_embed\" class=\"player_single_video_component\">\n<div id=\"divVideoPlayer\" class=\"video-sticky-box privacyAccettata\">\n<div class=\"video-sticky-box-inner\">\n<div class=\"video-sticky-box-frame-cont\">\n<div class=\"player player_video_rcs player_shortcode custom-video-sticky\" data-config=\"{&quot;newspaper&quot;:&quot;rcs&quot;,&quot;uuid&quot;:&quot;iodonna-0002403891&quot;,&quot;muted&quot;:true,&quot;blockAdv&quot;:false,&quot;ovlLogo&quot;:false,&quot;autoplay&quot;:true,&quot;watermark&quot;:false,&quot;scale&quot;:&quot;with-parent&quot;,&quot;poster&quot;:{&quot;pre&quot;:{&quot;type&quot;:&quot;bySelector&quot;,&quot;container&quot;:&quot;.player_preview&quot;,&quot;play&quot;:&quot;.play&quot;,&quot;playByContainer&quot;:true}},&quot;playerPage&quot;:&quot;tvSticky&quot;,&quot;tipo_video&quot;:&quot;articolo_ancorato&quot;}\">\n<div class=\"player_preview\">\n                                    <img decoding=\"async\" class=\"\" alt=\"Salud mental y adolescentes: 7 libros que les ayudan\" title=\"Salud mental y adolescentes: 7 libros que les ayudan\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/09\/Como-afrontar-la-adolescencia-quotsilenciosoquot-de-un-nino-varon-Los.webp.webp\"\/>                                    <span class=\"player_button play\"\/>\n                                <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2>Enfermedades raras y Ataxia de Friedreich: que es<\/h2>\n<p>&#8220;EL <strong>Los s\u00edntomas iniciales aparecen principalmente durante la adolescencia.<\/strong> y se caracterizan por <strong>debilidad, p\u00e9rdida de coordinaci\u00f3n, fatiga y dificultad con el equilibrio<\/strong>. El curso es debilitante y <strong>en 10-20 a\u00f1os, en la mayor\u00eda de los casos, es necesario el uso de silla de ruedas<\/strong>. A medida que avanza la enfermedad aparecen otros s\u00edntomas como problemas de visi\u00f3n, p\u00e9rdida de audici\u00f3n, dificultad para hablar, escoliosis, diabetes mellitus\u201d, explica el Doctor. <strong>caterina mariotti<\/strong>Neur\u00f3logo, Jefe de Gen\u00e9tica M\u00e9dica del<a rel=\"nofollow noopener\" href=\"https:\/\/www.istituto-besta.it\/\" data-wpel-link=\"external\" target=\"_blank\">Instituto Carlo Besta de Mil\u00e1n<\/a>.<\/p>\n<article class=\"id-vda-article box_ed_hp_02-article eltdf-item-space hentry-pos-i hentry-home_section-i post-iiiii post type-post status-publish format-standard hentry\">\n<\/article>\n<h2>D\u00eda Mundial de la Ataxia: el programa \u201c\u00a1Res\u00edgnate! Bailo con Friedreich&#8221;<\/h2>\n<p>Para crear conciencia sobre esta rara enfermedad, <strong>con motivo del D\u00eda Mundial de la Ataxia que se celebra el 25 de septiembre <\/strong>comienza all\u00ed<strong> campa\u00f1a de informaci\u00f3n<\/strong> <strong>\u201c<a rel=\"nofollow noopener\" href=\"https:\/\/www.atassia.it\/articoli\/\" data-wpel-link=\"external\" target=\"_blank\">\u00a1Res\u00edgnate! Bailo con Friedreich&#8221;<\/a><\/strong>creado por Biogen con el patrocinio de AISA ODV, la Asociaci\u00f3n Italiana para la lucha contra los S\u00edndromes At\u00e1xicos.<\/p>\n<p>En el coraz\u00f3n del proyecto se encuentra un<strong> docufilm, protagonizado por 4 pacientes y la implicaci\u00f3n de la actriz Vittoria Belvedere<\/strong>quien como madre de tres adolescentes quiso dar su aporte para arrojar luz sobre la vida de los j\u00f3venes que enfrentan esta compleja y dram\u00e1tica enfermedad.<\/p>\n<p><iframe loading=\"lazy\" title=\"Atassia di Friedreich, impatto sulla qualit\u00e0 di vita e ruolo dell\u2019Associazione pazienti AISA\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/odkPZO7E76g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h2>Enfermedades raras: esperanza para los pacientes j\u00f3venes<\/h2>\n<p>\u00abComo Asociaci\u00f3n esperamos que esta campa\u00f1a sea <strong>el primer paso para levantar el tel\u00f3n sobre una enfermedad rara que pone patas arriba la vida de j\u00f3venes y adolescentes<\/strong> y que ha permanecido pr\u00e1cticamente inaudita hasta hoy. Quienes viven con ataxia de Friedreich no se dan por vencidos. <strong>El cuerpo desaprende, pero la mente sigue avanzando y con ella avanza la determinaci\u00f3n de mirar hacia el futuro.<\/strong> con intensidad. De aqu\u00ed proviene la met\u00e1fora central de la campa\u00f1a: <strong>\u201cBailando con Friedreich\u201d es el s\u00edmbolo de la ligereza y plenitud de la vida.<\/strong>que la enfermedad no puede borrar&#8221;, comenta el profesor <strong>Mar\u00eda Litani<\/strong>Presidente Nacional de AISA ODV.<\/p>\n<h2>Vittoria Belvedere protagonista del documental que cuenta la historia de la enfermedad<\/h2>\n<p>El documental ser\u00e1 transmitido <strong>estreno el 19 de octubre a las 17.30 h en LA7d<\/strong> y luego estar\u00e1 disponible en streaming en el portal Rivedila7. Tambi\u00e9n estar\u00e1n al aire las voces de los 4 protagonistas <strong>un anuncio de radio en Radio Capital <\/strong>y sus historias ser\u00e1n contadas en l\u00ednea en <strong>Canales sociales de Biogen y AISA<\/strong>.<\/p>\n<div id=\"attachment_736643\" data-thumbnail_id=\"736643\" class=\"wp-caption aligncenter\" style=\"width:970px\"><picture class=\"lozad\"><source  type=\"image\/jpeg\"\/><\/picture>\n<p class=\"wp-caption-text\">Vittoria Belvedere (foto Fabio Lovino \/ Contrasto)<\/p>\n<\/div>\n<p>\u00abDar voz a las historias de estos j\u00f3venes <strong>fue una experiencia incre\u00edble<\/strong>. Sus palabras transmiten pasi\u00f3n, el deseo de no detenerse ante los muros que la vida pone delante y de bailar con la vida. <strong>Son un ejemplo extraordinario para todos nosotros.<\/strong>\u00bb, concluye <strong>Victoria Belvedere<\/strong>.<\/p>\n<p class=\"all-rights-reserved\">iO Donna \u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iodonna.it\/benessere\/salute-e-psicologia\/2024\/09\/25\/malattie-rare-atassia-di-friedreich-la-campagna-che-racconta-i-giovani\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ELy enfermedades raras Hay aproximadamente 10.000 conocidos y diagnosticados.. Estos son los datos reportados porObservatorio de Enfermedades Raras.<\/p>\n","protected":false},"author":1,"featured_media":1375147,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[205,255129,1756,98333,3019,12955,372,255130,169689,36,255131,10993,158],"class_list":["post-1375145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-anos","tag-ataxia","tag-casos","tag-diagnostica","tag-enfermedad","tag-enfermedades","tag-entre","tag-friedreich","tag-hereditaria","tag-los","tag-neurodegenerativa","tag-raras","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1375145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1375145"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1375145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1375147"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1375145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1375145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1375145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}