{"id":1374825,"date":"2024-09-24T23:26:19","date_gmt":"2024-09-24T23:26:19","guid":{"rendered":"https:\/\/teknomers.com\/es\/disparos-durante-una-discusion-en-den-bosch-emergen-imagenes-de-la-camara\/"},"modified":"2024-09-24T23:26:23","modified_gmt":"2024-09-24T23:26:23","slug":"disparos-durante-una-discusion-en-den-bosch-emergen-imagenes-de-la-camara","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/disparos-durante-una-discusion-en-den-bosch-emergen-imagenes-de-la-camara\/","title":{"rendered":"Disparos durante una discusi\u00f3n en Den Bosch, emergen im\u00e1genes de la c\u00e1mara"},"content":{"rendered":"\n<p>Han aparecido im\u00e1genes de c\u00e1maras de seguridad del presunto tiroteo ocurrido el lunes por la noche en Den Bosch. Se oyen explosiones y se ve a un grupo de hombres corriendo unos detr\u00e1s de otros por Herman Moerkerkplein hacia Korte Waterstraat. Se produce entonces una pelea, como se puede ver en las im\u00e1genes.<\/p>\n<div>\n<p>La polic\u00eda arrest\u00f3 a tres hombres el lunes por la noche despu\u00e9s de recibir un informe de un tiroteo. Los testigos hab\u00edan visto a varias personas huir despu\u00e9s de los disparos y dijeron que tambi\u00e9n hab\u00eda alguien tirado en el suelo. Cuando lleg\u00f3 la polic\u00eda, no encontraron a la v\u00edctima por ning\u00fan lado, pero los agentes encontraron varios casquillos de bala en la calle. Poco despu\u00e9s arrestaron a tres hombres moldavos de 20, 21 y 25 a\u00f1os. Uno de ellos result\u00f3 gravemente herido en la cabeza. <\/p>\n<p><strong>Los transe\u00fantes se sorprenden <\/strong><br \/>Dumpert comparte ahora im\u00e1genes de la velada en cuesti\u00f3n. El v\u00eddeo muestra a Herman Moerkerkplein poco antes de las nueve y media de la noche. En ese momento, un hombre y una mujer desprevenidos est\u00e1n sentados en las escaleras de la plaza, mientras de fondo suena un alboroto. <\/p>\n<p>Se oye un grito y acto seguido se oye un golpe. Las dos personas miran alarmadas, tras lo cual cinco chicos pasan corriendo uno tras otro. Mientras tanto, suenan dos explosiones m\u00e1s. <\/p>\n<p><strong>Pelearse<\/strong><br \/>Los chicos llegan a Korte Waterstraat, donde se produce una pelea. Tambi\u00e9n se oyen gritos en lenguaje ininteligible. El hombre sentado en la plaza decide entonces echar un vistazo y posiblemente hablar con los hombres. Porque un momento despu\u00e9s puedes ver que tres de los hombres huyen despotricando. El hombre que intervino en el disturbio vuelve a sentarse tranquilamente en la plaza.<\/p>\n<p><strong>TAMBI\u00c9N QUIERES LEER ESTO: <\/strong><\/p>\n<p>  Ni\u00f1os en una terraza vieron a un hombre ensangrentado caminando tras el tiroteo<\/p>\n<p>La investigaci\u00f3n policial muestra que las explosiones no provinieron de un arma de fuego real, sino que s\u00f3lo se dispararon cartuchos explosivos. Queda por ver si la sangre que hab\u00eda en la calle acab\u00f3 all\u00ed como consecuencia de la pelea.<\/p>\n<p>La polic\u00eda no quiere decir si las im\u00e1genes son conocidas y si ser\u00e1n incluidas en la investigaci\u00f3n. Un portavoz de la polic\u00eda no puede confirmar si las im\u00e1genes de la c\u00e1mara est\u00e1n relacionadas con el caso, pero parece que s\u00ed. Las im\u00e1genes fueron tomadas alrededor de las nueve y media de la noche, exactamente a la hora y en el lugar donde se escucharon las explosiones.   <\/p>\n<p><em>Mira a <\/em><a rel=\"nofollow noopener\" href=\"https:\/\/www.dumpert.nl\/item\/100103798_643c1557\" target=\"_blank\"> <em>aqu\u00ed <\/em><\/a><em>las im\u00e1genes de Dumpert<\/em><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.omroepbrabant.nl\/nieuws\/4558112\/schoten-gelost-bij-ruzie-in-den-bosch-camerabeelden-duiken-op\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-32<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Han aparecido im\u00e1genes de c\u00e1maras de seguridad del presunto tiroteo ocurrido el lunes por la noche en Den<\/p>\n","protected":false},"author":1,"featured_media":1373618,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[17497,3238,204202,3539,1692,25853,885,78513,1462,158],"class_list":["post-1374825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-bosch","tag-camara","tag-crimen-y-delincuencia","tag-den","tag-discusion","tag-disparos","tag-durante","tag-emergen","tag-imagenes","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1374825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1374825"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1374825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1373618"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1374825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1374825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1374825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}