{"id":1371999,"date":"2024-09-22T20:28:19","date_gmt":"2024-09-22T20:28:19","guid":{"rendered":"https:\/\/teknomers.com\/es\/austria-disturbios-de-aficionados-en-el-derbi-de-viena-lanzamiento-de-petardos\/"},"modified":"2024-09-22T20:28:24","modified_gmt":"2024-09-22T20:28:24","slug":"austria-disturbios-de-aficionados-en-el-derbi-de-viena-lanzamiento-de-petardos","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/austria-disturbios-de-aficionados-en-el-derbi-de-viena-lanzamiento-de-petardos\/","title":{"rendered":"Austria: Disturbios de aficionados en el derbi de Viena: lanzamiento de petardos"},"content":{"rendered":"\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"font-bold text-18 leading-17\">El duelo entre Austria y Rapid Viena siempre es explosivo. El domingo, sin embargo, se produjeron disturbios desagradables.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Despu\u00e9s del derbi urbano entre el Rapid y el Austria de Viena estallaron disturbios. Tras la victoria del Rapid por 2-1, los aficionados de ambos equipos irrumpieron en el campo y estallaron peleas. Anteriormente, los seguidores de Austria habr\u00edan lanzado petardos en direcci\u00f3n a la vecina Rapid East Stand. Tambi\u00e9n se dice que las balas volaron desde las filas de los fan\u00e1ticos del Rapid.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Seg\u00fan los medios, la polic\u00eda intervino tarde y al menos una persona result\u00f3 herida.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El entrenador del Rapid, Robert Klau\u00df, conden\u00f3 los hechos. &#8220;Son im\u00e1genes que no queremos ver; perjudican nuestra percepci\u00f3n exterior&#8221;, afirma el alem\u00e1n de 39 a\u00f1os. Dado que el Rapid est\u00e1 &#8220;bajo libertad condicional&#8221; despu\u00e9s de los incidentes del derbi del pasado mes de febrero, existe el riesgo de que se le resten puntos, afirm\u00f3 el ex entrenador del 1. FC Nuremberg. En ese momento, algunos profesionales del Rapid corearon insultos hom\u00f3fobos a la afici\u00f3n.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Para el seleccionador de Austria, Stephan Helm, es &#8220;impactante que se produzcan disturbios as\u00ed en un pa\u00eds como Austria. De hecho, no s\u00f3lo no puedes venir con tu familia a un evento as\u00ed, sino que hay que tener miedo&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/fussball\/international\/id_100495002\/oesterreich-fan-ausschreitungen-bei-wiener-stadtderby-boeller-geworfen.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El duelo entre Austria y Rapid Viena siempre es explosivo. El domingo, sin embargo, se produjeron disturbios desagradables.<\/p>\n","protected":false},"author":1,"featured_media":1372000,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[515,626,55071,2384,254742,58790,8997,54246,10766,17806,1152,628,625],"class_list":["post-1371999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-aficionados","tag-austria","tag-austria-viena","tag-derbi","tag-derbi-urbano","tag-disturbio","tag-disturbios","tag-explosividad","tag-lanzamiento","tag-petardos","tag-policia","tag-viena","tag-viena-rapida"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1371999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1371999"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1371999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1372000"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1371999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1371999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1371999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}