{"id":1371771,"date":"2024-09-22T15:54:19","date_gmt":"2024-09-22T15:54:19","guid":{"rendered":"https:\/\/teknomers.com\/es\/harris-y-trump-competiran-entre-si-en-un-segundo-duelo-televisivo-kamala-harris-estaria-lista\/"},"modified":"2024-09-22T15:54:23","modified_gmt":"2024-09-22T15:54:23","slug":"harris-y-trump-competiran-entre-si-en-un-segundo-duelo-televisivo-kamala-harris-estaria-lista","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/harris-y-trump-competiran-entre-si-en-un-segundo-duelo-televisivo-kamala-harris-estaria-lista\/","title":{"rendered":"\u00bfHarris y Trump competir\u00e1n entre s\u00ed en un segundo duelo televisivo? Kamala Harris estar\u00eda lista"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>La candidata presidencial dem\u00f3crata Kamala Harris ha aceptado oficialmente otro duelo televisivo contra su oponente republicano Donald Trump, pero no est\u00e1 claro si esto realmente se llevar\u00e1 a cabo.<\/p>\n<div>\n<p>&#8220;La vicepresidenta Harris est\u00e1 lista para otra oportunidad de compartir escenario con Donald Trump y acept\u00f3 la invitaci\u00f3n de CNN a un debate el 23 de octubre&#8221;, dijo su campa\u00f1a en un comunicado.<\/p>\n<p>Trump ha rechazado hasta ahora otro duelo televisivo y reiter\u00f3 esta postura tras la confirmaci\u00f3n de Harris en CNN. &#8220;Ella ha estado en un debate. Yo he tenido dos&#8221;, dijo durante una aparici\u00f3n de campa\u00f1a en el estado de Carolina del Norte. &#8220;Es demasiado tarde para otro debate. Me gustar\u00eda hacerlo en muchos sentidos, pero ya es demasiado tarde&#8221;.<!-- sh_cad_2 --><\/p>\n<p>Los dos tuvieron un acalorado intercambio de golpes el 10 de septiembre durante un duelo televisivo presentado por ABC: el dem\u00f3crata arrincon\u00f3 repetidamente al republicano. En una encuesta r\u00e1pida de CNN, el 63 por ciento de los encuestados la vio como la ganadora, en comparaci\u00f3n con el 37 por ciento de Trump. El expresidente, sin embargo, afirm\u00f3 que hab\u00eda ganado el debate televisivo.<\/p>\n<p>Posteriormente, Harris exigi\u00f3 un segundo duelo, pero Trump anunci\u00f3 que ya no quer\u00eda participar en m\u00e1s debates. Destac\u00f3 que ya hab\u00eda librado un primer duelo televisivo contra el anterior candidato presidencial dem\u00f3crata Joe Biden y luego un segundo contra Harris.<!-- sh_cad_4 --><\/p>\n<p>\u201cSer\u00eda algo sin precedentes en la historia moderna que solo hubiera un debate en las elecciones presidenciales\u201d, argumenta el equipo de campa\u00f1a de Harris. El argumento es que los votantes merecen otro duelo televisivo para tener una idea de las \u201cvisiones en competencia para Estados Unidos\u201d.\n<\/p>\n<p>\/gei\/DP\/\u00e9l<\/p>\n<p>WASHINGTON (dpa-AFX)<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/us-wahlkampf-treten-harris-und-trump-in-zweitem-tv-duell-gegeneinander-an-kamala-harris-waere-bereit-13861188\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-28<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La candidata presidencial dem\u00f3crata Kamala Harris ha aceptado oficialmente otro duelo televisivo contra su oponente republicano Donald Trump,<\/p>\n","protected":false},"author":1,"featured_media":1371772,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[67360,4844,372,21599,18394,78473,2353,930,525,15987,243],"class_list":["post-1371771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finanzas","tag-competiran","tag-duelo","tag-entre","tag-estaria","tag-harris","tag-kamala","tag-lista","tag-segundo","tag-si","tag-televisivo","tag-trump"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1371771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1371771"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1371771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1371772"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1371771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1371771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1371771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}