{"id":1371765,"date":"2024-09-22T15:51:19","date_gmt":"2024-09-22T15:51:19","guid":{"rendered":"https:\/\/teknomers.com\/es\/bayesiano-ninguna-accion-legal-contra-la-familia-lynch-por-parte-de-the-italian-sea-group-solo-mandato-generico-a-los-abogados\/"},"modified":"2024-09-22T15:51:23","modified_gmt":"2024-09-22T15:51:23","slug":"bayesiano-ninguna-accion-legal-contra-la-familia-lynch-por-parte-de-the-italian-sea-group-solo-mandato-generico-a-los-abogados","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/bayesiano-ninguna-accion-legal-contra-la-familia-lynch-por-parte-de-the-italian-sea-group-solo-mandato-generico-a-los-abogados\/","title":{"rendered":"Bayesiano, ninguna acci\u00f3n legal contra la familia Lynch por parte de The Italian Sea Group: \u00abS\u00f3lo mandato gen\u00e9rico a los abogados\u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>Escuche la versi\u00f3n en audio del art\u00edculo.<\/button><\/p>\n<p class=\"atext\">A las pocas horas se desmont\u00f3 la noticia del pedido de cuantiosa indemnizaci\u00f3n al propietario realizado por los constructores. <b>bayesiano<\/b>El yate de bandera brit\u00e1nica se hundi\u00f3 la madrugada del 19 de agosto frente al puerto de Porticello, provocando la muerte de siete personas, entre ellas el magnate ingl\u00e9s Mike. <b>Linchar<\/b>.<\/p>\n<p class=\"atext\">El anuncio de la acci\u00f3n judicial, difundido por varios peri\u00f3dicos locales ingleses e italianos, entre ellos el Nazione y el Giornale di Sicilia, fue desmentido con un comunicado de prensa directo de <b>El grupo mar\u00edtimo italiano<\/b>la empresa que se hizo cargo de la marca <b>Perini Navi<\/b>el astillero que construy\u00f3 el <b>bayesiano<\/b>.<\/p>\n<p class=\"atext\">De hecho, en una nota la empresa hace saber que &#8220;en la persona de su representante legal, Giovanni Costantino, niega rotundamente la acci\u00f3n judicial tras la tragedia bayesiana&#8221;.<\/p>\n<p class=\"atext\">Respecto a lo publicado por algunos diarios, tanto italianos como brit\u00e1nicos, sobre una supuesta solicitud de indemnizaci\u00f3n por da\u00f1os y perjuicios de 222 millones de euros, la empresa se\u00f1ala que \u00abaunque dio un mandato gen\u00e9rico a los abogados, ning\u00fan representante legal de la empresa examin\u00f3 , ni firm\u00f3 ni autoriz\u00f3 ning\u00fan auto de citaci\u00f3n. La empresa se distancia firmemente de lo publicado y se reserva el derecho de protegerse en todos los lugares.&#8221;<\/p>\n<aside class=\"acor acor--mkt\">\n<div class=\"row row--dotted\">\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/consigli24.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/tariffe.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/06\/Decreto-de-cohesion-solicitud-bipartidista-para-liberar-inmediatamente-la-cofinanciacion.png\" alt=\"Descubra m\u00e1s\"\/><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/aside>\n<p class=\"atext\">Seg\u00fan se public\u00f3 en la prensa, fue la empresa la que fue puesta en duda <b>revtom limitado,<\/b> que pertenece a <b>\u00c1ngela<\/b> <b>Bacar\u00e9s<\/b>viuda de Mike Lynch, el propietario del barco.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/danni-immagine-costruttori-yacht-bayesian-chiedono-222-mln-all-armatore-AFLQPE4D\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escuche la versi\u00f3n en audio del art\u00edculo. A las pocas horas se desmont\u00f3 la noticia del pedido de<\/p>\n","protected":false},"author":1,"featured_media":1371766,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[17459,1261,249073,110,126,40883,3778,109227,771,36,10432,14122,5212,1854,231,15,2525],"class_list":["post-1371765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-abogados","tag-accion","tag-bayesiano","tag-contra","tag-familia","tag-generico","tag-group","tag-italian","tag-legal","tag-los","tag-lynch","tag-mandato","tag-ninguna","tag-parte","tag-por","tag-sea","tag-solo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1371765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1371765"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1371765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1371766"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1371765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1371765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1371765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}