{"id":1371010,"date":"2024-09-21T23:57:23","date_gmt":"2024-09-21T23:57:23","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-martillo-del-conductor-horner-esta-cortejando-a-russell-2\/"},"modified":"2024-09-21T23:57:27","modified_gmt":"2024-09-21T23:57:27","slug":"el-martillo-del-conductor-horner-esta-cortejando-a-russell-2","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-martillo-del-conductor-horner-esta-cortejando-a-russell-2\/","title":{"rendered":"\u00bfEl martillo del conductor? Horner est\u00e1 cortejando a Russell"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>El jefe del equipo Mercedes, Toto Wolff, ha causado revuelo durante mucho tiempo con su noviazgo con el campe\u00f3n mundial Max Verstappen. Ahora el jefe de Red Bull, Christian Horner, est\u00e1 respondiendo: tiene a George Russell firmemente en la mira. <\/p>\n<p>El jefe del equipo Red Bull, Christian Horner, est\u00e1 cortejando p\u00fablicamente los servicios de la estrella de Mercedes, George Russell.<\/p>\n<p>&#8220;Queremos tomarnos nuestro tiempo para pensar en c\u00f3mo ser\u00e1n las opciones para el futuro&#8221;, comenz\u00f3 el brit\u00e1nico en una entrevista con &#8220;Sky Sports&#8221; al margen del Gran Premio de Singapur. Luego a\u00f1adi\u00f3 una frase que probablemente no caer\u00eda nada bien, especialmente entre sus rivales Mercedes: &#8220;No tenemos miedo de mirar fuera del grupo de pilotos original. George Russell ya no tiene contrato despu\u00e9s de la pr\u00f3xima temporada, ser\u00eda una tonter\u00eda&#8221;. No considerarlo.&#8221;<\/p>\n<p>Russell se mud\u00f3 de Williams a Mercedes en 2022, y su contrato de trabajo con las Flechas de Plata se extendi\u00f3 hasta finales de 2025 el verano pasado. Ha ganado carreras dos veces en su carrera en la F\u00f3rmula 1 hasta el momento: en 2022 gan\u00f3 en Sao Paulo y esta temporada tambi\u00e9n en Spielberg. <\/p>\n<div class=\"hs-news-image-container hs-news-image-container--orientation-center hs-news-image-container--width-max\"><\/div>\n<h2>\u00bfQu\u00e9 sigue para P\u00e9rez en Red Bull?<\/h2>\n<p>Para Toto Wolff, el joven de 26 a\u00f1os no s\u00f3lo es un elemento central ahora, sino tambi\u00e9n a medio y largo plazo. Porque: a partir de 2025, el talento excepcional Kimi Antonelli se trasladar\u00e1 a la cabina del campe\u00f3n mundial r\u00e9cord Lewis Hamilton, mientras que George Russell ser\u00e1 el piloto mucho m\u00e1s experimentado.<\/p>\n<p><interaction id=\"66d5ba93d0359c6d1bb40b1a\" class=\"apester-container hs-socialmedia-container hs-socialmedia-container--type-apester hs-socialmedia-container--orientation-center hs-socialmedia-container--width-max\"\/><\/p>\n<p>En Red Bull, las recientes declaraciones de Horner sobre la futura composici\u00f3n de los pilotos tambi\u00e9n pueden haber sido un gui\u00f1o hacia Sergio P\u00e9rez. El mexicano solo recibi\u00f3 en junio una extensi\u00f3n de contrato hasta finales de 2026, pero a\u00fan no ha podido devolverla con rendimiento.<\/p>\n<p>Recientemente se difundieron rumores desde M\u00e9xico de que el jugador de 34 a\u00f1os ahora est\u00e1 considerando terminar su carrera poco despu\u00e9s de la temporada actual. <\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne7097750\/formel-1--fahrer-beben-red-bull-buhlt-um-mercedes-star\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jefe del equipo Mercedes, Toto Wolff, ha causado revuelo durante mucho tiempo con su noviazgo con el<\/p>\n","protected":false},"author":1,"featured_media":1370646,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[6860,202108,7498,39803,38,203901,120557,97,276,30465,3037,8773,285,26921],"class_list":["post-1371010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-automovilismo","tag-carreras-de-toro-rojo","tag-conductor","tag-cortejando","tag-del","tag-deportes-en-general","tag-equipo-mercedes-amg-f1","tag-esta","tag-formula-1","tag-george-russell","tag-horner","tag-martillo","tag-russell","tag-sergio-perez"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1371010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1371010"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1371010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1370646"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1371010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1371010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1371010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}