{"id":1368398,"date":"2024-09-20T01:29:25","date_gmt":"2024-09-20T01:29:25","guid":{"rendered":"https:\/\/teknomers.com\/es\/augsburgo-gana-tras-la-prorroga-en-el-partido-inaugural-del-del\/"},"modified":"2024-09-20T01:29:30","modified_gmt":"2024-09-20T01:29:30","slug":"augsburgo-gana-tras-la-prorroga-en-el-partido-inaugural-del-del","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/augsburgo-gana-tras-la-prorroga-en-el-partido-inaugural-del-del\/","title":{"rendered":"Augsburgo gana tras la pr\u00f3rroga en el partido inaugural del DEL"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"seitenkopf\">\n<div class=\"seitenkopf__data columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"seitenkopf__title\">\n<p class=\"metatextline\">A partir de: 19 de septiembre de 2024 22:21<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n        <strong>El Augsburger Panther, casi descendido, comenz\u00f3 con una victoria la nueva temporada de la liga alemana de hockey sobre hielo (DEL). El colista de las dos \u00faltimas temporadas derrot\u00f3 al ERC Ingolstadt por 3-2 (1-0, 0-0, 1-2, 1-0) tras la pr\u00f3rroga en el partido inaugural del jueves. <\/strong>\n    <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Despu\u00e9s de largos partidos, los suabos no descendieron s\u00f3lo porque los respectivos campeones de la segunda divisi\u00f3n no hab\u00edan solicitado la admisi\u00f3n al DEL. <\/p>\n<h2 id=\"Kunyk-sorgt-fuer-Entscheidung\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Kunyk toma la decisi\u00f3n<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>El nuevo fichaje Cody Kunyk se adelant\u00f3 temprano para los locales (7\u00ba) ante 6.179 espectadores en el estadio Curt Frenzel. Los invitados dominaron entonces el partido, pero fallaron repetidamente debido al nuevo y fuerte portero Strauss Mann. No fue hasta ocho minutos antes del final que Alex Breton empat\u00f3, pero apenas doce segundos despu\u00e9s Riley Damiani anot\u00f3 para poner el 2-1 para Augsburgo. Philipp Krau\u00df forz\u00f3 la pr\u00f3rroga (56.\u00ba), Kunyk tom\u00f3 la decisi\u00f3n con su segundo gol (53.\u00ba). <\/p>\n<h2 id=\"Allererstes-DEL-Spiel-vor-30-Jahren-an-selber-Stelle\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">El primer juego DEL hace 30 a\u00f1os en el mismo lugar<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Hace 30 a\u00f1os, el hockey sobre hielo alem\u00e1n comenz\u00f3 una nueva era en el mismo lugar. En el primer partido del DEL, el veterano de la NHL Bobby Hull lanz\u00f3 el primer disco, pero el Augsburgo, como campe\u00f3n de la segunda divisi\u00f3n, perdi\u00f3 claramente por 1:6 contra el \u00faltimo campe\u00f3n de la Bundesliga, el Hedos Munich, que se hab\u00eda rebautizado como Maddogs.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Tres meses y medio despu\u00e9s, los campeones quebraron y la nueva liga sufri\u00f3 un desastre. El DEL se ha estabilizado econ\u00f3micamente y ha alcanzado r\u00e9cords en t\u00e9rminos de espectadores y ventas totales en su temporada de aniversario. <\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sportschau.de\/eishockey\/del\/augsburg-siegt-nach-verlaengerung-im-del-eroeffnungsspiel,del-spieltag-326.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de: 19 de septiembre de 2024 22:21 El Augsburger Panther, casi descendido, comenz\u00f3 con una victoria<\/p>\n","protected":false},"author":1,"featured_media":1368399,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9318,38,1418,3390,14944,475,13659,720],"class_list":["post-1368398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-augsburgo","tag-del","tag-gana","tag-hockey-sobre-hielo","tag-inaugural","tag-partido","tag-prorroga","tag-tras"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1368398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1368398"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1368398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1368399"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1368398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1368398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1368398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}