{"id":1305610,"date":"2024-08-05T15:06:18","date_gmt":"2024-08-05T15:06:18","guid":{"rendered":"https:\/\/teknomers.com\/es\/jeroen-kijk-en-de-vegte-recuerda-su-extrano-grito-televisivo-mop\/"},"modified":"2024-08-05T15:06:22","modified_gmt":"2024-08-05T15:06:22","slug":"jeroen-kijk-en-de-vegte-recuerda-su-extrano-grito-televisivo-mop","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/jeroen-kijk-en-de-vegte-recuerda-su-extrano-grito-televisivo-mop\/","title":{"rendered":"Jeroen Kijk en De Vegte recuerda su extra\u00f1o grito televisivo: &#8220;Mop&#8221;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"post-450945\">\n<div class=\"entry__content\">\n<p>Es uno de los fragmentos televisivos m\u00e1s extra\u00f1os de 2024 hasta el momento: el momento en que Jeroen Kijk en De Vegte empieza a llorar en directo en televisi\u00f3n por un asunto trivial.  &#8220;Fregar.&#8221;<\/p>\n<div class=\"entry__thumb\">\n <span class=\"entry__thumb-description\">\u00a9 ONG<\/span> <\/div>\n<p>Jeroen Kijk en De Vegte estuvo muy emocionado en el Festival de la Canci\u00f3n de Eurovisi\u00f3n en la primavera.  Comenz\u00f3 a llorar en vivo por televisi\u00f3n cuando Nikkie de Jager se retir\u00f3 como chica de puntos.  H\u00e9l\u00e8ne Hendriks se ri\u00f3 entonces del locutor de radio y locutor de RTL Boulevard, pero \u00e9l mismo no lo entendi\u00f3.  &#8220;Yo tampoco voy a pedir perd\u00f3n&#8221;.<\/p>\n<h2 class=\"wp-block-heading\">aullidos locos<\/h2>\n<p>\u00bfC\u00f3mo recuerda Jeroen ese grito loco ahora, unos meses despu\u00e9s?  \u201cNikkie y yo nos conocemos desde \u00bfWie is de mol?  yo los conocia <em>sobre la Luna<\/em> se le permitir\u00eda dar los puntos.  Pero la situaci\u00f3n en torno a Joost Klein hab\u00eda empeorado de manera tan extra\u00f1a que ella se retir\u00f3&#8221;, dice <a rel=\"nofollow noopener\" href=\"https:\/\/www.ad.nl\/show\/jeroen-kijk-in-de-vegte-over-benb-vol-liefde-je-kunt-je-zo-heerlijk-verbazen-over-je-medemens~a193eeb4\/\" target=\"_blank\">ANUNCIO<\/a>. <\/p>\n<p>A Jeroen le doli\u00f3 terriblemente, pero \u00bfpor qu\u00e9?  \u201cNikkie estaba en Leeuwarden, donde se hab\u00eda organizado una fiesta maravillosa.  Pens\u00e9: qu\u00e9 maravilloso que podamos contrastar esto con el conjunto de negatividad que ves en la televisi\u00f3n todos los d\u00edas.  Y luego todo fracas\u00f3\u201d.<\/p>\n<h2 class=\"wp-block-heading\">trapeador emocional<\/h2>\n<p>Todo muy desafortunado para Nikkie, pero eso no es algo por lo que llorar, \u00bfverdad?  Pero s\u00ed, dice Jeroen: \u201cEntonces tambi\u00e9n soy un fregona emocional.  Puedo llorar con una canci\u00f3n en la radio.  Entiendo que algunas personas se hayan preguntado qu\u00e9 es lo que le preocupa a ese hombre, pero no me averg\u00fcenzo de ello.  As\u00ed soy yo como persona\u201d.<\/p>\n<p>\u201cEn la radio tambi\u00e9n me conmueve la historia de un oyente.  As\u00ed me gusta trabajar.  No soy una m\u00e1quina con una voz de radio dise\u00f1ada, sino simplemente un ser humano\u201d.<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.mediacourant.nl\/2024\/08\/jeroen-kijk-in-de-vegte-blikt-terug-op-zijn-rare-tv-huilbui-dweil\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-48<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es uno de los fragmentos televisivos m\u00e1s extra\u00f1os de 2024 hasta el momento: el momento en que Jeroen<\/p>\n","protected":false},"author":1,"featured_media":1305611,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[3090,12893,12441,246231,36538,226682,11314,15987,171155],"class_list":["post-1305610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-extrano","tag-grito","tag-jeroen","tag-jeroen-mira-a-lo-lejos","tag-kijk","tag-mop","tag-recuerda","tag-televisivo","tag-vegte"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1305610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1305610"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1305610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1305611"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1305610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1305610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1305610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}