{"id":1303436,"date":"2024-08-03T18:02:11","date_gmt":"2024-08-03T18:02:11","guid":{"rendered":"https:\/\/teknomers.com\/es\/con-amor-contra-el-odio-racial-mira-beale-street-ahora\/"},"modified":"2024-08-03T18:02:16","modified_gmt":"2024-08-03T18:02:16","slug":"con-amor-contra-el-odio-racial-mira-beale-street-ahora","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/con-amor-contra-el-odio-racial-mira-beale-street-ahora\/","title":{"rendered":"Con amor contra el odio racial: \u00a1Mira \u201cBeale Street\u201d ahora!"},"content":{"rendered":"\n<div>\n<p>Despu\u00e9s de todo, el autor James Baldwin se ha convertido en un \u00edcono estadounidense; el racismo, la homofobia y el \u201corgullo blanco\u201d no pudieron afectar sus textos m\u00e1gicos.  Por el contrario, en vista del movimiento del poder blanco que ha resurgido bajo Donald Trump, la literatura de Baldwin act\u00faa como una lente que hace visible lo que es.<\/p>\n<p>Esto es particularmente cierto en su pen\u00faltima novela, &#8220;Beale Street Blues&#8221;, que est\u00e1 ambientada en el Harlem de los a\u00f1os 1970, porque Beale Street est\u00e1 en todas partes, es una met\u00e1fora del odio racial que contin\u00faa como un hilo conductor hasta el d\u00eda de hoy. Historia americana.<\/p>\n<p>La joven Clementine \u201cTish\u201d Rivers habla sobre su amor por Alonzo \u201cFonny\u201d Hunt.  Su historia de amor podr\u00eda ser paradis\u00edaca si no fuera por las circunstancias sociales.  Porque en la d\u00e9cada de 1970, a los racistas blancos se les permit\u00eda desahogarse en las calles como un brazo extendido del Estado.  Aqu\u00ed conoces a uno de los del Oficial Bell, que lleva a Fonny a prisi\u00f3n acusado de violar a la joven Victoria Rogers.  Pero el joven negro tiene una coartada para el momento del crimen.  Sin embargo, cuando la presunta v\u00edctima huye a Puerto Rico, el testimonio de un polic\u00eda blanco se contrapone al de un sospechoso negro.<\/p>\n<h2>V\u00edctimas inocentes: \u00bfh\u00e9roes perfectos?<\/h2>\n<p>Barry Jenkins, que gan\u00f3 el Oscar a la Mejor Pel\u00edcula en 2017 por \u201cMoonlight\u201d, se ha hecho cargo de la novela de Baldwin.  Capta el ritmo a la perfecci\u00f3n con colores c\u00e1lidos y melod\u00edas de jazz y deja que la joven Tish (KiKi Layne) hable alternativamente sobre el tiempo que pasaron juntos antes del arresto de Fonny (Stephan James) y la posterior lucha de su familia por su liberaci\u00f3n.<\/p>\n<p>La brutal psicolog\u00eda del racismo se refleja continuamente en la novela.  Te animas y pateas.  Esto tambi\u00e9n se aplica a los h\u00e9roes negros, que no son tan perfectos en Baldwin como en la adaptaci\u00f3n de Jenkins.  Sin embargo, siguen siendo v\u00edctimas inocentes.<\/p>\n<p><strong>\u201cBeale Street\u201d est\u00e1 en streaming <a rel=\"nofollow noopener\" href=\"https:\/\/mubi.com\/de\/de\/films\/if-beale-street-could-talk\" target=\"_blank\">MUBI<\/a>Joyn, Seven Entertainment, Freenet-Video y Kabel Eins Classics. <\/strong><\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rollingstone.de\/james-baldwin-beale-street-film-1634351\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de todo, el autor James Baldwin se ha convertido en un \u00edcono estadounidense; el racismo, la homofobia<\/p>\n","protected":false},"author":1,"featured_media":1303437,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[191,93,245998,128820,245999,99,110,245997,299,13286,44870,1802],"class_list":["post-1303436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-ahora","tag-amor","tag-barry-jenkins","tag-beale","tag-calle-beale","tag-con","tag-contra","tag-james-baldwin","tag-mira","tag-odio","tag-racial","tag-street"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1303436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1303436"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1303436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1303437"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1303436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1303436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1303436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}