{"id":1302318,"date":"2024-08-02T21:59:18","date_gmt":"2024-08-02T21:59:18","guid":{"rendered":"https:\/\/teknomers.com\/es\/matones-de-extrema-derecha-planean-una-serie-de-protestas-en-todo-el-reino-unido-este-fin-de-semana-en-medio-de-informes-falsos-de-que-el-atacante-de-southport-era-musulman\/"},"modified":"2024-08-02T21:59:23","modified_gmt":"2024-08-02T21:59:23","slug":"matones-de-extrema-derecha-planean-una-serie-de-protestas-en-todo-el-reino-unido-este-fin-de-semana-en-medio-de-informes-falsos-de-que-el-atacante-de-southport-era-musulman","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/matones-de-extrema-derecha-planean-una-serie-de-protestas-en-todo-el-reino-unido-este-fin-de-semana-en-medio-de-informes-falsos-de-que-el-atacante-de-southport-era-musulman\/","title":{"rendered":"Matones de extrema derecha planean una serie de protestas en todo el Reino Unido este fin de semana en medio de informes falsos de que el atacante de Southport era musulm\u00e1n"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>GRAN BRETA\u00d1A est\u00e1 en alerta roja ante hasta 15 protestas de extrema derecha este fin de semana, mientras la polic\u00eda public\u00f3 im\u00e1genes de sospechosos que est\u00e1n tratando de rastrear de disturbios anteriores.<\/p>\n<p>Se esperan m\u00e1s manifestaciones tras una ola de disturbios violentos provocados por falsos <span id=\"0673e456-febc-4110-bf91-8b3a3b57ea88\" class=\"suggested-link\">noticias<\/span> En Internet se afirma que el presunto asesino con cuchillo de tres ni\u00f1as era un solicitante de asilo musulm\u00e1n.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"1\"><a rel=\"nofollow\" href=\"#\"><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">7<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Unos matones atacaron una mezquita en Southport despu\u00e9s de que falsos rumores afirmaran que un musulm\u00e1n estaba detr\u00e1s del asesinato de tres ni\u00f1as<\/span><span class=\"article__credit\">Cr\u00e9dito: PP.<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"2\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Los alborotadores atacaron a la polic\u00eda y destrozaron comunidades y las autoridades temen que haya m\u00e1s.\" height=\"640\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635954_291_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg\" data-credit=\"Getty\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635954_291_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">7<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Los alborotadores atacaron a la polic\u00eda y destrozaron comunidades y las autoridades temen que haya m\u00e1s.<\/span><span class=\"article__credit\">Cr\u00e9dito: Getty<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"3\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Las fuerzas policiales est\u00e1n trabajando juntas y se han comprometido a detener cualquier desorden violento.\" height=\"640\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635955_608_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg\" data-credit=\"Alamy\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635955_608_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">7<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Las fuerzas policiales est\u00e1n trabajando juntas y se han comprometido a detener cualquier desorden violento.<\/span><span class=\"article__credit\">Cr\u00e9dito: Alamy<\/span><\/figcaption><\/figure>\n<p>Se desat\u00f3 un disturbio en Southport, Merseyside, cuando unos matones atacaron una mezquita cerca de donde Bebe King, de seis a\u00f1os, Elsie Dot Stancombe, de siete, y Alice Dasilva Aguiar, de nueve, fueron atacadas durante una clase de baile.<\/p>\n<p>Cincuenta y tres polic\u00edas resultaron heridos cuando los matones lanzaron ladrillos e incendiaron veh\u00edculos en varias horas de caos.<\/p>\n<p>Se produjeron otras protestas en el centro de Londres, donde 100 personas fueron detenidas, y en Hartlepool, donde un ni\u00f1o de 11 a\u00f1os fue detenido bajo sospecha de incendio provocado despu\u00e9s de que un veh\u00edculo policial fuera incendiado.<\/p>\n<p>La polic\u00eda de Manchester public\u00f3 im\u00e1genes de 11 hombres y mujeres que quieren interrogar despu\u00e9s de que matones enmascarados arrojaran botellas a polic\u00edas antidisturbios afuera de un hotel que alberga a solicitantes de asilo en el suburbio de Newton Heath.<\/p>\n<p>Mientras tanto, la fuerza de Hampshire hizo circular fotos de siete hombres que est\u00e1n buscando despu\u00e9s de que una manifestaci\u00f3n de 200 personas tipo turba frente a otro hotel para inmigrantes en Aldershot se tornara violenta.<\/p>\n<p>Se cree que los extremistas est\u00e1n utilizando TikTok y el servicio de mensajer\u00eda Telegram para organizar protestas durante el fin de semana en Liverpool, Sunderland, Manchester, Hull, Leeds, Middlesbrough, Southport y Bristol.<\/p>\n<p>Se esperan otros en Nottingham, donde se cree que hay dos planeados, as\u00ed como en Cardiff, High Wycombe en Bucks y Belfast.<\/p>\n<p>El Ministerio del Interior dio a conocer anoche un plan para combatir los disturbios, con 70 fiscales adicionales listos para acusar a los infractores en el lugar.<\/p>\n<p>Y el Consejo de Jefes de Polic\u00eda Nacional ha detallado una estrategia operativa, estableciendo prioridades claras para abordar los des\u00f3rdenes relacionados con las protestas.<\/p>\n<p>El ministro del Interior, Lord Hanson, advirti\u00f3: \u201cA cualquiera que est\u00e9 organizando esto, lo estaremos vigilando. Est\u00e9n preparados para enfrentar todo el peso de la ley por esta actividad criminal\u201d.<\/p>\n<div id=\"bc-video-6359800479112\" class=\"brightcove\"><span class=\"article__bc_video-caption\">El sospechoso de Southport, Axel Rudakubana, fue nombrado para acabar con los &#8220;disturbios idiotas&#8221;, pero se necesita m\u00e1s para detener a los matones, dice un experto<\/span><\/div>\n<p>Los expertos examinar\u00e1n las im\u00e1genes mientras los oficiales en helic\u00f3pteros policiales filman a los asistentes a las manifestaciones para registrar cualquier evidencia de criminalidad.<\/p>\n<p>Tambi\u00e9n se utilizar\u00e1n coches de polic\u00eda equipados con tecnolog\u00eda de reconocimiento autom\u00e1tico de matr\u00edculas para escanear los veh\u00edculos cerca de los puntos de reuni\u00f3n de las protestas.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"4\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"La polic\u00eda ha prometido que los alborotadores enfrentar\u00e1n todo el peso de la ley y se utilizar\u00e1 tecnolog\u00eda para identificarlos.\" height=\"640\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635956_943_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg\" data-credit=\"Getty\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635956_943_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">7<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">La polic\u00eda ha prometido que los alborotadores enfrentar\u00e1n todo el peso de la ley y se utilizar\u00e1 tecnolog\u00eda para identificarlos.<\/span><span class=\"article__credit\">Cr\u00e9dito: Getty<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"5\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"La polic\u00eda de Manchester ha publicado im\u00e1genes de personas buscadas en relaci\u00f3n con los disturbios en Newton Heath\" height=\"960\" width=\"938\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635956_376_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg\" data-credit=\"\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635956_376_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg?strip=all&amp;w=938\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">7<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">La polic\u00eda de Manchester ha publicado im\u00e1genes de personas buscadas en relaci\u00f3n con los disturbios en Newton Heath<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"6\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"La polic\u00eda de Hampshire est\u00e1 haciendo circular im\u00e1genes de sospechosos en relaci\u00f3n con un incidente en Aldershot\" height=\"960\" width=\"938\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635957_638_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg\" data-credit=\"\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635957_638_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg?strip=all&amp;w=938\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">7<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">La polic\u00eda de Hampshire est\u00e1 haciendo circular im\u00e1genes de sospechosos en relaci\u00f3n con un incidente en Aldershot<\/span><\/figcaption><\/figure>\n<p>Lord Walney, asesor gubernamental sobre violencia y disturbios pol\u00edticos, dijo sobre los disturbios: \u201cAlgunos actores de extrema derecha se han aficionado a esto y est\u00e1n tratando de provocar algo similar en pueblos y ciudades de todo el Reino Unido\u201d.<\/p>\n<p>El jefe de polic\u00eda Gavin Stephens, presidente del Consejo Nacional de Jefes de Polic\u00eda, dijo: \u201cLas fuerzas est\u00e1n trabajando juntas a nivel local, regional y nacional para recopilar y compartir inteligencia y asegurarse de que estamos listos para enfrentar cualquier desorden violento que pueda surgir\u201d.<\/p>\n<p>La subdirectora de polic\u00eda de Merseyside, Jenny Sims, agreg\u00f3: \u201cCualquiera que intente causar <span id=\"3d6c2644-3240-41f1-a966-c7289580ba5d\" class=\"suggested-link\">futuro<\/span> \u201cLos da\u00f1os y perjuicios a nuestras comunidades ser\u00e1n tratados con firmeza\u201d.<\/p>\n<p>El alcalde de la regi\u00f3n de la ciudad de Liverpool, Steve Rotheram, exigi\u00f3 a los ministros \u201cque hagan algo con las redes sociales\u201d. <\/p>\n<p>Dijo que se hab\u00eda utilizado para \u201calimentar las mentiras\u201d sobre el presunto autor de los apu\u00f1alamientos de Southport que \u201calimentaron parte del desorden que vimos en las calles\u201d.<\/p>\n<p><span id=\"fcb0d376-9e7e-4aef-afa9-6e72371b8f6d\" class=\"suggested-link\">Zara<\/span> Mohammed, del Consejo Musulm\u00e1n de Gran Breta\u00f1a, dijo que cientos de mezquitas en todo el pa\u00eds reforzar\u00e1n sus medidas de seguridad y protecci\u00f3n este fin de semana.<\/p>\n<p>Esto ocurri\u00f3 cuando el Primer Ministro Sir Keir Starmer regres\u00f3 ayer a Southport para agradecer a los servicios de emergencia y al personal del hospital por su respuesta a los apu\u00f1alamientos en los disturbios.<\/p>\n<p>Axel Rudakubana, de 17 a\u00f1os, que naci\u00f3 en Cardiff y vive en Lancashire, ha sido puesto en prisi\u00f3n preventiva para menores acusado de tres cargos de asesinato, diez de intento de asesinato y uno de posesi\u00f3n de un art\u00edculo blanco.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"7\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"El alcalde de Liverpool tambi\u00e9n critic\u00f3 las redes sociales despu\u00e9s de que se usaran para provocar disturbios.\" height=\"640\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635958_580_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg\" data-credit=\"Getty\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722635958_580_Matones-de-extrema-derecha-planean-una-serie-de-protestas-en.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">7<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">El alcalde de Liverpool tambi\u00e9n critic\u00f3 las redes sociales despu\u00e9s de que se usaran para provocar disturbios.<\/span><span class=\"article__credit\">Cr\u00e9dito: Getty<\/span><\/figcaption><\/figure>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/news\/29656974\/far-rights-thugs-planning-series-protests\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GRAN BRETA\u00d1A est\u00e1 en alerta roja ante hasta 15 protestas de extrema derecha este fin de semana, mientras<\/p>\n","protected":false},"author":1,"featured_media":1302319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[100,78303,11985,11514,239506,2603,560,21685,9132,1454,21577,2932,485,245064,4103,691,980,36785,2508,58517,17222,61834,10715,1152,5300,3270,213334,1246,985,245003,339,2073,158,5329],"class_list":["post-1302318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-atacante","tag-crisis-de-refugiados","tag-delito","tag-derecha","tag-el-periodico-the-sun","tag-era","tag-este","tag-extrema","tag-falsos","tag-fin","tag-gales","tag-informes","tag-inglaterra","tag-lado-mersey","tag-liverpool","tag-londres","tag-manchester","tag-matones","tag-medio","tag-medios-de-comunicacion-social","tag-musulman","tag-partido-conservador","tag-planean","tag-policia","tag-protestas","tag-reino","tag-seccion-noticiasnoticias-del-reino-unido","tag-semana","tag-serie","tag-southport","tag-todo","tag-tribunales","tag-una","tag-unido"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1302318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1302318"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1302318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1302319"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1302318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1302318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1302318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}