{"id":1302118,"date":"2024-08-02T18:45:21","date_gmt":"2024-08-02T18:45:21","guid":{"rendered":"https:\/\/teknomers.com\/es\/imane-khelif-como-kim-novak-la-cuestion-de-los-cromosomas-explicada-por-el-endocrinologo\/"},"modified":"2024-08-02T18:45:26","modified_gmt":"2024-08-02T18:45:26","slug":"imane-khelif-como-kim-novak-la-cuestion-de-los-cromosomas-explicada-por-el-endocrinologo","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/imane-khelif-como-kim-novak-la-cuestion-de-los-cromosomas-explicada-por-el-endocrinologo\/","title":{"rendered":"\u00bfImane Khelif como Kim Novak?  La cuesti\u00f3n de los cromosomas explicada por el endocrin\u00f3logo."},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><span class=\"first-letter\">PAG<\/span>Para calmar la pol\u00e9mica sobre lo ocurrido en los Juegos Ol\u00edmpicos ayer 1 de agosto de 2024, preferimos recurrir a la ciencia antes que a opiniones personales.  Para aclarar las caracter\u00edsticas hormonales que preocupan al boxeador argelino de 25 a\u00f1os <strong>Iman Khelif<\/strong> (y muchas otras mujeres) que \u2013 ahora lo han aclarado varios m\u00e9dicos de todo el mundo \u2013 es una mujer en todos los aspectos, hablamos con la<strong> <a rel=\"nofollow noopener\" href=\"https:\/\/cerva16.com\/team\/fabrizio-golonia\/\" data-wpel-link=\"external\" target=\"_blank\">Doctor Fabricio Golonia<\/a>especializado en medicina interna y endocrinolog\u00eda<\/strong> en el centro m\u00e9dico multiespecializado Cerva 16 de Mil\u00e1n.<\/p>\n<div id=\"wrapper_video_embed\" class=\"player_single_video_component\">\n<div id=\"divVideoPlayer\" class=\"video-sticky-box privacyAccettata\">\n<div class=\"video-sticky-box-inner\">\n<div class=\"video-sticky-box-frame-cont\">\n<div class=\"player player_video_rcs player_shortcode custom-video-sticky\" data-config=\"{&quot;newspaper&quot;:&quot;rcs&quot;,&quot;uuid&quot;:&quot;iodonna-0001993065&quot;,&quot;muted&quot;:true,&quot;blockAdv&quot;:false,&quot;ovlLogo&quot;:false,&quot;autoplay&quot;:true,&quot;watermark&quot;:false,&quot;scale&quot;:&quot;with-parent&quot;,&quot;poster&quot;:{&quot;pre&quot;:{&quot;type&quot;:&quot;bySelector&quot;,&quot;container&quot;:&quot;.player_preview&quot;,&quot;play&quot;:&quot;.play&quot;,&quot;playByContainer&quot;:true}},&quot;playerPage&quot;:&quot;tvSticky&quot;,&quot;tipo_video&quot;:&quot;articolo_ancorato&quot;}\">\n<div class=\"player_preview\">\n                                    <img decoding=\"async\" class=\"\" alt=\"Hormonas de la felicidad: 7 consejos para estimularlas de forma natural\" title=\"Hormonas de la felicidad: 7 consejos para estimularlas de forma natural\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/\u00bfImane-Khelif-como-Kim-Novak-La-cuestion-de-los-cromosomas.webp.webp\"\/>                                    <span class=\"player_button play\"\/>\n                                <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2>\u00bfPor qu\u00e9 la boxeadora Imane Khelif es una mujer en todos los aspectos a pesar de tener niveles altos de testosterona?<\/h2>\n<p>Los elementos puestos a disposici\u00f3n por <em>Comit\u00e9 Olimpico Internacional (<a rel=\"nofollow noopener\" href=\"https:\/\/it.wikipedia.org\/wiki\/Comitato_Olimpico_Internazionale\" data-wpel-link=\"external\" target=\"_blank\">ESO ES)<\/a><\/em>  hay pocos que puedan dar una respuesta completa.  EL <strong>Trastornos del desarrollo sexual.<\/strong> incluyen una serie bastante grande de <strong>anomal\u00edas cong\u00e9nitas<\/strong> en el que la <strong>sexo cromos\u00f3mico y anat\u00f3mico<\/strong> (apariencia externa de los genitales) son <strong>diferente<\/strong>.  En cuanto al m\u00e9rito espec\u00edfico de Imane Khelif, no se dispone de datos precisos (que el COI ciertamente posee y no quiere revelar).<\/p>\n<article class=\"id-vda-article box_ed_hp_02-article eltdf-item-space hentry-pos-i hentry-home_section-i post-iiiii post type-post status-publish format-standard hentry\">\n<\/article>\n<p>Las clasificaciones de los trastornos del desarrollo sexual son una<strong> tema en constante evoluci\u00f3n<\/strong> y limitarse a la sola presencia de un<a rel=\"nofollow noopener\" href=\"https:\/\/it.wikipedia.org\/wiki\/Cariotipo#:~:text=Dopo%20la%20fecondazione%20della%20cellula,e%2046%2CXY%20nel%20maschio.\" data-wpel-link=\"external\" target=\"_blank\"> patr\u00f3n cromos\u00f3mico 46 XX<\/a> para definir la estructura femenina y 46 XY para la estructura masculina<strong> es reductivo<\/strong>.<br \/>De hecho, tanto DSD 46 <strong>alteraciones en el desarrollo testicular (<a rel=\"nofollow noopener\" href=\"https:\/\/www.iss.it\/-\/disgenesia-gonadica-completa-o-parziale-\" data-wpel-link=\"external\" target=\"_blank\">disgenesia gonadal masculina<\/a>)<\/strong> Eso <strong>DSD 46XX <\/strong><a rel=\"nofollow noopener\" href=\"https:\/\/www.cnr.it\/it\/focus\/040-26\/un-nuovo-gene-implicato-nella-disgenesia-ovarica-precoce#:~:text=La%20Disgenesia%20Ovarica%20Precoce%20(Premature,di%20disturbi%20ossei%20e%20cardiovascolari.\" data-wpel-link=\"external\" target=\"_blank\"><strong>diag\u00e9nesis ov\u00e1rica<\/strong>.<\/a> Esto sucede sin ning\u00fan cambio aparente en el mapeo cromos\u00f3mico.<\/p>\n<h2>\u00bfImane Khelif como Kim Novak?  aqu\u00ed porque<\/h2>\n<p>Las alteraciones en la s\u00edntesis o acci\u00f3n de los andr\u00f3genos deben situarse de otra manera (como ocurre en la resistencia total o parcial a los andr\u00f3genos, donde la <strong>La persona es anat\u00f3micamente femenina pero tiene 46 cromosomas XY.<\/strong> como sucede en <em><a rel=\"nofollow noopener\" href=\"https:\/\/www.iss.it\/-\/insensibilita-completa-agli-androgeni\" data-wpel-link=\"external\" target=\"_blank\">CAIS<\/a><\/em>m\u00e1s com\u00fanmente conocido como <a rel=\"nofollow noopener\" href=\"https:\/\/www.my-personaltrainer.it\/salute-benessere\/sindrome-di-morris.html#:~:text=La%20sindrome%20di%20Morris%20%2D%20nota,cio%C3%A8%20gli%20ormoni%20sessuali%20maschili).\" data-wpel-link=\"external\" target=\"_blank\"><strong>s\u00edndrome de morris<\/strong><\/a>.  La &#8220;leyenda&#8221; narra esta condici\u00f3n como propia de personajes de la gran pantalla como <a rel=\"nofollow noopener\" href=\"https:\/\/it.wikipedia.org\/wiki\/Kim_Novak\" data-wpel-link=\"external\" target=\"_blank\"><strong>Kim Novak<\/strong>una de las actrices m\u00e1s famosas y significativas del cine de Hollywood entre mediados de los a\u00f1os cincuenta y finales de los sesenta.<\/a> u otras actrices conocidas.<\/p>\n<div id=\"attachment_2383897\" data-thumbnail_id=\"2383897\" class=\"wp-caption aligncenter\" style=\"width:1290px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">(Foto de Fabio Bozzani\/Anadolu v\u00eda Getty Images)<\/p>\n<\/div>\n<h2>\u00bfQu\u00e9 significa ser una persona con hiperandrogenismo, es decir, una producci\u00f3n de hormonas superior a una hipot\u00e9tica media femenina?<\/h2>\n<p>Entre <strong><a rel=\"nofollow noopener\" href=\"https:\/\/www.iipritalia.it\/_HOME\/disturbi-della-differenziazione-sessuale-dsd\/\" data-wpel-link=\"external\" target=\"_blank\">DSD<\/a> (Trastornos de la diferenciaci\u00f3n sexual)<\/strong> caracterizado por un <strong>exceso de andr\u00f3genos (hiperandrogenismo)<\/strong> Se identifican alteraciones enzim\u00e1ticas que ocurren en el per\u00edodo fetal y alteraciones que afectan al feto (deficiencia de 21 beta o 11 hidroxilasa).  O interesante es la relaci\u00f3n fetoplacentaria (deficiencia de aromatasa o deficiencia de citocromo P450 \u00f3xido reductasa) o alteraci\u00f3n de la secreci\u00f3n androg\u00e9nica de la madre (luteoma o arrenoblastoma) que puede conducir a la &#8220;masculinizaci\u00f3n&#8221; del individuo con estructura 46 XX.<\/p>\n<h2>\u00bfEst\u00e1 el s\u00edndrome de ovario poliqu\u00edstico entre las causas?  \u00bfCuales son los otros?<\/h2>\n<p>All\u00e1 <a rel=\"nofollow noopener\" href=\"https:\/\/www.msdmanuals.com\/it-it\/casa\/problemi-di-salute-delle-donne\/disturbi-mestruali-e-sanguinamento-vaginale-anomalo\/sindrome-dell%E2%80%99ovaio-policistico-pcos\" data-wpel-link=\"external\" target=\"_blank\">SOP<\/a> no es una condici\u00f3n que califique entre las incluidas bajo la (ahora en desuso) definici\u00f3n de intersexualidad.  El problema del s\u00edndrome de ovario poliqu\u00edstico es la resistencia a la insulina m\u00e1s que el hiperandrogenismo.<\/p>\n<h2>\u00bfCu\u00e1l es el rango de valores de la hormona testosterona en una mujer?<\/h2>\n<p>El rango de concentraci\u00f3n \u00f3ptimo de testosterona total (es decir, unida a prote\u00ednas transportadoras) para una mujer es en promedio entre 8 y 60 ng\/ml.<\/p>\n<p class=\"all-rights-reserved\">iO Donna \u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iodonna.it\/benessere\/salute-e-psicologia\/2024\/08\/02\/imane-khelif-come-kim-novak-la-questione-dei-cromosomi-46xy-spiegata-dallendocrinologo\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAGPara calmar la pol\u00e9mica sobre lo ocurrido en los Juegos Ol\u00edmpicos ayer 1 de agosto de 2024, preferimos<\/p>\n","protected":false},"author":1,"featured_media":1302119,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[440,245852,8492,44164,45507,147250,245436,2902,36,10670,231],"class_list":["post-1302118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-como","tag-cromosomas","tag-cuestion","tag-endocrinologo","tag-explicada","tag-imane","tag-khelif","tag-kim","tag-los","tag-novak","tag-por"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1302118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1302118"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1302118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1302119"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1302118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1302118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1302118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}