{"id":1301115,"date":"2024-08-02T02:12:23","date_gmt":"2024-08-02T02:12:23","guid":{"rendered":"https:\/\/teknomers.com\/es\/resena-de-didi-una-historia-de-transicion-a-la-edad-adulta-que-es-nostalgica-conmovedora-y-dolorosamente-divertida\/"},"modified":"2024-08-02T02:12:28","modified_gmt":"2024-08-02T02:12:28","slug":"resena-de-didi-una-historia-de-transicion-a-la-edad-adulta-que-es-nostalgica-conmovedora-y-dolorosamente-divertida","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/resena-de-didi-una-historia-de-transicion-a-la-edad-adulta-que-es-nostalgica-conmovedora-y-dolorosamente-divertida\/","title":{"rendered":"Rese\u00f1a de Didi: una historia de transici\u00f3n a la edad adulta que es nost\u00e1lgica, conmovedora y dolorosamente divertida"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<h2 class=\"wp-block-heading has-text-align-center\">HICE<\/h2>\n<p class=\"has-text-align-center\">(15) 91 minutos <\/p>\n<h2 class=\"has-text-align-center\"><span style=\"color:#ff0000\">\u2605\u2605\u2605\u2605\u2606<\/span><\/h2>\n<p>En los viejos tiempos de 2008, antes del reinado de WhatsApp y TikTok, cuando el alfabeto emoji todav\u00eda estaba en sus inicios, los adolescentes expertos en tecnolog\u00eda se comunicaban en sus escritorios de Windows.<\/p>\n<p>Y es en su dormitorio en California, en el Messenger de AOL, en Facebook de pared a pared y en el desaparecido Myspace (RIP), donde el adolescente taiwan\u00e9s-estadounidense Chris Wang pasa la mayor parte de su tiempo.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"1\"><a rel=\"nofollow\" href=\"#\"><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Didi es una historia de transici\u00f3n a la edad adulta que es nost\u00e1lgica, conmovedora y dolorosamente divertida.<\/span><span class=\"article__credit\">Cr\u00e9dito: PA<\/span><\/figcaption><\/figure>\n<p>Eso es cuando no est\u00e1 buscando en Google &#8220;C\u00f3mo besar&#8221; y practicando con una manzana.<\/p>\n<p>Chris acecha cibern\u00e9ticamente a Madi, su amor plat\u00f3nico, publica videos de ardillas explosivas en YouTube y trata de atravesar la transici\u00f3n hormonal hacia su edad adulta.<\/p>\n<p>Su familia lo llama Didi (\u201chermano peque\u00f1o\u201d en mandar\u00edn), Wang-Wang entre sus amigos y Chris entre los patinadores mayores a quienes intenta impresionar desesperadamente.<\/p>\n<p>La comedia debut semiautobiogr\u00e1fica del director y escritor Sean Wang muestra a Chris alcanzando la madurez de una manera desordenada y extremadamente identificable.<\/p>\n<p>Hay caos y angustia dentro de su confundido cerebro de 13 a\u00f1os, que est\u00e1 asediado por influencias online.<\/p>\n<p>A punto de comenzar la escuela secundaria, Chris est\u00e1 rodeado de mujeres, pero no las entiende.<\/p>\n<p>Vive con su sobrecargada madre Chungsing, que sue\u00f1a con ser artista, su hermana mayor Vivian y su feroz abuela (interpretada por la abuela del director en la vida real).<\/p>\n<p>Se est\u00e1 distanciando de su mejor amigo de la infancia, Fahad. <\/p>\n<div id=\"bc-video-6355850775112\" class=\"brightcove\"><span class=\"article__bc_video-caption\">Los fans de Deadpool y Wolverine gritan \u201c\u00a1Dejen de estropear la pel\u00edcula!\u201d mientras un avance revela el regreso del popular personaje con un nuevo actor<\/span><\/div>\n<p>Pero, seg\u00fan admite \u00e9l mismo, cuanto m\u00e1s se esfuerza y \u200b\u200bm\u00e1s obsesivamente intenta hacerlo bien, m\u00e1s sigue Chris juzgando mal las situaciones y cometiendo errores.<\/p>\n<p>\u00c9l consigue una cita con Madi, pero luego es insoportable observar su incomodidad cuando ella intenta insinuarse sobre \u00e9l.<\/p>\n<p>M\u00e1s tarde, por supuesto, todav\u00eda les cuenta a sus amigos que marc\u00f3.<\/p>\n<p>Insulta a los amigos de Madi en la cara, pensando que su lenguaje ofensivo de \u201crapero\u201d es genial.<\/p>\n<p>Luego golpea a otro en un ataque de ira.<\/p>\n<p>Cuando pasa el rato con los chicos populares, que quieren que grabe sus trucos en patineta, vuelve a cometer errores al no presionar el bot\u00f3n de grabaci\u00f3n.<\/p>\n<p>Una banda sonora de los a\u00f1os 2000 y breves toques de surrealismo de una lubina parlante a\u00f1aden un toque extra de peculiaridad a este cuento adolescente nost\u00e1lgico, conmovedor y dolorosamente divertido.<\/p>\n<p>Laura Stott<\/p>\n<h2 class=\"wp-block-heading has-text-align-center\">EL REINO DE KENSUKE<\/h2>\n<p class=\"has-text-align-center\">(<strong>PG) 85 minutos<\/strong>s<\/p>\n<h2 class=\"has-text-align-center\"><span style=\"color:#ff0000\">\u2605\u2605\u2605\u2605\u2606<\/span><\/h2>\n<p>Este tierno y hermoso cuento animado sobre Michael, un ni\u00f1o que llega a una isla del Pac\u00edfico con su perra Stella, seguramente te llegar\u00e1 al coraz\u00f3n.<\/p>\n<p>Con un gui\u00f3n adaptado por el ganador del premio Bafta Frank Cottrell Boyce del libro de Michael Morpurgo, no faltan los creadores de palabras detr\u00e1s de esta emotiva historia.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"2\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"El Reino de Kensuke es un cuento animado tierno y hermoso.\" height=\"402\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722564743_462_Resena-de-Didi-una-historia-de-transicion-a-la-edad.jpg\" data-credit=\"PA\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722564743_462_Resena-de-Didi-una-historia-de-transicion-a-la-edad.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">El Reino de Kensuke es un cuento animado tierno y hermoso.<\/span><span class=\"article__credit\">Cr\u00e9dito: PA<\/span><\/figcaption><\/figure>\n<p>Y con personajes tra\u00eddos a la vida por Cillian Murphy, Sally Hawkins y Ken Watanabe, es imposible no quedar encantado.<\/p>\n<p>Es inteligentemente cautivador y tiene una forma suave y constante de hacerte pensar sobre cuestiones universales.<\/p>\n<p>La amistad, la supervivencia y la detonaci\u00f3n at\u00f3mica en Nagasaki durante la Segunda Guerra Mundial son s\u00f3lo algunos de los temas poderosos y de peso que se consideran bellamente.<\/p>\n<p>Y su enormidad permanece contigo mucho tiempo despu\u00e9s de verla.<\/p>\n<p>Las escenas exquisitamente dibujadas (en particular los cielos impresionantes y las representaciones hipn\u00f3ticas del agua) tambi\u00e9n son visualmente fascinantes.<\/p>\n<p>Sencilla, modesta pero a\u00fan m\u00e1s h\u00e1bil y sentida por ello, esta pel\u00edcula resonar\u00e1 en ti, sea cual sea tu edad.<\/p>\n<h2 class=\"wp-block-heading has-text-align-center\">HAROLD Y EL CRAY\u00d3N P\u00daRPURA<\/h2>\n<p class=\"has-text-align-center\">(PG) 90 minutos    <\/p>\n<h2 class=\"has-text-align-center\"><span style=\"color:#ff0000\">\u2605\u2606\u2606\u2606\u2606<\/span><\/h2>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"3\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Darcey Ewart es Robin en una nueva versi\u00f3n de la eterna aventura de forajidos.\" height=\"640\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722564743_30_Resena-de-Didi-una-historia-de-transicion-a-la-edad.jpg\" data-credit=\"PA\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/08\/1722564743_30_Resena-de-Didi-una-historia-de-transicion-a-la-edad.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Darcey Ewart es Robin en una nueva versi\u00f3n de la eterna aventura de forajidos.<\/span><span class=\"article__credit\">Cr\u00e9dito: PA<\/span><\/figcaption><\/figure>\n<p>ADAPTADO de un libro infantil de 1955, este cuento destrozado del personaje animado Harold, que cobra vida con su cray\u00f3n m\u00e1gico morado, habr\u00eda sido mejor dejarlo dentro de la imaginaci\u00f3n de los lectores j\u00f3venes.<\/p>\n<p>Finalmente, nuestro protagonista garabatea un portal para entrar al mundo real, se convierte en humano y va en busca del anciano que lo cre\u00f3.<\/p>\n<p>Acompa\u00f1ando a \u00e9l en su b\u00fasqueda est\u00e1n sus amigos Moose y Porcupine, quienes asumen interpretaciones humanas escalofriantes de los rasgos de sus respectivas criaturas.<\/p>\n<p>Tambi\u00e9n forman parte de la pandilla los nuevos amigos Terri (Zooey Deschanel de New Girl) y su hijo Mel.<\/p>\n<p>No hay mucho que tenga sentido en este mundo te\u00f1ido de leche.<\/p>\n<p>Harold es como un cruce entre Tom Hanks en Big y Will Ferrell en Elf, pero sin ning\u00fan encanto o matiz.<\/p>\n<p>\u00c9l camina con inocencia por todos lados con un gui\u00f3n que le hace ruido.<\/p>\n<p>El elenco adulto parece mayoritariamente mortificado. <\/p>\n<p>Y es poco probable que los ni\u00f1os, que son el supuesto p\u00fablico objetivo de este desastre, comprendan la subtrama surrealista con Jemaine Clement como el espeluznante autor fracasado Gary.<\/p>\n<div class=\"article-boxout\">\n<p><h3 class=\"article-boxout__headline t-s-border-color\">NOTICIAS DE CINE<\/h3>\n<\/p>\n<div class=\"article-boxout__content theme__background-color-rgba-20\">\n<div>\n<ul>\n<li>KATE Winslet interpreta a la legendaria fot\u00f3grafa de guerra Lee Miller en la pel\u00edcula biogr\u00e1fica Lee.<\/li>\n<li>Gladiator II tendr\u00e1 la secuencia de acci\u00f3n m\u00e1s grande que Ridley Scott haya hecho jam\u00e1s.<\/li>\n<li>Se ha confirmado una secuela de In A Violent Nature de este a\u00f1o.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/tv\/29634593\/didi-review-coming-of-age-comedy\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HICE (15) 91 minutos \u2605\u2605\u2605\u2605\u2606 En los viejos tiempos de 2008, antes del reinado de WhatsApp y TikTok,<\/p>\n","protected":false},"author":1,"featured_media":1301116,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[19844,8631,213467,31344,24393,18003,60320,4061,239506,4226,1490,1058,245694,24899,3733,66005,2457,219689,2757,158],"class_list":["post-1301115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-adulta","tag-california","tag-cola-larga","tag-conmovedora","tag-didi","tag-divertida","tag-dolorosamente","tag-edad","tag-el-periodico-the-sun","tag-estados-unidos","tag-historia","tag-hollywood","tag-kevin-bacon","tag-los-angeles","tag-netflix","tag-nostalgica","tag-resena","tag-seccion-tvcine","tag-transicion","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1301115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1301115"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1301115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1301116"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1301115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1301115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1301115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}