{"id":1291340,"date":"2024-07-25T19:13:13","date_gmt":"2024-07-25T19:13:13","guid":{"rendered":"https:\/\/teknomers.com\/es\/proximo-golpe-olimpico-nadal-tambien-se-tambalea\/"},"modified":"2024-07-25T19:13:18","modified_gmt":"2024-07-25T19:13:18","slug":"proximo-golpe-olimpico-nadal-tambien-se-tambalea","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/proximo-golpe-olimpico-nadal-tambien-se-tambalea\/","title":{"rendered":"Pr\u00f3ximo golpe ol\u00edmpico: Nadal tambi\u00e9n se tambalea"},"content":{"rendered":"\n<div>\n<p>La b\u00fasqueda del oro ol\u00edmpico en tenis se desarrollar\u00e1 en 2024 sin numerosas estrellas del escenario.  El jueves, otra jugadora top 10 cancel\u00f3 su salida en Par\u00eds.<\/p>\n<p>Elena Rybakina, que gan\u00f3 Wimbledon en 2022 y lleg\u00f3 a la final del Abierto de Australia en 2023, anunci\u00f3 el jueves que no participar\u00eda en los Juegos Ol\u00edmpicos de Par\u00eds. <\/p>\n<p>La kazaja de 25 a\u00f1os, que actualmente ocupa el cuarto puesto del mundo, es la segunda jugadora del top 10 que tiene que cancelar su salida en Rolland Garros despu\u00e9s de la bielorrusa Aryna Sabalenka, n\u00famero tres del mundo.  Adem\u00e1s, las exfinalistas de Grand Slam Ons Jabeur (T\u00fanez\/No. 16) y Madison Keys (EE.UU.\/No. 14) han anunciado su retirada.<\/p>\n<p>Seg\u00fan la asociaci\u00f3n kazaja, Rybakina padece bronquitis aguda.  Los m\u00e9dicos le prohibieron categ\u00f3ricamente luchar por las medallas. <\/p>\n<p>La cancelaci\u00f3n de Rybakina tambi\u00e9n podr\u00eda afectar a Angelique Kerber.  Si la alemana supera su dif\u00edcil obst\u00e1culo inicial, Naomi Osaka, Rybakina, que habr\u00eda sido la clara favorita contra la rumana Jacqueline Cristian en su primer partido, ya no ser\u00e1 una amenaza en la segunda ronda.<\/p>\n<p>El lugar de Rybakina en el campo lo ocupa ahora la francesa Caroline Garc\u00eda, tambi\u00e9n una rival dif\u00edcil.  Daria Saville de Australia tambi\u00e9n entra en el grupo como reemplazo. <\/p>\n<p><interaction id=\"6698c989fc7bc4e6b3145d1b\" class=\"apester-container hs-socialmedia-container hs-socialmedia-container--type-apester hs-socialmedia-container--orientation-center hs-socialmedia-container--width-max\"\/><\/p>\n<h2>El n\u00famero uno del mundo cancela la competici\u00f3n masculina<\/h2>\n<p>Tambi\u00e9n hubo cancelaciones muy sonadas entre los hombres: el n\u00famero uno del mundo, Jannik Sinner, de Italia, sufre de amigdalitis, y otros jugadores importantes est\u00e1n ausentes: Casper Ruud de Noruega, Grigor Dimitrov de Bulgaria y Hubert Hurkacz de Polonia.<\/p>\n<p>Pero eso no es todo: el comienzo de la leyenda de la tierra batida Rafael Nadal se ve repentinamente inestable despu\u00e9s de que el espa\u00f1ol tuvo que cancelar una sesi\u00f3n de entrenamiento con Alexander Zverev el jueves con poca antelaci\u00f3n debido a un &#8220;peque\u00f1o contratiempo&#8221;.<\/p>\n<p>El entrenador de Nadal, Carlos Moy\u00e1, dijo a la emisora \u200b\u200b\u200b\u200bde radio espa\u00f1ola &#8220;Onda Cero&#8221;.  Queda por ver si Nadal podr\u00e1 ser titular en el torneo ol\u00edmpico.  &#8220;No puedo garantizar nada. Tenemos que esperar y ver&#8221;, dijo Moya.<\/p>\n<p>Los primeros juegos comienzan en Par\u00eds el 27 de julio.  Desde la perspectiva alemana, entonces comenzar\u00e1n los Juegos Ol\u00edmpicos para Laura Siegemund (contra Danielle Collins) y Kerber, as\u00ed como para los dobles Dominik Koepfer y Jan-Lenard Struff (contra Mektic\/Pavic) y el d\u00fao femenino Tatjana Maria\/Tamara Korpatsch (contra Carle\/Podoroska).<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne6882815\/naechster-tennis-knall-bei-olympia---auch-rafael-nadal-wackelt\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La b\u00fasqueda del oro ol\u00edmpico en tenis se desarrollar\u00e1 en 2024 sin numerosas estrellas del escenario. El jueves,<\/p>\n","protected":false},"author":1,"featured_media":1291341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[203901,50303,5115,69,64610,244302,4551,2227,4227,4619,13212,733,711],"class_list":["post-1291340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-deportes-en-general","tag-elena-rybakina","tag-golpe","tag-juegos-olimpicos","tag-juegos-olimpicos-de-verano","tag-mujer-soltera","tag-nadal","tag-olimpico","tag-proximo","tag-rafael-nadal","tag-tambalea","tag-tambien","tag-tenis"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1291340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1291340"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1291340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1291341"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1291340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1291340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1291340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}