{"id":1291334,"date":"2024-07-25T19:11:07","date_gmt":"2024-07-25T19:11:07","guid":{"rendered":"https:\/\/teknomers.com\/es\/aduana-encuentra-tres-toneladas-de-metanfetamina-escondidas-en-bolsas-de-arena-procedentes-de-mexico\/"},"modified":"2024-07-25T19:11:13","modified_gmt":"2024-07-25T19:11:13","slug":"aduana-encuentra-tres-toneladas-de-metanfetamina-escondidas-en-bolsas-de-arena-procedentes-de-mexico","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/aduana-encuentra-tres-toneladas-de-metanfetamina-escondidas-en-bolsas-de-arena-procedentes-de-mexico\/","title":{"rendered":"Aduana encuentra tres toneladas de metanfetamina escondidas en bolsas de arena procedentes de M\u00e9xico"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>A principios de marzo, la aduana intercept\u00f3 m\u00e1s de 3.200 kilos de metanfetamina, m\u00e1s conocida como cristal, en el puerto de Rotterdam.  La droga estaba escondida en bolsas que conten\u00edan una &#8220;sustancia parecida a la arena&#8221; procedente de M\u00e9xico.  tiene eso <a rel=\"nofollow noopener\" data-id=\"https:\/\/www.om.nl\/actueel\/nieuws\/2024\/07\/25\/grootste-crystal-meth-vangst-in-nederland-tot-nu-toe\" data-type=\"link\" href=\"https:\/\/www.om.nl\/actueel\/nieuws\/2024\/07\/25\/grootste-crystal-meth-vangst-in-nederland-tot-nu-toe\" target=\"_blank\">Enjuiciamiento <\/a>anunciado el jueves.  El cargamento estaba destinado a una empresa de Den Hout, Brabante.  Un residente de esa localidad, de 55 a\u00f1os, ha sido detenido.  Ahora ha sido liberado, pero seguir\u00e1 siendo sospechoso mientras la aduana, el Ministerio P\u00fablico y la polic\u00eda portuaria investiguen la captura. <\/p>\n<p>Los sacos de arena en los que se escond\u00edan las drogas resultaron estar muy contaminados con cobre y PFAS.  Por eso se pasaron meses buscando la forma correcta de destruir la metanfetamina.  Esto se logr\u00f3 la semana pasada, informa el Ministerio P\u00fablico, aunque no se ha anunciado exactamente c\u00f3mo se hizo.  La remesa de droga tiene un valor de 22,4 millones de euros.  El Ministerio P\u00fablico habla de &#8220;la mayor incautaci\u00f3n de metanfetamina en los Pa\u00edses Bajos hasta la fecha&#8221;. <\/p>\n<p>El puerto de Rotterdam es un importante centro del tr\u00e1fico internacional de drogas.  Las drogas que desembarcan all\u00ed o en los puertos de Amberes y Vlissingen son distribuidas por toda Europa por parte de los narcotraficantes.  El a\u00f1o pasado, la aduana de Rotterdam encontr\u00f3 el mayor cargamento de coca\u00edna que hab\u00edan descubierto entre un cargamento de pl\u00e1tanos procedente de Ecuador: m\u00e1s de 8.088 kilos. <\/p>\n<p><dmt-icon class=\"dmt-article-suggestion__icon\" name=\"ic-forward\"\/><\/p>\n<div class=\"dmt-article-suggestion__text\">\n<p>\t\t\t\tLea tambi\u00e9n\n\t\t\t<\/p>\n<p><span>Nunca antes se hab\u00eda interceptado tanta coca\u00edna en los puertos de Rotterdam, Amberes y Vlissingen.<\/span>\n<\/div>\n<h2 class=\"article-heading wp-block-heading\" data-styled=\"false\"\/>\n<p><dmt-util-bar article=\"4860764\" headline=\"Douane vindt drie ton crystal meth verstopt in zakken zand uit Mexico\" url=\"https:\/\/www.nrc.nl\/nieuws\/2024\/07\/25\/douane-vindt-drie-ton-crystal-meth-verstopt-in-zakken-zand-uit-mexico-a4860764\"><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"share\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Para compartir<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-share-web\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"contact\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Env\u00ede un correo electr\u00f3nico al editor<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-email\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<\/dmt-util-bar> <\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2024\/07\/25\/douane-vindt-drie-ton-crystal-meth-verstopt-in-zakken-zand-uit-mexico-a4860764\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A principios de marzo, la aduana intercept\u00f3 m\u00e1s de 3.200 kilos de metanfetamina, m\u00e1s conocida como cristal, en<\/p>\n","protected":false},"author":1,"featured_media":1291335,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[77829,4970,4506,5194,23187,21146,940,202143,8483,1130],"class_list":["post-1291334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-aduana","tag-arena","tag-bolsas","tag-encuentra","tag-escondidas","tag-metanfetamina","tag-mexico","tag-procedentes","tag-toneladas","tag-tres"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1291334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1291334"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1291334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1291335"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1291334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1291334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1291334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}