{"id":1288015,"date":"2024-07-23T10:23:52","date_gmt":"2024-07-23T10:23:52","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-sc-magdeburg-incorpora-a-un-jugador-tuerto-en-la-defensa\/"},"modified":"2024-07-23T10:23:56","modified_gmt":"2024-07-23T10:23:56","slug":"el-sc-magdeburg-incorpora-a-un-jugador-tuerto-en-la-defensa","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-sc-magdeburg-incorpora-a-un-jugador-tuerto-en-la-defensa\/","title":{"rendered":"El SC Magdeburg incorpora a un jugador tuerto en la defensa"},"content":{"rendered":"\n<div>\n<p>El equipo de balonmano SC Magdeburg de la Bundesliga ha finalizado su b\u00fasqueda de refuerzos para el lateral izquierdo y ha fichado a Antonio Serradilla Cuenca procedente del club noruego Elverum H\u00e5ndball.  Lo especial: el espa\u00f1ol s\u00f3lo tiene un ojo.<\/p>\n<p>Serradilla ha firmado contrato con el SC Magdeburg para la pr\u00f3xima temporada. <\/p>\n<p>&#8220;El SC Magdeburg es uno de los mejores clubes del mundo, la Bundesliga es la liga m\u00e1s fuerte del mundo. No lo pens\u00e9 dos veces cuando recib\u00ed la solicitud. Me gustar\u00eda ayudar a que el SCM siga situ\u00e1ndose en lo m\u00e1s alto de la Bundesliga y de Europa&#8221;, afirm\u00f3 el jugador de 25 a\u00f1os.<\/p>\n<p>En Magdeburgo, Serradilla tambi\u00e9n deber\u00eda ayudar a sobrellevar la enorme carga de la pr\u00f3xima temporada.  &#8220;Con \u00e9l tenemos una opci\u00f3n importante, especialmente en nuestra red de cobertura, para poder distribuir mejor la carga en las pr\u00f3ximas cuatro competiciones m\u00e1s la Supercopa&#8221;, afirm\u00f3 el entrenador Bennet Wiegert.<\/p>\n<p>Seg\u00fan \u201cSport Bild\u201d, el SCM debe transferir una tarifa de transferencia al Elverum.  Se desconoce qu\u00e9 tan alto es.<\/p>\n<p>Serradilla se mud\u00f3 a Noruega procedente del club espa\u00f1ol BM Logro\u00f1o La Rioja a principios de 2023.  Jug\u00f3 14 partidos con la selecci\u00f3n espa\u00f1ola. <\/p>\n<p><interaction id=\"5f549b7352874d56981b290a\" class=\"apester-container hs-socialmedia-container hs-socialmedia-container--type-apester hs-socialmedia-container--orientation-center hs-socialmedia-container--width-max\"\/><\/p>\n<p>Serradilla tuvo que afrontar un duro golpe del destino en 2021.  Despu\u00e9s de experimentar repentinamente problemas de visi\u00f3n, le diagnosticaron un tumor en el ojo derecho.  El jugador de defensa decidi\u00f3 entonces someterse a una cirug\u00eda para extirparle el ojo.<\/p>\n<p>A pesar de tener una vista reducida, Serradilla regres\u00f3 al balonmano profesional.  Desde la operaci\u00f3n lleva gafas protectoras.<\/p>\n<p>&#8220;Fue un golpe duro, no esperaba que fuera tan grave. Fue bastante malo, fue una operaci\u00f3n complicada&#8221;, record\u00f3 su terrible experiencia en el portal de la Federaci\u00f3n Europea de Balonmano.<\/p>\n<h2>SC Magdeburg se queda con las manos vac\u00edas con Stutzke<\/h2>\n<p>Seg\u00fan los medios, la soluci\u00f3n deseada por el SC Magdeburg para el lateral izquierdo era el jugador nacional Lukas Stutzke.  El jugador de 26 a\u00f1os estuvo disponible en forma gratuita despu\u00e9s del descenso del Bergischer HC. <\/p>\n<p>Pero Stutzke decidi\u00f3 trasladarse al TSV Hannover-Burgdorf.  Firm\u00f3 un contrato en la capital del estado de Baja Sajonia hasta 2027.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne6874538\/handball-bundesliga-sc-magdeburg-holt-einaeugigen-rueckraumspieler\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo de balonmano SC Magdeburg de la Bundesliga ha finalizado su b\u00fasqueda de refuerzos para el lateral<\/p>\n","protected":false},"author":1,"featured_media":1287928,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[243845,1226,3275,203901,2103,14257,2783,9256,2097,154528],"class_list":["post-1288015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-antonio-serradilla-cuenca","tag-balonmano","tag-defensa","tag-deportes-en-general","tag-hbl","tag-incorpora","tag-jugador","tag-magdeburg","tag-sc-magdeburgo","tag-tuerto"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1288015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1288015"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1288015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1287928"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1288015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1288015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1288015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}