{"id":1287967,"date":"2024-07-23T09:22:27","date_gmt":"2024-07-23T09:22:27","guid":{"rendered":"https:\/\/teknomers.com\/es\/recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias-de-vacaciones-al-ano-la-gente-me-llama-criminal-pero-merezco-un-descanso-como-todos\/"},"modified":"2024-07-23T09:22:32","modified_gmt":"2024-07-23T09:22:32","slug":"recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias-de-vacaciones-al-ano-la-gente-me-llama-criminal-pero-merezco-un-descanso-como-todos","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias-de-vacaciones-al-ano-la-gente-me-llama-criminal-pero-merezco-un-descanso-como-todos\/","title":{"rendered":"Recibo tres tipos de beneficios, pero me voy cinco d\u00edas de vacaciones al a\u00f1o. La gente me llama &#8220;criminal&#8221;, pero merezco un descanso como todos."},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>YA sea un trago en Escocia, un frenes\u00ed en las carreras de Newmarket o unas cervezas en la playa de B\u00e9lgica, me encanta escaparme tan a menudo como puedo.<\/p>\n<p>Rara vez voy a los barrios bajos, mi objetivo es alojarme en establecimientos de 4 estrellas en general y disfrutar de las comidas y los vinos que ello conlleva.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"1\"><a rel=\"nofollow\" href=\"#\"><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">5<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Erica Crompton, que recibe el Cr\u00e9dito Universal, disfruta de unas cinco vacaciones al a\u00f1o<\/span><span class=\"article__credit\">Cr\u00e9dito: suministrado<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"2\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Ella dice que aquellos que reciben beneficios tienen el mismo derecho a vacaciones que las personas que trabajan.\" height=\"960\" width=\"679\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721726545_726_Recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias.jpg\" data-credit=\"Supplied\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721726545_726_Recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias.jpg?strip=all&amp;w=679\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">5<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Ella dice que aquellos que reciben beneficios tienen el mismo derecho a vacaciones que las personas que trabajan.<\/span><span class=\"article__credit\">Cr\u00e9dito: suministrado<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"3\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Ella y su pareja Paul disfrutaron recientemente de unas vacaciones en \u00c1msterdam.\" height=\"960\" width=\"721\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721726545_551_Recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias.jpg\" data-credit=\"Supplied\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721726545_551_Recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias.jpg?strip=all&amp;w=721\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">5<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Ella y su pareja Paul disfrutaron recientemente de unas vacaciones en \u00c1msterdam.<\/span><span class=\"article__credit\">Cr\u00e9dito: suministrado<\/span><\/figcaption><\/figure>\n<p>Me voy de vacaciones cortas al menos cinco veces al a\u00f1o, la mayor\u00eda al Reino Unido, pero a veces me aventuro un poco m\u00e1s lejos en Europa.<\/p>\n<p>S\u00e9 que muchos de ustedes estar\u00e1n pensando &#8216;\u00bfC\u00f3mo es que ella tiene vacaciones anuales?&#8217; Bueno, la respuesta corta es: no las tengo.<\/p>\n<p>No soy la esposa de un millonario ni una heredera rica; de hecho, recibo el Cr\u00e9dito Universal. <\/p>\n<p>Recibo la mitad de mi asignaci\u00f3n de \u00a3910 por vivir con una enfermedad mental grave llamada trastorno esquizoafectivo y psicosis, y la otra mitad por cuidar a mi pareja con quien ahora vivo (\u00e9l usa silla de ruedas a tiempo completo).<\/p>\n<p>El Cr\u00e9dito Universal no es el \u00fanico beneficio que recibo. Tambi\u00e9n recibo 290 libras al mes en concepto de Pagos Personales Independientes (PIP) por vivir con mi enfermedad mental. <\/p>\n<p>Esto actualmente est\u00e1 bajo revisi\u00f3n porque el DWP no considera que mi enfermedad mental grave sea permanente; creen que podr\u00eda mejorar o empeorar, por lo que me piden que vuelva a solicitar mi Pago Personal Independiente cada dos a\u00f1os. <\/p>\n<p>Me dijeron que en aproximadamente un a\u00f1o podr\u00eda necesitar una entrevista por tel\u00e9fono o en persona y, dependiendo de lo que piense el evaluador, mis beneficios podr\u00edan ser eliminados.<\/p>\n<p>Vivir con una enfermedad mental grave a menudo puede hacer que la vida sea dif\u00edcil, con ansiedad y paranoia diarias e insomnio frecuente.<\/p>\n<p>Creo que tengo derecho a mis beneficios, lo que significa que no tengo que trabajar a tiempo completo, lo que en el pasado ha empeorado mi enfermedad.<\/p>\n<p>Pero tambi\u00e9n creo que tengo derecho a tomarme vacaciones tan a menudo y con tanto estilo como quiera. <\/p>\n<div id=\"bc-video-6357199195112\" class=\"brightcove\"><span class=\"article__bc_video-caption\">Los trolls me llaman &#8220;gorr\u00f3n de los beneficios&#8221; porque vivo en una casa de protecci\u00f3n oficial, pero parece glamurosa gracias a las compras de B&#038;M e Ikea.<\/span><\/div>\n<p>\u00bfPor qu\u00e9 no? \u00bfNo es mi responsabilidad decidir c\u00f3mo gasto mis prestaciones? \u00bfAcaso las personas discapacitadas y desempleadas no merecen tambi\u00e9n un respiro?<\/p>\n<p>De todos modos, las vacaciones nunca nos han costado mucho porque a veces trabajo y lo combino con un descanso. Puedo trabajar un poco con mi Cr\u00e9dito Universal y cobrar. Tuve que hacer una entrevista con un evaluador para esto, que decidi\u00f3 que no era un trabajador aut\u00f3nomo, sino que &#8220;no era un trabajador aut\u00f3nomo remunerado&#8221;, ya que solo gano alrededor de \u00a34500 al a\u00f1o y todo es muy espor\u00e1dico.<\/p>\n<p>El dinero que gano me sirve para pagar mis vacaciones. Si trabajo en Escocia, lo convertir\u00e9 en un descanso de dos noches.<\/p>\n<p>A esto se le llama &#8216;workation&#8217;, y all\u00ed combino la peque\u00f1a cantidad de trabajo que me permiten hacer con unas vacaciones. <\/p>\n<p>El mes pasado, por ejemplo, ten\u00eda reservada una charla de una hora en \u00c1msterdam y utilic\u00e9 el dinero gastado en viajar y pasar un par de noches m\u00e1s en un hotel de la costa belga.<\/p>\n<p>\u00bfQu\u00e9 mejor manera de recompensarse por un trabajo bien hecho que con unas cervezas de trigo con vistas al mar?<\/p>\n<p>Tambi\u00e9n dirijo una peque\u00f1a revista ben\u00e9fica que cubre temas de viajes accesibles, as\u00ed que organizo viajes por todo el pa\u00eds a cambio de una rese\u00f1a de mi pareja en su silla de ruedas.<\/p>\n<p>La semana pasada vimos la final de f\u00fatbol de Inglaterra en un lujoso cine ubicado en un antiguo molino reformado en Clitheroe, Lancashire, y pudimos alojarnos en un hotel de 4 estrellas por una noche a cambio de un d\u00eda de pruebas de sillas de ruedas en el bosque de Bowland al d\u00eda siguiente.<\/p>\n<div class=\"article-boxout\">\n<p><h3 class=\"article-boxout__headline t-s-border-color\">CONSEJOS DE ERICA SOBRE C\u00d3MO PASAR VACACIONES GRATIS<\/h3>\n<\/p>\n<div class=\"article-boxout__content theme__background-color-rgba-20\">\n<div>\n<p>En todo el Reino Unido y en todo el mundo, tambi\u00e9n existe WWOOF: cultivar unas pocas horas al d\u00eda a cambio de comida y alojamiento, algo que hice en el pasado durante unas vacaciones de un mes en Lanarkshire, Escocia, despu\u00e9s de una estad\u00eda en el hospital.<\/p>\n<p>En aquel entonces yo recib\u00eda el antiguo Subsidio de Empleo y Apoyo, y realizaba trabajos agr\u00edcolas sencillos, como plantar y desmalezar, a cambio de tres comidas al d\u00eda y una cama individual en un dormitorio compartido.<\/p>\n<p>Si quieres ahorrar a\u00fan m\u00e1s y evitar la tarifa de suscripci\u00f3n anual de \u00a320 a WWOOF, prueba <a rel=\"nofollow noopener\" href=\"https:\/\/urldefense.com\/v3\/__http:\/\/HelpX.net__;!!F0Stn7g!CybMlt_RJ5L4vYHke_qwrc890vrQgkROMad0yTklDViGfviIW8OaEF1FF6VGfswNAupIMkS0F-IhP_naguOQUcfyUVOg5J91$\" target=\"_blank\">AyudaX.net<\/a> que es similar pero gratuito. <\/p>\n<p>Tambi\u00e9n incluye m\u00e1s tipos de &#8220;trabajo&#8221;, como limpiar casas o realizar tareas administrativas.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>Y esta primavera tambi\u00e9n nos alojamos en &#8216;Millionaire&#8217;s Row&#8217; en Newmarket. <\/p>\n<p>El hotel Bedford Lodge est\u00e1 situado en la famosa ciudad de las carreras y actualmente se est\u00e1 trabajando arduamente para hacer que la ciudad sea accesible para todos. <\/p>\n<p>Nos organizaron una cena de bistec y tambi\u00e9n nos dieron pases VIP para pasar un d\u00eda en las carreras (\u00a1aunque perd\u00ed mis pocas apuestas de \u00a35!)<\/p>\n<p>Y durante los \u00faltimos tres a\u00f1os, VisitScotland tambi\u00e9n nos ha acogido en viajes de trabajo. <\/p>\n<p>Sin duda, lo m\u00e1s destacado para nosotros fue alojarnos en el lujoso hotel de 4 estrellas Cringletie, que ha ganado premios por su accesibilidad, e incluso tomamos tragos de ginebra ilimitados en la destiler\u00eda 1881 en la cercana Peebles, en las fronteras escocesas.<\/p>\n<p>Pero no todo es cerveza y camas grandes. <\/p>\n<p>Al observar los comentarios de otros solicitantes del Cr\u00e9dito Universal que se atreven a mencionar que han estado de vacaciones en X (antes conocido como Twitter), se nos podr\u00eda perdonar que pens\u00e1ramos que somos criminales en lugar de discapacitados. <\/p>\n<p>A la gente como yo la atacan por atreverse a tomarse un descanso.<\/p>\n<p>Pero el hecho de que reciba prestaciones no significa que no pueda darme un capricho, especialmente con el subsidio por cuidados que recibo ahora. <\/p>\n<p>La vida puede ser dif\u00edcil, tanto para m\u00ed como para los dem\u00e1s, por favor no nos lo hagan m\u00e1s dif\u00edcil.<\/p>\n<div class=\"article-boxout\">\n<p><h3 class=\"article-boxout__headline t-s-border-color\">\u00bfQu\u00e9 es el trastorno esquizoafectivo?<\/h3>\n<\/p>\n<div class=\"article-boxout__content theme__background-color-rgba-20\">\n<p class=\"article__content--intro\">El trastorno esquizoafectivo es un problema de salud mental en el que se experimenta psicosis y s\u00edntomas del estado de \u00e1nimo. <\/p>\n<div>\n<p>Algunas personas han sugerido que el trastorno esquizoafectivo se sit\u00faa en el medio de un espectro, con <a rel=\"nofollow noopener\" href=\"https:\/\/www.mind.org.uk\/information-support\/types-of-mental-health-problems\/schizophrenia\/\" target=\"_blank\">esquizofrenia<\/a> en un extremo y <a rel=\"nofollow noopener\" href=\"https:\/\/www.mind.org.uk\/information-support\/types-of-mental-health-problems\/bipolar-disorder\/\" target=\"_blank\">trastorno bipolar<\/a> Por otro lado, esto se debe a que estos diagn\u00f3sticos comparten muchos s\u00edntomas similares, pero el trastorno esquizoafectivo se reconoce como un diagn\u00f3stico independiente.<\/p>\n<p>Es posible que haya momentos en los que le resulte dif\u00edcil cuidarse a s\u00ed mismo o en los que sus m\u00e9dicos consideren que no comprende bien su comportamiento y c\u00f3mo se siente. <\/p>\n<p>Los s\u00edntomas pueden comenzar a cualquier edad, pero suelen aparecer cuando eres un adulto joven. Algunas personas solo experimentan s\u00edntomas del trastorno esquizoafectivo una vez en la vida.<\/p>\n<p><em>Fuente: <a rel=\"nofollow noopener\" href=\"https:\/\/www.mind.org.uk\/information-support\/types-of-mental-health-problems\/schizoaffective-disorder\/about-schizoaffective-disorder\/\" target=\"_blank\" aria-label=\"Mind (opens in a new tab)\">Mente<\/a><\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"4\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"La pareja disfrut\u00f3 de una excelente cena con bistec en Newmarket.\" height=\"720\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721726546_762_Recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias.jpg\" data-credit=\"Supplied\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721726546_762_Recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">5<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">La pareja disfrut\u00f3 de una excelente cena con bistec en Newmarket.<\/span><span class=\"article__credit\">Cr\u00e9dito: suministrado<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"5\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"El escritor ha conseguido disfrutar de unas vacaciones gratis a cambio de rese\u00f1as.\" height=\"960\" width=\"720\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721726547_575_Recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias.jpg\" data-credit=\"Supplied\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721726547_575_Recibo-tres-tipos-de-beneficios-pero-me-voy-cinco-dias.jpg?strip=all&amp;w=720\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">5<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">El escritor ha conseguido disfrutar de unas vacaciones gratis a cambio de rese\u00f1as.<\/span><span class=\"article__credit\">Cr\u00e9dito: suministrado<\/span><\/figcaption><\/figure>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/fabulous\/29380645\/benefits-go-five-holidays-year-deserve-it\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>YA sea un trago en Escocia, un frenes\u00ed en las carreras de Newmarket o unas cervezas en la<\/p>\n","protected":false},"author":1,"featured_media":1287968,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[2283,203,4090,3370,213467,440,214100,124888,82979,10022,420,469,3641,222689,139,445,3074,34801,214128,267,13583,213628,16284,468,3790,1130,5083,13102],"class_list":["post-1287967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-ano","tag-belgica","tag-beneficios","tag-cinco","tag-cola-larga","tag-como","tag-consejos-de-viaje","tag-costo-de-la-vida","tag-credito-universal","tag-criminal","tag-descanso","tag-dias","tag-escocia","tag-exclusivo-fabuloso","tag-gente","tag-instagram","tag-llama","tag-merezco","tag-ofertas-de-viajes","tag-pero","tag-recibo","tag-salud-mental-y-enfermedad","tag-tipos","tag-todos","tag-trabajos","tag-tres","tag-vacaciones","tag-voy"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1287967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1287967"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1287967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1287968"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1287967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1287967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1287967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}