{"id":1287423,"date":"2024-07-22T22:30:11","date_gmt":"2024-07-22T22:30:11","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-knvb-recibe-el-premio-de-la-fifa-por-sus-competiciones-juveniles-innovadoras\/"},"modified":"2024-07-22T22:30:16","modified_gmt":"2024-07-22T22:30:16","slug":"la-knvb-recibe-el-premio-de-la-fifa-por-sus-competiciones-juveniles-innovadoras","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-knvb-recibe-el-premio-de-la-fifa-por-sus-competiciones-juveniles-innovadoras\/","title":{"rendered":"La KNVB recibe el premio de la FIFA por sus competiciones juveniles innovadoras"},"content":{"rendered":"\n<div>\n<p>  \u00bfPrefieres ver anuncios que coincidan con tus intereses?  Mediahuis Noord, en colaboraci\u00f3n con afiliados que, como ellos, forman parte del grupo Mediahuis, elabora perfiles de grupo conjuntos para mostrarle publicidad personalizada en base a ellos.  Con su permiso, compartimos los siguientes datos con partes afiliadas dentro del grupo Mediahuis para anuncios personalizados en las plataformas de Mediahuis Noord y estas partes afiliadas: <\/p>\n<ul>\n<li>Detalles de la cuenta: sexo, fecha de nacimiento, lugar de residencia y n\u00famero de cliente<\/li>\n<\/ul>\n<p>  Puede encontrar m\u00e1s informaci\u00f3n sobre c\u00f3mo utilizamos sus datos en nuestra <a rel=\"nofollow noopener\" href=\"https:\/\/www.mediahuisnoord.nl\/privacy\/\" target=\"_blank\">pol\u00edtica de privacidad<\/a> y <a rel=\"nofollow noopener\" href=\"https:\/\/www.mediahuisnoord.nl\/cookieverklaring_tcf2-0\/\" target=\"_blank\">pol\u00edtica de cookies<\/a>. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.dvhn.nl\/sport\/KNVB-krijgt-FIFA-prijs-voor-innovatieve-jeugdcompetities-29147161.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-45<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPrefieres ver anuncios que coincidan con tus intereses? Mediahuis Noord, en colaboraci\u00f3n con afiliados que, como ellos, forman<\/p>\n","protected":false},"author":1,"featured_media":1287424,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[213044,4978,5481,13932,13605,7486,213070,231,2761,3064,251,213071],"class_list":["post-1287423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-tipotermino-definido","tag-competiciones","tag-fifa","tag-innovadoras","tag-juveniles","tag-knvb","tag-nombre-futbol","tag-por","tag-premio","tag-recibe","tag-sus","tag-urldvhn-nl-tags-labels-voetbal-1"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1287423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1287423"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1287423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1287424"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1287423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1287423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1287423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}