{"id":1286700,"date":"2024-07-22T11:10:18","date_gmt":"2024-07-22T11:10:18","guid":{"rendered":"https:\/\/teknomers.com\/es\/ousmane-dembele-el-tecnico-critica-a-la-estrella-del-psg-juega-como-una-persona-autista\/"},"modified":"2024-07-22T11:10:23","modified_gmt":"2024-07-22T11:10:23","slug":"ousmane-dembele-el-tecnico-critica-a-la-estrella-del-psg-juega-como-una-persona-autista","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/ousmane-dembele-el-tecnico-critica-a-la-estrella-del-psg-juega-como-una-persona-autista\/","title":{"rendered":"Ousmane Demb\u00e9l\u00e9: El t\u00e9cnico critica a la estrella del PSG \u2013 &quot;juega como una persona autista&quot;"},"content":{"rendered":"\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"font-bold text-18 leading-17\">Ousmane Demb\u00e9l\u00e9 es uno de los futbolistas m\u00e1s talentosos del mundo.  Pero a\u00fan no ha logrado su gran avance.  Un entrenador critica y luego se disculpa.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Ousmane Demb\u00e9l\u00e9 disput\u00f3 cinco partidos en la Eurocopa de Alemania, pero el talentoso extremo no marc\u00f3 ning\u00fan gol.  Una estad\u00edstica bastante decepcionante para el exjugador del Borussia Dortmund, considerado uno de los futbolistas m\u00e1s talentosos del mundo.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El t\u00e9cnico Jorge Sampaoli tambi\u00e9n valora las cualidades de Demb\u00e9l\u00e9.  En una entrevista con la revista francesa &#8220;So Foot&#8221;, el argentino tambi\u00e9n critic\u00f3 al joven de 27 a\u00f1os.  &#8220;Cuando pasa a un oponente, los dem\u00e1s jugadores son como espectadores. Saben que juega como un autista: comienza la acci\u00f3n y la termina solo&#8221;, dijo Sampaoli, a\u00f1adiendo: &#8220;No tiene la capacidad de hacer Su poner a sus compa\u00f1eros en el punto de mira. Simplemente sabe brillar \u00e9l mismo. &#8220;Mbapp\u00e9 se parece un poco a \u00e9l&#8221;.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El propio Sampaoli tambi\u00e9n recibi\u00f3 muchas cr\u00edticas por la frase \u201ccomo un autista\u201d, por lo que volvi\u00f3 a pronunciarse en Instagram.  &#8220;Nunca tuve la intenci\u00f3n de referirme al autismo. Pido disculpas a todos. Quer\u00eda hablar de individualidad&#8221;.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El exseleccionador argentino tambi\u00e9n prometi\u00f3 mejorar: &#8220;M\u00e1s que nunca tenemos que tener cuidado con las palabras que elegimos&#8221;.  Y el franc\u00e9s no es tan testarudo como Sampaoli retrat\u00f3 a Demb\u00e9l\u00e9.  En un total de 306 partidos competitivos a nivel de clubes, el fuerte atacante prepar\u00f3 84 goles y anot\u00f3 68.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/fussball\/international\/id_100453628\/ousmane-dembele-trainer-kritisiert-psg-star-spielt-wie-ein-autist-.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ousmane Demb\u00e9l\u00e9 es uno de los futbolistas m\u00e1s talentosos del mundo. Pero a\u00fan no ha logrado su gran<\/p>\n","protected":false},"author":1,"featured_media":1286701,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[243706,83,203197,440,2458,38,31928,486,40184,79446,32145,39429,5389,8945,88672,1278,158],"class_list":["post-1286700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-autistaquot","tag-bvb","tag-campeonato-de-europa-de-futbol","tag-como","tag-critica","tag-del","tag-dembele","tag-estrella","tag-jorge-sampaoli","tag-ousmane","tag-ousmane-dembele","tag-paris-sg","tag-persona","tag-psg","tag-quotjuega","tag-tecnico","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1286700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1286700"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1286700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1286701"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1286700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1286700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1286700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}