{"id":1284902,"date":"2024-07-20T19:53:12","date_gmt":"2024-07-20T19:53:12","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-ex-estrella-del-chelsea-exige-que-los-blues-venda-a-enzo-fernandez-porque-nunca-sera-perdonado-por-la-ola-de-racismo\/"},"modified":"2024-07-20T19:53:17","modified_gmt":"2024-07-20T19:53:17","slug":"la-ex-estrella-del-chelsea-exige-que-los-blues-venda-a-enzo-fernandez-porque-nunca-sera-perdonado-por-la-ola-de-racismo","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-ex-estrella-del-chelsea-exige-que-los-blues-venda-a-enzo-fernandez-porque-nunca-sera-perdonado-por-la-ola-de-racismo\/","title":{"rendered":"La ex estrella del Chelsea exige que los Blues VENDA a Enzo Fern\u00e1ndez porque &#8220;nunca ser\u00e1 perdonado&#8221; por la ola de racismo"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong>La ex estrella del Chelsea, Tony Cascarino, cree que su antiguo equipo deber\u00eda VENDER a Enzo Fern\u00e1ndez.<\/strong><\/p>\n<p>La estrella argentina est\u00e1 en problemas despu\u00e9s de filmarse a s\u00ed mismo y a sus compa\u00f1eros de selecci\u00f3n internacional cantando una vil canci\u00f3n racista sobre la selecci\u00f3n nacional francesa.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"1\"><a rel=\"nofollow\" href=\"#\"><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Tony Cascarino cree que el Chelsea tendr\u00e1 que vender a Enzo Fern\u00e1ndez tras su ola de racismo<\/span><span class=\"article__credit\">Cr\u00e9dito: PA<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"2\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"El as argentino se film\u00f3 a s\u00ed mismo cantando un c\u00e1ntico vil sobre la selecci\u00f3n nacional francesa\" height=\"454\" width=\"476\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721505191_857_La-ex-estrella-del-Chelsea-exige-que-los-Blues-VENDA.jpg\" data-credit=\"Instagram @enzojfernandez\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721505191_857_La-ex-estrella-del-Chelsea-exige-que-los-Blues-VENDA.jpg?strip=all&amp;w=476\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">El as argentino se film\u00f3 a s\u00ed mismo cantando un c\u00e1ntico vil sobre la selecci\u00f3n nacional francesa<\/span><span class=\"article__credit\">Cr\u00e9dito: Instagram @enzojfernandez<\/span><\/figcaption><\/figure>\n<p>Fern\u00e1ndez recibi\u00f3 una gran reacci\u00f3n por el clip, y varias estrellas del Chelsea dejaron de seguirlo en las redes sociales.<\/p>\n<p>Wesley Fofana incluso recurri\u00f3 a Internet para criticar el \u201cracismo desinhibido\u201d.<\/p>\n<p>Y SunSport entiende que los Blues enfrentan una importante divisi\u00f3n en el vestuario antes de la nueva campa\u00f1a de la Premier League.<\/p>\n<p>Fern\u00e1ndez se ha disculpado desde entonces por su participaci\u00f3n en los c\u00e1nticos ofensivos.<\/p>\n<p>Pero a\u00fan queda por ver si puede hacer las paces con sus amigos del Chelsea, incluido el gran contingente de estrellas francesas del club.<\/p>\n<p>Y el ex as de Stamford Bridge, Cascarino, cree que Fern\u00e1ndez no le ha dejado a los Blues otra opci\u00f3n que venderlo.<\/p>\n<p>Siente que los comentarios de Fern\u00e1ndez lo mantendr\u00e1n dividido para siempre del resto del vestuario.<\/p>\n<p>Y a pesar de haber pagado hace 18 meses una cifra r\u00e9cord de 105 millones de libras para fichar al ganador de la Copa del Mundo, el Chelsea deber\u00eda reducir sus p\u00e9rdidas en aras de la unidad del equipo.<\/p>\n<p>Cascarino le dijo a talkSPORT: &#8220;Va a ser complicado. Miro hacia atr\u00e1s, cuando estaba en el Chelsea en los a\u00f1os 90, y no estoy seguro de que el vestuario estuviera de acuerdo con lo que hizo Enzo Fern\u00e1ndez.<\/p>\n<p>&#8220;Es una situaci\u00f3n complicada de abordar. Creo que el Chelsea tiene que tomar una decisi\u00f3n importante sobre si realmente se queda con Enzo Fern\u00e1ndez.<\/p>\n<div id=\"bc-video-6358143073112\" class=\"brightcove\"><span class=\"article__bc_video-caption\">Los fan\u00e1ticos del Chelsea no pueden esperar la nueva temporada tras la aparici\u00f3n de un video de la sesi\u00f3n de entrenamiento, pero algunos temen que &#8220;estemos revelando demasiado&#8221;<\/span><\/div>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"3\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Cascarino cree que hay una manera en que Fern\u00e1ndez puede redimirse\" height=\"755\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721505192_770_La-ex-estrella-del-Chelsea-exige-que-los-Blues-VENDA.jpg\" data-credit=\"The Sun\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721505192_770_La-ex-estrella-del-Chelsea-exige-que-los-Blues-VENDA.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Cascarino cree que hay una manera en que Fern\u00e1ndez puede redimirse<\/span><span class=\"article__credit\">Cr\u00e9dito: The Sun<\/span><\/figcaption><\/figure>\n<p>\u201cAl tener jugadores que no est\u00e1n contentos con un chico en el vestuario, no estoy seguro de que haya muchos que se sientan c\u00f3modos con algunas de las cosas que han sucedido.<\/p>\n<p>&#8220;No hay excusa para que eso salga a la luz. No les va a sentar bien a los otros jugadores, \u00bfno?<\/p>\n<p>\u201cNo s\u00e9 c\u00f3mo se puede manejar esto porque habr\u00e1 jugadores que no puedan perdonar. Puede haber algunos que puedan seguir adelante a pesar de que no les guste lo que pas\u00f3.<\/p>\n<p>&#8220;No es necesario que todos los miembros del club se lleven bien, pero esto es muy complicado. Algunos jugadores no querr\u00e1n seguir adelante o no querr\u00e1n que la relaci\u00f3n funcione&#8221;.<\/p>\n<p>Pero Cascarino cree que puede haber una \u00faltima forma en que Fern\u00e1ndez pueda volver a estar en la buena p\u00e1gina del Chelsea.<\/p>\n<p>A\u00f1adi\u00f3: \u201cTambi\u00e9n tendr\u00e1 que disculparse cara a cara con el equipo y quiz\u00e1s entonces habr\u00e1 un poco m\u00e1s de perd\u00f3n\u201d.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container\" data-index=\"3\"><img loading=\"lazy\" decoding=\"async\" height=\"960\" width=\"635\" class=\"lazyload alignnone size-thesun-article-image wp-image-28563545\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721505192_410_La-ex-estrella-del-Chelsea-exige-que-los-Blues-VENDA.jpg\" data-credit=\"\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721505192_410_La-ex-estrella-del-Chelsea-exige-que-los-Blues-VENDA.jpg?strip=all&amp;w=635\"  role=\"img\"\/><\/div>\n<\/figure>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/sport\/29364813\/chelsea-enzo-fernandez-transfer-exit-tony-cascarino\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ex estrella del Chelsea, Tony Cascarino, cree que su antiguo equipo deber\u00eda VENDER a Enzo Fern\u00e1ndez. La<\/p>\n","protected":false},"author":1,"featured_media":1284903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[8226,272,38,49097,69638,486,204,10359,36,239851,241291,78,4024,59108,231,2538,7489,212972,213010,201,63301],"class_list":["post-1284902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-blues","tag-chelsea","tag-del","tag-enzo","tag-enzo-fernandez","tag-estrella","tag-exige","tag-fernandez","tag-los","tag-noticias-de-transferencias","tag-noticias-sobre-el-fichaje-del-chelsea","tag-nunca","tag-ola","tag-perdonado","tag-por","tag-porque","tag-racismo","tag-seccion-deportefutbol","tag-seccion-deportefutbolpremier-league","tag-sera","tag-venda"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1284902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1284902"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1284902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1284903"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1284902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1284902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1284902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}