{"id":1284791,"date":"2024-07-20T17:45:21","date_gmt":"2024-07-20T17:45:21","guid":{"rendered":"https:\/\/teknomers.com\/es\/fue-eso-todo-para-perez-marko-se-vuelve-claro\/"},"modified":"2024-07-20T17:45:25","modified_gmt":"2024-07-20T17:45:25","slug":"fue-eso-todo-para-perez-marko-se-vuelve-claro","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/fue-eso-todo-para-perez-marko-se-vuelve-claro\/","title":{"rendered":"\u00bfFue eso todo para P\u00e9rez?  Marko se vuelve claro"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>\u00bfCu\u00e1ndo se le acabar\u00e1 la paciencia a Red Bull Racing con Sergio P\u00e9rez?  Esta pregunta se hace cada vez con m\u00e1s fuerza tras la devastadora ca\u00edda del mexicano en la clasificaci\u00f3n para el Gran Premio de Hungr\u00eda.  Mientras Helmut Marko, consultor de Red Bull, se refiere al planteamiento planificado del equipo austriaco de F\u00f3rmula 1, el experto en F1 Ralf Schumacher lo deja claro.<\/p>\n<p>El ya contabilizado piloto de F\u00f3rmula 1 Sergio P\u00e9rez choc\u00f3 su coche contra las barreras en la Q1 durante la clasificaci\u00f3n para el Gran Premio de Hungr\u00eda y provoc\u00f3 importantes da\u00f1os en el coche &#8211; P\u00e9rez ya hab\u00eda tenido un accidente en la clasificaci\u00f3n el fin de semana anterior en Silverstone.<\/p>\n<p>En Hungr\u00eda, en la primera sesi\u00f3n de clasificaci\u00f3n del s\u00e1bado por la tarde, patin\u00f3 en la novena posici\u00f3n en la curva 7 despu\u00e9s de girar demasiado a la derecha antes de tomar la curva a la izquierda, donde la pista estaba evidentemente mojada.  En la curva 8, el guardarrail acab\u00f3 bruscamente con las esperanzas de mejora del mexicano, que ahora partir\u00e1 desde la 16\u00aa posici\u00f3n de la parrilla (domingo, 15.00 horas, RTL y Sky).<\/p>\n<p>Despu\u00e9s de s\u00f3lo 15 puntos en los \u00faltimos seis Grandes Premios, P\u00e9rez ya tem\u00eda por su habit\u00e1culo antes del fin de semana en Hungr\u00eda, pero ahora surgi\u00f3 la pregunta de si podr\u00eda perderlo incluso m\u00e1s r\u00e1pido de lo esperado.<\/p>\n<p>Pero Helmut Marko, consultor de deportes de motor de Red Bull, le pes\u00f3.  &#8220;Mantendremos nuestro enfoque y esperaremos a la pr\u00f3xima carrera (en Spa\/B\u00e9lgica, editor). Luego nos sentaremos juntos y veremos qu\u00e9 vamos a hacer&#8221;, pospuso Marko la decisi\u00f3n de P\u00e9rez en &#8220;Sky&#8221;. . por una semana. <\/p>\n<h2>Red Bull Racing piensa en Lawson como sustituto de P\u00e9rez<\/h2>\n<p>Liam Lawson es considerado un posible reemplazo directo del tambaleante mexicano.  No s\u00f3lo realiz\u00f3 recientemente un buen test, &#8220;sino que tambi\u00e9n trabaj\u00f3 mucho en el simulador&#8221;, enfatiz\u00f3 Marko y a\u00f1adi\u00f3 significativamente: &#8220;\u00c9se es sin duda un candidato, si es que aparece un candidato necesario&#8221;.<\/p>\n<p><interaction id=\"668d6e9c10b68b54f0ff1156\" class=\"apester-container hs-socialmedia-container hs-socialmedia-container--type-apester hs-socialmedia-container--orientation-center hs-socialmedia-container--width-max\"\/><\/p>\n<p>Mientras Marko intentaba mostrar lo menos posible su decepci\u00f3n por la actual crisis de P\u00e9rez, el experto en televisi\u00f3n Ralf Schumacher en &#8220;Sky&#8221; se mostr\u00f3 m\u00e1s claro.<\/p>\n<p>&#8220;\u00bfCu\u00e1ntas veces deber\u00eda decirlo? No s\u00e9 cu\u00e1nto tiempo Red Bull observar\u00e1 esto y lo har\u00e1. Creo que ya no tiene sentido. Y P\u00e9rez lo sabe&#8221;, dijo Schumacher.<\/p>\n<h2>Schumacher: P\u00e9rez deber\u00eda ser liberado<\/h2>\n<p>&#8220;Ahora vuelve a empezar desde atr\u00e1s. Los da\u00f1os, ni siquiera necesitamos hablar de eso. Red Bull tiene tantos pilotos. Esto tiene que llegar a su fin. Realmente deber\u00eda ser liberado. Lo siento. Eso es todo. Para \u00e9l &#8220;tambi\u00e9n es una cat\u00e1strofe&#8221;, concluy\u00f3 el ex piloto de F1.<\/p>\n<p>Adem\u00e1s de P\u00e9rez, Max Verstappen tampoco se mostr\u00f3 satisfecho con el resultado de la clasificaci\u00f3n, en la que el campe\u00f3n del mundo termin\u00f3 en tercer lugar.  Cuando se le pregunt\u00f3 c\u00f3mo quer\u00eda vencer a sus actuales rivales m\u00e1s cercanos de McLaren el domingo, el holand\u00e9s se limit\u00f3 a decir: &#8220;No lo s\u00e9&#8221;.<\/p>\n<div class=\"hs-news-image-container hs-news-image-container--orientation-center hs-news-image-container--width-max\"><\/div>\n<p>Gracias a una gran actuaci\u00f3n en la clasificaci\u00f3n, Lando Norris y Oscar Piastri consiguieron el primer y segundo puesto y, por tanto, se encuentran en la primera fila de la parrilla.<\/p>\n<p>&#8220;Podemos controlar la carrera desde delante&#8221;, dijo Norris.  El joven de 24 a\u00f1os celebr\u00f3 su primera victoria en F\u00f3rmula 1 este a\u00f1o en Miami y quiere m\u00e1s.  &#8220;El coche va genial, el objetivo para ma\u00f1ana es el primer puesto&#8221;.<\/p>\n<p>Su compa\u00f1ero de equipo australiano adopta un tono a\u00fan mayor.  &#8220;Tenemos una gran tarea: ganar el campeonato de constructores&#8221;, afirm\u00f3 el piloto de 23 a\u00f1os.<\/p>\n<p>Eso no es absurdo.  Aunque la diferencia con Red Bull es actualmente de 78 puntos, Verstappen vuelve a ser un luchador solitario tras la ca\u00edda de P\u00e9rez.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne6868841\/crash-bei-formel-1-in-ungarn-wars-das-fuer-perez-marko-wird-deutlich\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1ndo se le acabar\u00e1 la paciencia a Red Bull Racing con Sergio P\u00e9rez? Esta pregunta se hace cada<\/p>\n","protected":false},"author":1,"featured_media":1284792,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[6860,202108,6172,203901,1075,276,244,94235,29438,18,23335,26921,2571,339,647],"class_list":["post-1284791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-automovilismo","tag-carreras-de-toro-rojo","tag-claro","tag-deportes-en-general","tag-eso","tag-formula-1","tag-fue","tag-gran-premio-de-hungria","tag-marko","tag-para","tag-perez","tag-sergio-perez","tag-sport-de-video","tag-todo","tag-vuelve"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1284791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1284791"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1284791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1284792"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1284791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1284791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1284791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}