{"id":1284245,"date":"2024-07-20T07:15:10","date_gmt":"2024-07-20T07:15:10","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-actriz-romana-como-el-ultimo-personaje-que-interpreto-en-till-night-do-us-part-se-encuentra-en-esa-fase-de-la-vida-en-la-que-hay-que-tomar-grandes-decisiones-un-master-un-hijo-una-hipoteca\/"},"modified":"2024-07-20T07:15:15","modified_gmt":"2024-07-20T07:15:15","slug":"la-actriz-romana-como-el-ultimo-personaje-que-interpreto-en-till-night-do-us-part-se-encuentra-en-esa-fase-de-la-vida-en-la-que-hay-que-tomar-grandes-decisiones-un-master-un-hijo-una-hipoteca","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-actriz-romana-como-el-ultimo-personaje-que-interpreto-en-till-night-do-us-part-se-encuentra-en-esa-fase-de-la-vida-en-la-que-hay-que-tomar-grandes-decisiones-un-master-un-hijo-una-hipoteca\/","title":{"rendered":"La actriz romana, como el \u00faltimo personaje que interpret\u00f3 en &#8220;Till Night Do Us Part&#8221;, se encuentra en esa fase de la vida en la que hay que tomar grandes decisiones: &#8220;Un m\u00e1ster, un hijo, una hipoteca&#8221;&#8230;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"p1\">\u00ab<strong class=\"first-letter\">\u00abPilar Fogliati, me hiciste re\u00edr mucho<\/strong>\u00bb.<br \/>La actriz romana, especializada en matices (del dialecto romano -y son infinitos- pero pruebe a pedirle que act\u00fae en piamont\u00e9s gen\u00e9rico), suspira aliviada: &#8220;Si os he entretenido, soy feliz&#8221;.<\/p>\n<div id=\"wrapper_video_embed\" class=\"player_single_video_component\">\n<div id=\"divVideoPlayer\" class=\"video-sticky-box privacyAccettata\">\n<div class=\"video-sticky-box-inner\">\n<div class=\"video-sticky-box-frame-cont\">\n<div class=\"player player_video_rcs player_shortcode custom-video-sticky\" data-config=\"{&quot;newspaper&quot;:&quot;rcs&quot;,&quot;uuid&quot;:&quot;iodonna-0002283178&quot;,&quot;muted&quot;:true,&quot;blockAdv&quot;:false,&quot;ovlLogo&quot;:false,&quot;autoplay&quot;:true,&quot;watermark&quot;:false,&quot;scale&quot;:&quot;with-parent&quot;,&quot;poster&quot;:{&quot;pre&quot;:{&quot;type&quot;:&quot;bySelector&quot;,&quot;container&quot;:&quot;.player_preview&quot;,&quot;play&quot;:&quot;.play&quot;,&quot;playByContainer&quot;:true}},&quot;playerPage&quot;:&quot;tvSticky&quot;,&quot;tipo_video&quot;:&quot;articolo_ancorato&quot;}\">\n<div class=\"player_preview\">\n                                    <img decoding=\"async\" class=\"\" alt=\"Pilar Fogliati: \u00abEn \u201cRomeo es Julieta\u201d hablo de nosotros, los actores precarios\u00bb\" title=\"Pilar Fogliati: \u00abEn \u201cRomeo es Julieta\u201d hablo de nosotros, los actores precarios\u00bb\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/La-actriz-romana-como-el-ultimo-personaje-que-interpreto-en.webp.webp\"\/>                                    <span class=\"player_button play\"\/>\n                                <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"p2\"><span class=\"s1\">La comedia como vocaci\u00f3n, pero con una apertura a la comedia rom\u00e1ntica.  Recogi\u00f3 el Nastro d&#8217;argento (ex aequo con Virginia Raffaele) como mejor actriz de comedia <i>Romeo y Julieta<\/i>y el premio Anica80 por su debut como director con <i>Rom\u00e1ntico<\/i>, Pilar Fogliati no se siente inc\u00f3moda si le piden que se considere la Meg Ryan de Appia o Pigneto: \u00abLa \u201crom-com\u201d es uno de mis g\u00e9neros favoritos.  A quienes, viendo comedias americanas de los a\u00f1os 90, dicen: &#8220;\u00a1Pero estas cosas no suceden en la vida!&#8221;, les respondo: &#8220;\u00a1Exactamente!&#8221;.  Tambi\u00e9n porque luego cuando nos pasa algo incre\u00edble exclamamos: \u201c\u00a1No sabes lo que me pas\u00f3, parec\u00eda de pel\u00edcula!\u201d\u00bb.<\/span><\/p>\n<article class=\"id-vda-article box_ed_hp_02-article eltdf-item-space hentry-pos-i hentry-home_section-i post-iiiii post type-post status-publish format-standard hentry\">\n<\/article>\n<p class=\"p3\"><strong><span class=\"s2\">Pronto dir\u00e1s: &#8220;Parec\u00eda una serie de televisi\u00f3n&#8221;.<br \/><\/span><\/strong>Nooo, nunca lo diremos.  &#8220;Pel\u00edcula&#8221; suena mejor.<\/p>\n<div id=\"attachment_2371670\" data-thumbnail_id=\"2371670\" class=\"wp-caption aligncenter\" style=\"width:1034px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">Pilaer Fogliati y Filippo Scicchitano en \u201cHasta que la noche nos separe\u201d.<\/p>\n<\/div>\n<p class=\"p3\"><strong><span class=\"s2\">Uno de los suyos se estrenar\u00e1 a finales de agosto: <i>Hasta que la noche nos separe<\/i>dirigida por Riccardo Antonaroli, nueva versi\u00f3n de la israel\u00ed <i>Luna de miel<\/i>que la ve como una reci\u00e9n casada que deambula por la Roma nocturna con su joven marido, interpretado por Filippo Scicchitano.<br \/><\/span><\/strong>Lo bonito es que el director realmente se pregunt\u00f3: &#8220;Pero dos que acaban de casarse, que dijeron que eran &#8220;para siempre&#8221;, que saludaron a 200 personas en la recepci\u00f3n, cuando finalmente cruzan el umbral de la suite nupcial, \u00bfqu\u00e9 hacen? \u00bfhacer? ?&#8221;.  Deber\u00eda ser obvio, pero&#8230; Estos dos, por ejemplo, empiezan a discutir y la noche da un giro inesperado, que es una forma de volver a cuestionarse, in extremis, sobre ese pacto que acaban de hacer.  Luego comienza una aventura un tanto on\u00edrica por los callejones de la ciudad, donde podr\u00e1s conocer a una chica con un vestido de novia e inmediatamente despu\u00e9s al cami\u00f3n de la basura.  Porque esto es Roma, la gaviota sobre la basura y dos amantes bes\u00e1ndose cerca.<\/p>\n<p class=\"p3\"><strong><span class=\"s2\">\u00bfUna idea de c\u00f3mo son los italianos de treinta a\u00f1os que deciden casarse?<br \/><\/span><\/strong>Ellos son quienes respondieron a la pregunta: \u201c\u00bfTodav\u00eda me doy un tiempo o doy el gran paso?\u201d.  Es mi generaci\u00f3n y la pel\u00edcula toma este momento como pretexto para hablar de nuestras dudas, esa fase de transici\u00f3n en la que ya no eres una ni\u00f1a, eres casi una mujer, pero a\u00fan conservas rasgos infantiles.  Piensas en tu carrera, quieres saber qui\u00e9n eres y tienes que tomar grandes decisiones, conseguir una maestr\u00eda, un hijo, una hipoteca.  Cosas todas que tienen mucho que ver con la situaci\u00f3n precaria que vive mi generaci\u00f3n.  Cuando sientes que todo es precario, \u00bfc\u00f3mo decir \u201cpara siempre\u201d?<\/p>\n<h2>La vida en pareja en un apartamento de dos habitaciones.<\/h2>\n<p class=\"p3\"><strong><span class=\"s2\">Hay un personaje secundario en la hermosa novela. <a rel=\"nofollow noopener\" href=\"https:\/\/www.adelphi.it\/libro\/9788845939006\" target=\"_blank\" data-wpel-link=\"external\"><i>Para\u00edso<\/i> por Michele Masneri<\/a> (Adelphi) que tambi\u00e9n habla de esto: transforma las casas, reduce los pisos de tres y cuatro habitaciones que compran las parejas cuando forman una familia a apartamentos de dos habitaciones, cuando se separan.  El apartamento de dos habitaciones, destino obligado de los solteros.<br \/><\/span><\/strong>Interesante ver los cambios existenciales en relaci\u00f3n al espacio vital.  Sin embargo, vivo en un apartamento de dos habitaciones con mi novio.  Una casa perfecta para dos, un espacioso apartamento de dos habitaciones.  Llevo poco tiempo viviendo con \u00e9l, lo postergamos mucho, no pudimos tomar la decisi\u00f3n.  Y tan pronto como hicimos eso, comenc\u00e9 a hacer mi pel\u00edcula nocturna.  Sal\u00ed a las 6 de la tarde y regres\u00e9 a las 5. Sin embargo, como toda persona normal, se despert\u00f3 a las 8 de la ma\u00f1ana para ir a trabajar.  Me preguntaron: \u201c\u00bfC\u00f3mo es la convivencia?\u201d.  \u201c\u00bfY qui\u00e9n lo ve?\u201d  Respond\u00ed.<\/p>\n<div id=\"attachment_2371675\" data-thumbnail_id=\"2371675\" class=\"wp-caption aligncenter\" style=\"width:1034px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">Pilar Fogliati y Alessandro Gassmann en \u201cHasta que la noche nos separe\u201d.<\/p>\n<\/div>\n<p class=\"p3\"><strong><span class=\"s2\">Eligi\u00f3 un socio con un trabajo &#8220;normal&#8221;, no uno del negocio.<br \/><\/span><\/strong>Sabia elecci\u00f3n.  El m\u00edo es un trabajo precario por definici\u00f3n, hay que aceptarlo y es mejor saberlo de antemano, para no hacerse ilusiones.<\/p>\n<p class=\"p3\"><strong><span class=\"s2\">Tambi\u00e9n porque hay muchas maneras de llegar a fin de mes.  Tambi\u00e9n fue entrenadora del Romanesco.  \u00bfEra realmente necesario?  El cine italiano ya habla demasiado romano.<br \/><\/span><\/strong>(<i>sonrisas<\/i>) Pero hay muchas maneras de hablar romano&#8230; (y Pilar Fogliati, como dec\u00edamos, es la reina de los matices, el punto de inflexi\u00f3n para ella lleg\u00f3 con un v\u00eddeo que se hizo viral en el que interpretaba a cuatro mujeres con cuatro acentos diferentes de tantas zonas de la capital, <i>ed<\/i>).<\/p>\n<p class=\"p3\"><strong><span class=\"s2\">Proviene de una familia numerosa, es la tercera de cuatro y los dos primeros tienen, como ella dir\u00eda, &#8220;trabajos normales&#8221;.  \u00bfEs tambi\u00e9n por eso que sus padres le permitieron hacerlo?  Uno de cada cuatro artistas est\u00e1 en casa.<br \/><\/span><\/strong>No puedo quejarme de mis padres.  Mi hermano y mi hermana mayores tienen mucho \u00e9xito y tienen trabajos seguros.  Mi madre s\u00f3lo me dijo una cosa: \u201cSi quieres ser actriz tienes que hacerlo en serio.  As\u00ed, ya sea el Silvio D&#8217;Amico en Roma o, en Gran Breta\u00f1a, la Lamda (Academia de M\u00fasica y Arte Dram\u00e1tico de Londres).  Haz estas dos audiciones, si no pasas no vale la pena&#8221;.<\/p>\n<h2>La s\u00f3lida familia de Pilar Fogliati<\/h2>\n<p class=\"p3\"><strong><span class=\"s2\">Y se uni\u00f3 a Silvio D&#8217;Amico.  As\u00ed todos se van a casa en paz.<br \/><\/span><\/strong>Mi madre nos presion\u00f3 cuando ten\u00edamos 18 a\u00f1os: \u201cTienes que ir a la universidad, tienes que estudiar\u201d, pero funcion\u00f3.  Cuando sales del instituto a\u00fan es muy pronto para entender qu\u00e9 hacer con tu vida.  Si no hay alguien que te mantenga encaminado, est\u00e1s en problemas.  Mi hermana menor tiene 17 a\u00f1os y le digo: \u201cAn\u00edmate, ya veremos.  Tambi\u00e9n puedes cambiar de opini\u00f3n en la vida&#8221;.<\/p>\n<p class=\"p3\"><strong><span class=\"s2\">Una madre ilustrada y una familia s\u00f3lida, un modelo de \u00e9xito.<br \/><\/span><\/strong>En mi familia, como en todas, pas\u00f3 <i>de todo y mas<\/i>, pero mis padres todav\u00eda est\u00e1n juntos y se aman.  Sin duda son un buen ejemplo, un matrimonio que contin\u00faa, no se rinde.<\/p>\n<div id=\"attachment_2371676\" data-thumbnail_id=\"2371676\" class=\"wp-caption aligncenter\" style=\"width:1034px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">Pilar Fogliati en \u201cHasta que la noche nos separe\u201d.<\/p>\n<\/div>\n<p class=\"p3\"><strong><span class=\"s2\">\u00bfDe d\u00f3nde viene este ex\u00f3tico nombre? \u00bfTiene algo que ver Hemingway?  (Pilar es una de las protagonistas de <i>Por qui\u00e9n doblan las campanas<\/i>Pilar era el barco m\u00e1s querido del escritor americano).<\/span><\/strong><\/p>\n<p class=\"p2\">No proviene de las lecturas.  Me llamaron as\u00ed en honor a mi abuela que naci\u00f3 en Buenos Aires.  Muy bella, era modelo, cuando los maniqu\u00edes eran pocos.  Vino a Italia y conoci\u00f3 a mi abuelo.  En su honor me llamaron Mar\u00eda del Pilar, que no es un nombre com\u00fan, pero hace referencia a una santa, la Virgen del Pilastro, que es muy venerada.  El nombre de mi padre es Gonzalo, solo nosotros dos tenemos nombres hispanos en la familia.  Luego en el pasaporte escribieron s\u00f3lo Mar\u00eda Pilar porque quiz\u00e1s el &#8220;del&#8221; les son\u00f3 raro.  Cada vez que me presento a alguien que no me conoce me pasa algo gracioso: &#8220;Hola, soy Pilar&#8221;, &#8220;<i>S\u00ed, pero dime tu nombre, no tu apellido.<\/i>\u201d.<\/p>\n<h2>El obst\u00e1culo del segundo trabajo.<\/h2>\n<p class=\"p3\"><strong><span class=\"s2\">\u00bfTuviste alg\u00fan problema con la burocracia?<br \/><\/span><\/strong>(<i>risas<\/i>) Me tom\u00f3 un tiempo obtener mi licencia.  Despu\u00e9s de tres intentos, finalmente llega la nota rosa.  Voy a recogerlo y leo: \u201cMaria Pilar Fogliati nacida en Alejandr\u00eda, Egipto\u201d.  Yo digo: &#8220;Pero lo siento, nac\u00ed en Alessandria en Piamonte, y adem\u00e1s Pilar ni siquiera es un nombre \u00e1rabe&#8221;.  Y ella: \u201c\u00bfY yo qu\u00e9 s\u00e9?  Le\u00ed a Pilar y dije: esto es extranjero\u2026\u201d.  Luego estamos llenos de nombres extranjeros, Michael y Kevin, Chlo\u00e9&#8230;<\/p>\n<p class=\"p3\"><strong><span class=\"s2\">Si ahora fuera a la escuela de manejo, seguramente la reconocer\u00edan.<br \/><\/span><\/strong>Cuando sucede, para alguien como yo que reci\u00e9n comienza, es como si le dijeran: &#8220;\u00a1Bien hecho, sigue as\u00ed!&#8221;.<\/p>\n<p class=\"p3\"><strong><span class=\"s2\">Mira, ya est\u00e1s en la fase descendente, alcanzaste la condici\u00f3n de autor al hacer una pel\u00edcula escrita, dirigida y protagonizada por ti: es tu pel\u00edcula, independiente de la mirada de los dem\u00e1s.<br \/><\/span><\/strong>(<i>risas<\/i>) Estoy en el principio porque he vivido muchas primicias, porque en Italia o se hacen pel\u00edculas pop o art\u00edsticas, o se hace drama o comedia social, y he vivido de todo, y mi sue\u00f1o era hacer una comedia pura. .  Luego est\u00e1 el obst\u00e1culo del segundo trabajo.  Especialmente si el primero fue apreciado.  Pero esto tambi\u00e9n me permiti\u00f3 comprender mi lugar.  S\u00e9 cu\u00e1l fue el esp\u00edritu que me llev\u00f3 a hacer esa pel\u00edcula: una temeridad afortunada.  Tengo que volver a encontrarlo y para ello tengo que tener en mis manos algo que haga latir mi coraz\u00f3n.  Sin c\u00e1lculos, como: (<i>tiene un acento vagamente milan\u00e9s<\/i>) \u201cAhora tengo que hacer la segunda, algo inteligente\u201d.  Son pensamientos que contaminan.  Siento que la comedia me hace sentir bien, pero tambi\u00e9n estoy usando la experiencia adquirida all\u00ed para experimentar con otras cosas.<\/p>\n<div id=\"attachment_2371682\" data-thumbnail_id=\"2371682\" class=\"wp-caption aligncenter\" style=\"width:1034px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">La actriz y directora italiana Pilar Fogliati durante el photocall de presentaci\u00f3n de la pel\u00edcula &#8220;Romeo es Julieta&#8221;.  Roma (Italia), 13 de febrero de 2024 (Foto de Marilla Sicilia\/Archivio Marilla Sicilia\/Mondadori Portfolio v\u00eda Getty Images)<\/p>\n<\/div>\n<p class=\"p3\"><strong><span class=\"s2\">Es bueno experimentar, tal vez incluso dar algunos cabezazos.<br \/><\/span><\/strong>\u00a1Muchos cabezazos!  Aunque no los puedas ver, son dolores de cabeza internos, tengo chichones por dentro.<\/p>\n<p class=\"p3\"><strong><span class=\"s2\">Y, gracias a los cabezazos, \u00bfqu\u00e9 mirada tiene sobre sus compa\u00f1eros que representa tan bien?<br \/><\/span><\/strong><span class=\"s1\">Lo que observo y escucho es que en mi generaci\u00f3n ha aumentado el conocimiento y la curiosidad que tenemos sobre nosotros mismos, nuestro inconsciente, nuestro bienestar.  Cada vez estamos menos dispuestos a sacrificar algo que nos concierne en nombre de un proyecto com\u00fan.  Realmente debe valer la pena, porque hay m\u00e1s opciones: puedo casarme o no, puedo estar en pareja o no, puedo sustentarme, puedo trabajar, comprar una casa.  Es una libertad nueva, pero como todas las libertades tambi\u00e9n te pone en una cierta crisis, te lleva a hacerte preguntas que no te hac\u00edas antes.  \u00bfY entonces que?  \u00a1A terapia! <\/span><\/p>\n<p class=\"p3\"><strong><span class=\"s2\">\u00bfElla tambi\u00e9n fue all\u00ed?<br \/><\/span><\/strong>S\u00ed, y era necesario.  Necesitaba conocerme un poco mejor, hab\u00eda aspectos de mi car\u00e1cter que necesitaba suavizar, quer\u00eda ser una mejor persona.  Y continuar.  El autoconocimiento es lo que m\u00e1s te ayuda a avanzar.<\/p>\n<p class=\"p3\"><strong><span class=\"s2\">Nora Ephron en <i>insomnio en el amor<\/i> (era 1993) hizo decir a uno de los personajes: \u00abLo que consideramos destino son s\u00f3lo dos neurosis conscientes de ser una pareja perfecta\u00bb.<br \/><\/span><\/strong>\u00a1Bien!  Lo importante es que las neurosis encajen bien. <i>Vamos<\/i>.<\/p>\n<p class=\"all-rights-reserved\">iO Donna \u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iodonna.it\/spettacoli\/cinema\/2024\/07\/20\/pilar-fogliati-se-la-vita-e-una-commedia-io-mi-abbandono-a-una-fortunata-incoscienza\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00abPilar Fogliati, me hiciste re\u00edr mucho\u00bb.La actriz romana, especializada en matices (del dialecto romano -y son infinitos- pero<\/p>\n","protected":false},"author":1,"featured_media":1284246,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[5143,440,15999,5194,4337,1534,1806,268,1737,11612,31147,23580,9891,22125,13941,39323,5093,1327,158,148],"class_list":["post-1284245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-actriz","tag-como","tag-decisiones","tag-encuentra","tag-esa","tag-fase","tag-grandes","tag-hay","tag-hijo","tag-hipoteca","tag-interpreto","tag-master","tag-night","tag-part","tag-personaje","tag-romana","tag-tomar","tag-ultimo","tag-una","tag-vida"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1284245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1284245"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1284245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1284246"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1284245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1284245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1284245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}