{"id":1284130,"date":"2024-07-20T05:23:10","date_gmt":"2024-07-20T05:23:10","guid":{"rendered":"https:\/\/teknomers.com\/es\/citroen-embiste-un-tranvia-una-persona-resulta-herida\/"},"modified":"2024-07-20T05:23:15","modified_gmt":"2024-07-20T05:23:15","slug":"citroen-embiste-un-tranvia-una-persona-resulta-herida","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/citroen-embiste-un-tranvia-una-persona-resulta-herida\/","title":{"rendered":"Citro\u00ebn embiste un tranv\u00eda: una persona resulta herida"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"post-4860200\">\n<figure class=\"position-relative mb-3\"><figcaption class=\"small fw-bold mt-1\">\n<p>         La causa del accidente no est\u00e1 clara por el momento.                      <span class=\"fw-normal\">Foto de : spreepicture<\/span><br \/>\n            <\/figcaption><\/figure>\n<div class=\"entry-content col-auto col-lg-8 mx-auto\" style=\"min-width: 70%\">\n<p class=\"fw-bold\">\n<p>    Por Dirk Bottger\n<\/p>\n<div class=\"w-auto d-flex flex-column-reverse d-lg-block w-mrec\">\n<p class=\"fw-bold\">El viernes por la noche un coche choc\u00f3 contra un tranv\u00eda en Wei\u00dfensee, Berl\u00edn.<\/p>\n<\/div>\n<p>Seg\u00fan informaci\u00f3n de BZ, alrededor de las 23.00 horas el conductor de un Citro\u00ebn embisti\u00f3 un tranv\u00eda en la calle Berliner Allee.  Seg\u00fan las primeras informaciones, una persona result\u00f3 levemente herida. <\/p>\n<figure class=\"position-relative wp-block-image\">\n            <img decoding=\"async\" width=\"992\" height=\"558\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721452990_804_Citroen-embiste-un-tranvia-una-persona-resulta-herida.jpg\" alt=\"La causa del accidente no est\u00e1 clara por el momento.\" loading=\"lazy\"  class=\"img-4860203 img-fluid w-100 size-xl d-inline-block bg-fallback\"\/><figcaption class=\"small fw-bold mt-1\">\n<p>         Erlin-Pankow, en el distrito de Wei\u00dfensee, sufri\u00f3 un grave accidente.  Cuando el conductor de un Citro\u00ebn embisti\u00f3 a un tranv\u00eda.  Seg\u00fan las primeras informaciones, una persona result\u00f3 herida, aunque no de gravedad.                       <span class=\"fw-normal\">Foto de : spreepicture<\/span><br \/>\n            <\/figcaption><\/figure>\n<p><strong>Hubo da\u00f1os desconocidos en el coche y el tranv\u00eda.  La l\u00ednea de tranv\u00eda estuvo interrumpida durante aproximadamente una hora.  Los bomberos recuperaron el coche y atendieron a los heridos. <\/strong><\/p>\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-b-z-die-stimme-berlins wp-block-embed-b-z-die-stimme-berlins\"\/>\n<p><em>La polic\u00eda ahora est\u00e1 investigando si la conductora ignor\u00f3 el derecho de v\u00eda y si deber\u00eda haber girado all\u00ed.<\/em><\/p>\n<\/p><\/div>\n<section data-type=\"tag-links\" class=\"d-flex align-items-center gap-2 mt-4 mb-2\">\n            <span class=\"fw-bold text-nowrap\">Asignaturas: <\/span><br \/>\n            <span class=\"d-flex gap-2 overflow-scroll hide-scrollbar\" data-actions=\"scroll-horizontal\"><\/p>\n<p>                            Accidente de tranv\u00eda<br \/>\n                        <\/span><br \/>\n        <\/section>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.bz-berlin.de\/polizei\/citroen-rammt-tram-person-verletzt\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-27<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La causa del accidente no est\u00e1 clara por el momento. Foto de : spreepicture Por Dirk Bottger El<\/p>\n","protected":false},"author":1,"featured_media":1284131,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[76002,24556,4706,5389,8248,10831,158],"class_list":["post-1284130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-citroen","tag-embiste","tag-herida","tag-persona","tag-resulta","tag-tranvia","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1284130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1284130"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1284130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1284131"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1284130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1284130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1284130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}