{"id":1283136,"date":"2024-07-19T12:06:08","date_gmt":"2024-07-19T12:06:08","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-bvb-amplia-su-contrato-con-el-portero\/"},"modified":"2024-07-19T12:06:13","modified_gmt":"2024-07-19T12:06:13","slug":"el-bvb-amplia-su-contrato-con-el-portero","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-bvb-amplia-su-contrato-con-el-portero\/","title":{"rendered":"El BVB ampl\u00eda su contrato con el portero"},"content":{"rendered":"\n<div>\n<p>El club de f\u00fatbol de la Bundesliga Borussia Dortmund ha ampliado el contrato de Alexander Meyer.  El portero seguir\u00e1 siendo el n\u00famero dos del BVB en el futuro.<\/p>\n<p>El nuevo documento de trabajo de Meyer en el Borussia Dortmund tiene fecha hasta 2026. <\/p>\n<p>&#8220;Estoy muy contento de que hayamos podido renovar a Alex un a\u00f1o m\u00e1s desde el principio. Es un excelente portero, un jugador de equipo absoluto y un profesional ejemplar que lo da todo en cada entrenamiento, siempre est\u00e1 listo y muestra su rendimiento cuando lo necesitamos&#8221;, afirm\u00f3 el director deportivo Sebastian Kehl.<\/p>\n<p>El exprofesional a\u00f1adi\u00f3: &#8220;Con su car\u00e1cter positivo, tambi\u00e9n juega un papel importante en el vestuario y rezuma liderazgo, tranquilidad y seguridad. Para nosotros, Alex es el mejor segundo portero de la Bundesliga&#8221;.<\/p>\n<p><interaction id=\"66851b6361e583a56e85d242\" class=\"apester-container hs-socialmedia-container hs-socialmedia-container--type-apester hs-socialmedia-container--orientation-center hs-socialmedia-container--width-max\"\/><\/p>\n<p>Meyer pas\u00f3 de Jahn Regensburg al BVB en 2022.  El veterano act\u00faa como suplente de Gregor Kobel en Dortmund.  Meyer ha jugado hasta ahora un total de 21 partidos competitivos con Westfalia.  La temporada pasada disput\u00f3 ocho partidos de la Bundesliga y uno de la Liga de Campeones.<\/p>\n<p>&#8220;Me siento muy c\u00f3modo en Dortmund, siento un gran aprecio por parte de los responsables, el cuerpo t\u00e9cnico, mis compa\u00f1eros, los empleados y nuestros aficionados. Para m\u00ed todav\u00eda no es un hecho que pueda vestir la camiseta del BVB&#8221;, coment\u00f3 el 33 -a\u00f1os de antig\u00fcedad su extensi\u00f3n.<\/p>\n<h2>Meyer sue\u00f1a con el t\u00edtulo con el BVB<\/h2>\n<p>Su gran objetivo es &#8220;poder celebrar un t\u00edtulo con la familia del BVB al final de la temporada en Borsigplatz. Para eso estoy trabajando con mis compa\u00f1eros&#8221;, dijo Meyer.<\/p>\n<p>\u201cSky\u201d ya hab\u00eda informado el jueves sobre la pr\u00f3xima pr\u00f3rroga.  Por eso Meyer goza de \u201cuna gran reputaci\u00f3n\u201d en el Borussia Dortmund.<\/p>\n<p>El portero trabaj\u00f3 anteriormente durante su carrera para el Hamburger SV II, TSV Havelse, Energie Cottbus, VfB Stuttgart y Jahn Regensburg.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne6865649\/bvb-verlaengert-mit-bestem-zweiten-torhueter-der-bundesliga\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El club de f\u00fatbol de la Bundesliga Borussia Dortmund ha ampliado el contrato de Alexander Meyer. El portero<\/p>\n","protected":false},"author":1,"featured_media":1283137,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[60396,6499,3480,81,83,99,404,203901,6365,28760,1709],"class_list":["post-1283136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-alejandro-meyer","tag-amplia","tag-borussia-dortmund","tag-bundesliga","tag-bvb","tag-con","tag-contrato","tag-deportes-en-general","tag-futbol-americano","tag-futbol-superior","tag-portero"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1283136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1283136"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1283136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1283137"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1283136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1283136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1283136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}