{"id":1282758,"date":"2024-07-19T05:45:11","date_gmt":"2024-07-19T05:45:11","guid":{"rendered":"https:\/\/teknomers.com\/es\/preocupaciones-por-la-seguridad-vial-en-las-nuevas-construcciones-de-nieuwe-veste-es-un-punto-de-atencion\/"},"modified":"2024-07-19T05:45:17","modified_gmt":"2024-07-19T05:45:17","slug":"preocupaciones-por-la-seguridad-vial-en-las-nuevas-construcciones-de-nieuwe-veste-es-un-punto-de-atencion","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/preocupaciones-por-la-seguridad-vial-en-las-nuevas-construcciones-de-nieuwe-veste-es-un-punto-de-atencion\/","title":{"rendered":"Preocupaciones por la seguridad vial en las nuevas construcciones De Nieuwe Veste: &#8216;Es un punto de atenci\u00f3n&#8217;"},"content":{"rendered":"\n<div __component=\"api.api-text\" type=\"text\" id=\"733e692f-22c4-49fc-a59b-e6748beefd03\" data-v-37f0a0af=\"\" data-v-26349d05=\"\">\n<p>Sulimma quiere que se tomen las medidas de seguridad antes de que se construya la nueva escuela.  &#8220;No s\u00f3lo tenemos una responsabilidad en lo que respecta a la seguridad de los estudiantes, sino que tambi\u00e9n tenemos una responsabilidad social con nuestros conciudadanos. No deber\u00eda ser que los residentes pronto se vean molestados por grandes grupos de estudiantes en bicicleta que pasan por el centro&#8221;.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"12c10d65-f555-4609-b40f-b7f1b8f3b365\" data-v-37f0a0af=\"\" data-v-26349d05=\"\">\n<p>Despu\u00e9s de las vacaciones de verano, el consejo municipal debatir\u00e1 el tema &#8220;Seguridad vial en la nueva escuela&#8221;.  Sulimma: &#8220;Espero que nosotros, como escuela, podamos resolver esto junto con el municipio, porque hasta ahora hemos podido trabajar bien juntos durante todo el proceso de nueva construcci\u00f3n&#8221;.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"7ede2c3b-e622-46d3-855c-5722db1e03e6\" data-v-37f0a0af=\"\" data-v-26349d05=\"\">\n<p>De Nieuwe Veste no abrir\u00e1 sus puertas en el nuevo emplazamiento hasta el inicio del curso escolar 2026-2027, aunque esto todav\u00eda depende, entre otras cosas, de la compra de terrenos por parte del municipio.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"d2efe111-ee64-445f-a946-af44a308e4ae\" data-v-37f0a0af=\"\" data-v-26349d05=\"\">\n<p>\u201cEn general, el proyecto se ha ralentizado bastante en los \u00faltimos a\u00f1os\u201d, afirma Sulimma.  Esto conlleva costes, como por ejemplo elevados costes de calefacci\u00f3n.  &#8220;En un edificio para 1.900 estudiantes, mientras tienes alrededor de 1.100, se quema bastante. Adem\u00e1s del hecho de que siempre tuvimos que elegir qu\u00e9 mantenimiento deb\u00edamos hacer y qu\u00e9 mantenimiento no deb\u00edamos hacer. Eso es dif\u00edcil si no No s\u00e9 exactamente d\u00f3nde est\u00e1s parado\u201d.  La escuela espera que el municipio le compense los costes adicionales derivados del retraso.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"cf64f6a9-4cd1-44d5-a937-3b5abe0cb89d\" data-v-37f0a0af=\"\" data-v-26349d05=\"\">\n<p>Sulimma deja ahora De Nieuwe Veste para convertirse en directora del Staring College, con escuelas en Lochem y Borculo, en Gelderland.  &#8220;All\u00ed me esperan retos completamente diferentes. En cualquier caso, no hay ninguna nueva construcci\u00f3n, ya que el edificio de la escuela en Borculo s\u00f3lo tiene seis semanas&#8221;.  A partir del 1 de octubre, Rinke van de Hoek asumir\u00e1 el cargo de nueva directora de locaciones de De Nieuwe Veste.<\/p>\n<p> <!----><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rtvdrenthe.nl\/nieuws\/16659785\/zorgen-over-verkeersveiligheid-bij-nieuwbouw-de-nieuwe-veste-is-aandachtspunt\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-41<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sulimma quiere que se tomen las medidas de seguridad antes de que se construya la nueva escuela. &#8220;No<\/p>\n","protected":false},"author":1,"featured_media":1282759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[812,215768,10695,16484,246,10692,31156,2498,231,4913,171,42,61867,47685],"class_list":["post-1282758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-atencion","tag-bosque-nuevo","tag-coevorden","tag-construcciones","tag-las","tag-municipio-de-coevorden","tag-nieuwe","tag-nuevas","tag-por","tag-preocupaciones","tag-punto","tag-seguridad","tag-veste","tag-vial"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1282758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1282758"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1282758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1282759"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1282758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1282758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1282758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}