{"id":1282729,"date":"2024-07-19T05:13:15","date_gmt":"2024-07-19T05:13:15","guid":{"rendered":"https:\/\/teknomers.com\/es\/atalanta-3-0-al-primavera-koopmeiners-en-el-campo-lesion-de-godfrey\/"},"modified":"2024-07-19T05:13:23","modified_gmt":"2024-07-19T05:13:23","slug":"atalanta-3-0-al-primavera-koopmeiners-en-el-campo-lesion-de-godfrey","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/atalanta-3-0-al-primavera-koopmeiners-en-el-campo-lesion-de-godfrey\/","title":{"rendered":"Atalanta, 3-0 al Primavera.  Koopmeiners en el campo, lesi\u00f3n de Godfrey"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><h2 class=\"is-subtitle\">El ingl\u00e9s pide sustituci\u00f3n a la media hora por una distensi\u00f3n muscular.  Doblete de Diao y gol de Michieletto, hermano en el arte<\/h2>\n<\/p>\n<div class=\"bck-author-signature gz-hide-in-editor\">\n<div class=\"author-signature__content\">\n<div class=\"author-block\">\n<p>\n                                                    <span class=\"author-name\">Giorgio Dusi<\/span>\n                            <\/p>\n<p>\n                <time class=\"article-date xlk\" content=\"2024-07-18T19:25:23+02:00\" data-time=\"2024-07-18\"><\/p>\n<p>                    18 de julio &#8211; 19.25 h  <span class=\"from-location\">&#8211; CLUSONE (B\u00c9RGAMO)<\/span><br \/>\n                <\/time>\n            <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"content \" id=\"m38324-38323-38325\">\n<p class=\"paragraph\" spellcheck=\"true\">La primera derrota de la temporada del Atalanta ante su afici\u00f3n, ante el equipo Primavera, es agridulce.  Porque si por un lado es el primer abrazo del p\u00fablico, por otro tambi\u00e9n est\u00e1 la primera lesi\u00f3n desde el inicio de la preparaci\u00f3n el 10 de julio.  Y para uno de los nuevos fichajes: Ben Godfrey.<\/p>\n<\/div>\n<div class=\"content content-paragraph \" id=\"m38350-38349-38351\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m38431-38430-38432\">la parada<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Titular en el once de Gasperini, el ex jugador del Everton levant\u00f3 la bandera blanca despu\u00e9s de aproximadamente media hora de juego: se toc\u00f3 la zona de la ingle izquierda y luego hizo una se\u00f1al al banquillo para que fuera sustituido.  Tras salir acompa\u00f1ado por el personal m\u00e9dico, los primeros indicios hablan de una distensi\u00f3n muscular en el muslo izquierdo: las pruebas de las pr\u00f3ximas horas permitir\u00e1n un diagn\u00f3stico m\u00e1s claro y completo.  La promoci\u00f3n de 1998 se hab\u00eda unido al grupo desde el primer d\u00eda de retiro.<\/p>\n<\/div>\n<p><!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml]@ --><!--@ESI generic END--><\/p>\n<div class=\"content content-paragraph \" id=\"m38360-38359-38361\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m38437-38436-38438\">koop en el campo<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Bajo la mirada de la familia Percassi, que se encuentra en su casa de Clusone, Teun Koopmeiners, en el centro de los rumores de traspaso y que hasta ayer s\u00f3lo hab\u00eda realizado trabajos individuales, tambi\u00e9n encontr\u00f3 su espacio en el once inicial.  A\u00fan no se hab\u00eda unido al grupo.  Jug\u00f3 en el centro del campo junto a Pasalic (que regres\u00f3 hace dos d\u00edas y ya est\u00e1 en forma), recibi\u00f3 los c\u00e1nticos de alrededor de mil presentes en la Citt\u00e0 di Clusone y tambi\u00e9n peg\u00f3 al poste en la primera parte.<\/p>\n<\/div>\n<div class=\"content content-paragraph \" id=\"m38365-38364-38366\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m38443-38442-38444\">j\u00f3venes a la vista<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">El partido abri\u00f3 el marcador en la segunda parte con un gol de Diao, nacido en 2005, una joya de la selecci\u00f3n Sub 23 que est\u00e1 trabajando con los grandes.  Asistencia del nuevo fichaje Sulemana, oficializada ayer.  En la segunda mitad, Gasperini tambi\u00e9n jug\u00f3 con el primer equipo a Michieletto y Steffanoni de la categor\u00eda 2008 (campeones de Italia con la categor\u00eda Sub 16) y Bonanomi de la categor\u00eda 2006.  El propio Andrea Michieletto, hermano del internacional italiano de voleibol Alessandro, meti\u00f3 el bal\u00f3n en la porter\u00eda para poner el 2-0 tras una asistencia de Palestra de 2005, antes de que Diao anotara el triplete.<\/p>\n<\/div>\n<div class=\"content content-paragraph \" id=\"m38370-38369-38371\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m38449-38448-38450\">as\u00ed en la cancha<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\"><b>Atalanta-Atalanta Primavera 3-0<\/b><\/p>\n<\/div>\n<div class=\"content \" id=\"m38375-38374-38376\">\n<p class=\"paragraph\" spellcheck=\"true\"><b>Marcadores:<\/b> 52&#8242; Diao, 85&#8242; Michieletto, 93&#8242; Diao  <b>Atalanta 1.\u00aa parte (3-4-1-2):<\/b> Musso;  Godfrey (28&#8242; Bonfanti), Hien, Kolasinac;  Zappacosta, Pasalic, Koopmeiners, Ruggeri;  Joven;  El Bilal, Lookman.<\/p>\n<\/div>\n<div class=\"content \" id=\"m38380-38379-38381\">\n<p class=\"paragraph\" spellcheck=\"true\"><b>Atalanta 2.\u00ba tiempo (3-4-1-2):<\/b> Carnesecchi;  Hateboer, Djimsiti, Toloi;  Palestra, Sulemana, Steffanoni, Bakker;  Bonanomi;  Michieletto, Diao.<\/p>\n<\/div>\n<div class=\"container-last-content-desktop\">\n<div class=\"content not-selectable-js fxr-left-center\">\n<div class=\"bck-copyright\">\n<p class=\"is-copyright\">\u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/div><\/div>\n<p>                                        <!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/taboola\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/taboola\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/taboola\/default.shtml]@ --><!--@ESI generic END--><br \/>\n                                        <!-- include virtual=\"$SERVICE_PATH\/taboola\/default.shtml\" --><\/p>\n<p>                                        <!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&EXT_COMMENTS=xalok&path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&EXT_COMMENTS=xalok&path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml]@ --><!--@ESI generic END--><br \/>\n                                        <!-- include virtual=\"$SSI_PATH\/components\/comments\/list\/default.shtml\" --><\/p><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/Calcio\/Serie-A\/Atalanta\/18-07-2024\/atalanta-3-0-alla-primavera-in-amichevole-in-campo-koopmeiners-infortunio-per-godfrey.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ingl\u00e9s pide sustituci\u00f3n a la media hora por una distensi\u00f3n muscular. Doblete de Diao y gol de<\/p>\n","protected":false},"author":1,"featured_media":1282730,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[3616,3525,239566,11513,1990,5159],"class_list":["post-1282729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-atalanta","tag-campo","tag-godfrey","tag-koopmeiners","tag-lesion","tag-primavera"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1282729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1282729"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1282729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1282730"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1282729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1282729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1282729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}