{"id":1282626,"date":"2024-07-19T02:44:08","date_gmt":"2024-07-19T02:44:08","guid":{"rendered":"https:\/\/teknomers.com\/es\/muevete-a-la-villa-olimpica-gimnasio-guarderia-y-dispensador-de-preservativos\/"},"modified":"2024-07-19T02:44:12","modified_gmt":"2024-07-19T02:44:12","slug":"muevete-a-la-villa-olimpica-gimnasio-guarderia-y-dispensador-de-preservativos","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/muevete-a-la-villa-olimpica-gimnasio-guarderia-y-dispensador-de-preservativos\/","title":{"rendered":"Mu\u00e9vete a la Villa Ol\u00edmpica: gimnasio, guarder\u00eda y dispensador de preservativos"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"seitenkopf\">\n<div class=\"seitenkopf__data columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"seitenkopf__title\">\n<p class=\"metatextline\">A partir de: 18 de julio de 2024 14:23<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n        <strong>Est\u00e1 instalado en la Villa Ol\u00edmpica de Par\u00eds.  Los primeros de 9.000 atletas se han instalado en los cuartos del norte de Par\u00eds.  Los jugadores de hockey inauguran su casa en Alemania.<\/strong>\n    <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Bajo un cielo azul y una agradable temperatura de 24 grados, los primeros atletas llegaron el jueves (18 de julio de 2024) a la Villa Ol\u00edmpica, se instalaron en sus habitaciones y disfrutaron de un ambiente tan especial.  &#8220;Es un momento especial cuando la villa realmente cobra vida&#8221;, afirm\u00f3 Andr\u00e9-Pierre Goubert, del equipo ol\u00edmpico franc\u00e9s.<\/p>\n<h2 id=\"Deutsche-Hockeyspielerinnen-kommen-am-Freitag\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Alem\u00e1n <span class=\"hyphenate\">jugadores de hockey <\/span>ven el viernes<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Atletas de Tailandia, Australia y Colombia fueron los primeros en entrar en el terreno de 52 hect\u00e1reas en el norte de Par\u00eds, donde se espera que los jugadores de hockey sean los primeros participantes ol\u00edmpicos alemanes el viernes (19 de julio de 2024).  En los pr\u00f3ximos d\u00edas y semanas, la aldea con sus 82 edificios de nueva construcci\u00f3n acoger\u00e1 a casi 14.500 personas de m\u00e1s de 200 pa\u00edses, incluidos 9.000 atletas.<\/p>\n<h2 id=\"Riesen-Mensa-und-erstmals-Kinderkrippe\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Cafeter\u00eda gigante y, por primera vez, \u201ccentro infantil\u201d<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Los atletas pueden esperar un distrito completamente nuevo, el concepto se basa en el respeto al clima, pero tambi\u00e9n tiene sus inconvenientes.  Los elegantes balcones del pueblo, que se extiende por los distritos de Saint-Denis, Saint-Ouen y la isla de Saint-Denis, est\u00e1n decorados con los colores nacionales y las pesas se preparan en el gimnasio de 170 metros cuadrados.  Por primera vez el pueblo cuenta con una zona de juegos para ni\u00f1os, ya que muchos deportistas traer\u00e1n a sus hijos a Par\u00eds.  La cafeter\u00eda con 3.300 asientos y seis comedores diferentes que ofrece platos de todo el mundo est\u00e1 lista para funcionar.  Y los dispensadores de condones tambi\u00e9n cuentan con un generoso surtido de alrededor de 220.000 ejemplares.<\/p>\n<h2 id=\"Wird-das-Dorf-nach-den-Paralympics-zum-Vorzeigeprojekt\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">\u00bfSe convertir\u00e1 el pueblo en ciudad despu\u00e9s de los Juegos Paral\u00edmpicos? <span class=\"hyphenate\">\u00bfAnexo?<\/span><\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>El Estado franc\u00e9s aport\u00f3 646 millones de euros de dinero p\u00fablico y el resto provino de las mayores empresas inmobiliarias de Francia.  Par\u00eds espera un impulso en t\u00e9rminos de desarrollo urbano y sociedad.  Despu\u00e9s de los Juegos de Verano y los Juegos Paral\u00edmpicos, la zona deber\u00eda convertirse en un proyecto escaparate.  Seg\u00fan los planes, un tercio de los 2.800 apartamentos se vender\u00e1 a propietarios privados, un tercio se utilizar\u00e1 como vivienda social y el resto se alquilar\u00e1, incluso a estudiantes.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Saint-Denis est\u00e1 situado en el departamento franc\u00e9s m\u00e1s pobre y conocido por la delincuencia, Seine-Saint-Denis.  El lugar recibi\u00f3 una nueva capa de pintura con motivo de los Juegos Ol\u00edmpicos.  Grandes inversiones fluyeron hacia Saint-Denis, incluido un gran nuevo centro de nataci\u00f3n.<\/p>\n<h2 id=\"Kuehlsystem-statt-Klimaanlagen---Paris-musste-nachruesten\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Sistema de refrigeraci\u00f3n en lugar de aire acondicionado: Par\u00eds tuvo que modernizarse<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Por el bien del medio ambiente, la villa de los deportistas fue dise\u00f1ada con camas de cart\u00f3n y sin aire acondicionado.  Pero el sistema de enfriamiento geot\u00e9rmico, que utiliza agua fr\u00eda de las profundidades del suelo, parece estar llegando a sus l\u00edmites dadas las necesidades de algunos atletas.  Ante la preocupaci\u00f3n de algunas selecciones nacionales por el calor parisino, los organizadores equiparon los apartamentos con 2.500 aparatos de aire acondicionado port\u00e1tiles improvisados.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sportschau.de\/olympia\/einzug-ins-olympische-dorf-gym-kinderkrippe-und-kondomspender,olympia-eroeffnung-olympisches-dorf-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de: 18 de julio de 2024 14:23 Est\u00e1 instalado en la Villa Ol\u00edmpica de Par\u00eds. Los<\/p>\n","protected":false},"author":1,"featured_media":1282627,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[23630,5310,23,84116,15306,70,5123,30239,11582],"class_list":["post-1282626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-dispensador","tag-gimnasio","tag-guarderia","tag-juegos-olimpicos-2024","tag-muevete","tag-olimpia","tag-olimpica","tag-preservativos","tag-villa"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1282626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1282626"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1282626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1282627"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1282626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1282626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1282626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}