{"id":1277707,"date":"2024-07-15T15:59:13","date_gmt":"2024-07-15T15:59:13","guid":{"rendered":"https:\/\/teknomers.com\/es\/trump-el-intento-de-asesinato-y-el-poder-de-las-imagenes\/"},"modified":"2024-07-15T15:59:18","modified_gmt":"2024-07-15T15:59:18","slug":"trump-el-intento-de-asesinato-y-el-poder-de-las-imagenes","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/trump-el-intento-de-asesinato-y-el-poder-de-las-imagenes\/","title":{"rendered":"Trump, el intento de asesinato y el poder de las im\u00e1genes"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div data-testid=\"text-module\">\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"byi3ftt\">\n<div class=\"r1f6k8yy\" style=\"--r1f6k8yy-0:384\/127\"><picture class=\"slrzex8\" style=\"--slrzex8-0:var(--surface-subtle)\"><source  \/><\/picture><\/div>\n<\/div>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>Buenas noches, <\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">La mayor\u00eda de la gente se despert\u00f3 ayer con esta noticia: le dispararon a Donald Trump.  El shock fue grande y contin\u00faa hasta el d\u00eda de hoy.  Desde entonces, una imagen ha dado la vuelta al mundo.  Un Trump sangrante levantando el pu\u00f1o segundos despu\u00e9s del intento de asesinato y gritando &#8220;\u00a1Pelea! \u00a1Pelea! \u00a1Pelea!&#8221;.  llamadas.  Incluso en el momento en que una bala le alcanza la oreja, sabe c\u00f3mo ponerse en el centro de atenci\u00f3n.<\/div>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Donald Trump levanta el pu\u00f1o frente a una bandera de Estados Unidos\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\"> <\/span><span class=\"m211382\">15 de julio de 2024 |  2:21 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Y el propio Trump tambi\u00e9n utiliza la imagen: <\/p>\n<\/div>\n<div class=\"bbqjgdv c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r80o15e\">\n<figure>\n<blockquote class=\"b1speu17\">\n<p class=\"tosa0j6 hhhtovw\">Mucha gente dice que es la foto m\u00e1s ic\u00f3nica que jam\u00e1s hayan visto.  Tienes raz\u00f3n y no mor\u00ed.  Generalmente hay que morir para tener una foto ic\u00f3nica.<\/p>\n<\/blockquote><figcaption>\n<p class=\"aley63f m1lnp037\">Donald Trump, expresidente de Estados Unidos<\/p>\n<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">En una entrevista con el <a rel=\"nofollow noopener\" data-testid=\"richtext-link\" href=\"https:\/\/nypost.com\/2024\/07\/14\/us-news\/grateful-defiant-trump-recounts-surreal-assassination-attempt-at-rally-im-supposed-to-be-dead\/\" target=\"_blank\" class=\"\">&#8220;Correo de Nueva York&#8221;<\/a> Dijo adem\u00e1s que quer\u00eda revisar su discurso en la conferencia del partido.  Originalmente hab\u00eda preparado \u201cun discurso extremadamente duro\u201d sobre la \u201chorrible administraci\u00f3n\u201d del presidente Joe Biden.  Pero descart\u00f3 este texto y ahora quiere dar un discurso \u201cque unir\u00e1 a nuestro pa\u00eds\u201d.<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p><em>Donald Trump afirma querer trabajar por la unidad nacional.  La corresponsal del ZDF Claudia Bates de Milwaukee analiza lo que esto podr\u00eda significar:<\/em><\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"SGS Bates\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\"> <\/span><span class=\"m211382\">15 de julio de 2024 |  1:39 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p><em>A la hora de buscar el motivo exacto, \u201ca\u00fan queda mucho trabajo por aclarar\u201d:<\/em><\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Claudia Bates\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\"> <\/span><span class=\"m211382\">15 de julio de 2024 |  3:19 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>En <strong>ZDF hoy en vivo <\/strong>Hoy la pregunta era qu\u00e9 consecuencias tendr\u00e1 el ataque en la campa\u00f1a electoral.  El invitado fue el polit\u00f3logo y experto en comunicaci\u00f3n pol\u00edtica, Prof. Andrea R\u00f6mmele.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p><em>Puedes ver el programa aqu\u00ed: <\/em><\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"TN: Intento de asesinato a Trump\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">El expresidente estadounidense Trump recibi\u00f3 un disparo en un mitin de campa\u00f1a.  S\u00f3lo result\u00f3 levemente herido, el presunto autor est\u00e1 muerto, informa ZDFheute.<\/span><span class=\"m211382\">14 de julio de 2024 |  34:29 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span><strong>Asunto documental: el juez desestima los cargos<\/strong><\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Otro mensaje sobre Donald Trump: hay movimiento en uno de los procesos en curso contra el ex presidente: en el caso de la sustracci\u00f3n de documentos gubernamentales secretos, el juez a cargo ha suspendido el proceso penal.  Aileen Cannon justific\u00f3 la decisi\u00f3n con dudas sobre el nombramiento legal del fiscal especial Jack Smith en el caso.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Trump fue acusado a nivel federal en el asunto de los documentos el a\u00f1o pasado.  En este caso se le acusa de almacenar ilegalmente informaci\u00f3n muy sensible de su etapa como presidente (2017 a 2021).<\/p>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>\u00bfQu\u00e9 queda de la Eurocopa de casa?<\/span><\/h2>\n<\/p>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Euro 2024: Espa\u00f1a - Inglaterra\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\"> <\/span><span class=\"m211382\">15 de julio de 2024 |  3:32 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>\u00bfY qu\u00e9 hacen los espa\u00f1oles tras la victoria?  \u00a1Celebra por supuesto!  Los v\u00edtores son enormes.  Un d\u00eda despu\u00e9s de su victoria, est\u00e1 previsto que la selecci\u00f3n espa\u00f1ola de f\u00fatbol sea recibida hoy en la capital, Madrid.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p><em>Anne Arend, corresponsal del ZDF, sobre el pr\u00f3ximo calendario:<\/em><\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"anne-arend\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\"> <\/span><span class=\"m211382\">15 de julio de 2024 |  1:12 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>\u00bfA\u00fan tienes algo de espacio en el jard\u00edn?  \u00bfUnos 23 metros (alto) por 64 metros (ancho)?  \u00bfS\u00ed?  Y si todav\u00eda te quedan unos 180.000 euros, puedes llevarte a casa un pedazo de la historia de la Eurocopa.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Se pone a la venta la enorme porter\u00eda de f\u00fatbol que adorna la zona de aficionados del campeonato europeo de f\u00fatbol en la Puerta de Brandeburgo.  La empresa que construy\u00f3 la porter\u00eda dijo que la porter\u00eda deber\u00eda ser desmantelada y desguazada despu\u00e9s del Campeonato de Europa.  Sin embargo, si se encuentra un comprador, tambi\u00e9n se puede concertar una cita para la recogida.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"byi3ftt\">\n<div class=\"r1f6k8yy\" style=\"--r1f6k8yy-0:384\/480\"><picture class=\"slrzex8\" style=\"--slrzex8-0:var(--surface-subtle)\"><source  \/><img src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/Trump-el-intento-de-asesinato-y-el-poder-de-las.jpeg\"  alt=\"Gr\u00e1fico: Porter\u00eda de f\u00fatbol XXL ofrecida en anuncios clasificados en Berl\u00edn\" decoding=\"async\" loading=\"lazy\"  style=\"object-fit:cover;object-position:center\" class=\"f1mqliu0\"\/><\/picture><\/div>\n<\/div>\n<p>Gr\u00e1fico: Porter\u00eda de f\u00fatbol XXL ofrecida en anuncios clasificados en Berl\u00edn<\/p>\n<p>Fuente: kleinanzeigen.de<\/p>\n<hr class=\"l1uat3jy d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\"><em>Tambi\u00e9n puedes encontrar todo lo que necesitas leer en el nuestro. <\/em><strong><em>Blog en vivo<\/em><\/strong><em>.<\/em><\/div>\n<\/div>\n<div data-testid=\"content-module\" class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<article class=\"bhv9830\">\n<div class=\"tcxl1dq\">\n<h3>\n<p>Campeonato de Europa de f\u00fatbol 2024<\/p>\n<p><span class=\"h12yzj33\">:<\/span>Eurocopa 2024<\/h3>\n<p>La Eurocopa de f\u00fatbol de Alemania 2024 en directo por ZDF.  Transmisiones en vivo, momentos destacados, ticker en vivo, informaci\u00f3n sobre el equipo de la DFB e informaci\u00f3n general sobre el Campeonato de Europa.<\/p>\n<\/div>\n<div class=\"i107tcpe\">\n<div class=\"r1f6k8yy\" style=\"--r1f6k8yy-0:16\/9\"><picture class=\"slrzex8\" style=\"--slrzex8-0:var(--surface-subtle)\"><source  \/><img src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/06\/1718381462_842_Kilt-IA-cocaina-el-dia-en-resumen.jpeg\"  alt=\"Logotipo EM 2024 en Alemania\" decoding=\"async\" loading=\"lazy\"  style=\"object-fit:cover;object-position:center\" class=\"f1mqliu0\"\/><\/picture><\/div>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Triste, aunque no del todo sorprendente, noticia de nuestra selecci\u00f3n de la DFB: Thomas M\u00fcller visti\u00f3 por \u00faltima vez la camiseta de Alemania en la derrota por 2-1 contra Espa\u00f1a.<\/p>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>La renovaci\u00f3n de Riedbahn garantiza el cierre total <\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Durante el Campeonato de Europa, Deutsche Bahn no mostr\u00f3 precisamente su mejor cara: trenes impuntuales, tranv\u00edas abarrotados y mala comunicaci\u00f3n molestaron a muchos aficionados.<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>A partir de hoy, los viajeros en tren necesitan a\u00fan m\u00e1s paciencia: Deutsche Bahn comienza a renovar la ruta Mannheim-Frankfurt.  Se espera que las obras de construcci\u00f3n duren cinco meses.<\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Un ICE est\u00e1 estacionado en la estaci\u00f3n principal de trenes de Frankfurt.\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\"> <\/span><span class=\"m211382\">15 de julio de 2024 |  1:26 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>numero del dia<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Las organizaciones de la ONU est\u00e1n haciendo sonar la alarma por la falta de avances en la vacunaci\u00f3n infantil.  Las tasas de vacunaci\u00f3n en todo el mundo cayeron durante la pandemia de la corona y el a\u00f1o pasado todav\u00eda estaban por debajo de los niveles anteriores a la corona, como informan la Organizaci\u00f3n Mundial de la Salud (OMS) y el fondo para la infancia Unicef.<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>La vacuna contra la difteria, el t\u00e9tanos y la tos ferina se utiliza como indicador de las tasas de vacunaci\u00f3n entre los ni\u00f1os.  El n\u00famero de ni\u00f1os sin una sola dosis de esta triple vacuna aument\u00f3 el a\u00f1o pasado <strong>14,5 millones. <\/strong>Antes de que comenzara la pandemia eran 12,8 millones.<\/p>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>hallazgo del dia<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Es una sensaci\u00f3n cient\u00edfica: un ejemplar de una de las especies de ballenas m\u00e1s raras y menos conocidas del mundo ha aparecido en una playa de Nueva Zelanda.  El cad\u00e1ver del mam\u00edfero marino de cinco metros de largo probablemente era un zifio de Bahamonde, dijo la autoridad local de conservaci\u00f3n de la naturaleza (DOC).<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"byi3ftt\">\n<div class=\"r1f6k8yy\" style=\"--r1f6k8yy-0:384\/283\"><picture class=\"slrzex8\" style=\"--slrzex8-0:var(--surface-subtle)\"><source  \/><img src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1721059153_989_Trump-el-intento-de-asesinato-y-el-poder-de-las.jpeg\"  alt=\"Las im\u00e1genes, proporcionadas por el Departamento de Conservaci\u00f3n de Nueva Zelanda, muestran un zifio de Bahamonde arrastrado a la costa en una playa de la regi\u00f3n de Otago.\" decoding=\"async\" loading=\"lazy\"  style=\"object-fit:cover;object-position:center\" class=\"f1mqliu0\"\/><\/picture><\/div>\n<\/div>\n<p>Fuente: dpa<\/p>\n<hr class=\"l1uat3jy d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>M\u00e1s titulares<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\"><em>Si desea suscribirse a nuestra actualizaci\u00f3n de ZDFheute, puede <\/em><a rel=\"nofollow noopener\" data-testid=\"richtext-link\" href=\"https:\/\/zdfheute-update.zdf.de\/info\/\" target=\"_self\" class=\"\"><em>aqu\u00ed<\/em><\/a><em>  hacer o en el tuyo <\/em><strong><em>Aplicaci\u00f3n ZDFheute<\/em><\/strong><em>  en Mis noticias \/ Configuraci\u00f3n \/ Suscripci\u00f3n de actualizaci\u00f3n ZDFheute.<\/em><\/div>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>Consejos de streaming para despu\u00e9s del trabajo <\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Un avi\u00f3n de la Marina de los EE. UU. controlado por IA pierde el control despu\u00e9s de ser alcanzado por un rayo.  Se supone que los experimentados pilotos de combate Ben, Kara y Henry entrar\u00e1n. <strong>&#8220;Sigilo: bajo el radar&#8221;<\/strong> detener el avi\u00f3n fuertemente armado.  (<em>115 minutos<\/em>)<\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Motivo del cartel de la pel\u00edcula con Jessica Biel, Jamie Foxx y Josh Lucas.\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\"> <\/span><span class=\"m211382\">13 de julio de 2024 |  115:43 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>C\u00f3mo entrena la Bundeswehr a los soldados ucranianos: Oliver G. Becker acompa\u00f1\u00f3 en su informe el importante entrenamiento de los soldados en distintos lugares de Alemania y obtuvo conocimientos \u00fanicos.  (<em>29 minutos<\/em>)<\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--player-aspect-ratio:56.25%;--aspect-ratio:16\/9\" class=\"syazf3a c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"\u00bfBajo el radar?  - Entrena mientras luchas\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\"> <\/span><span class=\"m211382\">9 de julio de 2024 |  29:38 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>\u00a1Disfruta tu velada!<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\"><strong>\u00bfTodo esta bien?<\/strong> \u00a1Gracias por leer nuestra actualizaci\u00f3n de ZDFheute!  No dude en recomendar la sesi\u00f3n informativa a sus amigos y conocidos: aqu\u00ed est\u00e1 <a rel=\"nofollow noopener\" data-testid=\"richtext-link\" href=\"https:\/\/zdfheute-update.zdf.de\/info\/\" target=\"_self\" class=\"\">Enlace de registro<\/a>.  Tambi\u00e9n estaremos encantados de recibir sus comentarios sobre lo que le gusta especialmente y lo que deber\u00edamos hacer mejor en zdfheute-feedback@zdf.de.  \u00a1Gracias por tu apoyo!<\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.zdf.de\/nachrichten\/briefing\/trump-em-riedbahn-zdfheute-update-102.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-39<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas noches, La mayor\u00eda de la gente se despert\u00f3 ayer con esta noticia: le dispararon a Donald Trump.<\/p>\n","protected":false},"author":1,"featured_media":1237631,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1319,1462,2510,246,534,243],"class_list":["post-1277707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-asesinato","tag-imagenes","tag-intento","tag-las","tag-poder","tag-trump"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1277707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1277707"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1277707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1237631"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1277707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1277707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1277707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}