{"id":1274721,"date":"2024-07-13T06:14:16","date_gmt":"2024-07-13T06:14:16","guid":{"rendered":"https:\/\/teknomers.com\/es\/negociaciones-de-directores-el-ejecutivo-de-qbeyond-ex-qsc-mueve-acciones\/"},"modified":"2024-07-13T06:14:20","modified_gmt":"2024-07-13T06:14:20","slug":"negociaciones-de-directores-el-ejecutivo-de-qbeyond-ex-qsc-mueve-acciones","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/negociaciones-de-directores-el-ejecutivo-de-qbeyond-ex-qsc-mueve-acciones\/","title":{"rendered":"Negociaciones de directores: el ejecutivo de qbeyond (ex QSC) mueve acciones"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>La acci\u00f3n de qbeyond (ex QSC) llam\u00f3 la atenci\u00f3n de los inversores despu\u00e9s de un acuerdo con informaci\u00f3n privilegiada. <\/p>\n<div>\n<p>El 11 de julio de 2024, las transacciones de los directores se registraron en qbeyond (ex QSC).  La transacci\u00f3n se inform\u00f3 oficialmente el 12 de julio de 2024.  Rixen, Thies, miembro de la junta directiva, accedi\u00f3 a las acciones de qbeyond (ex QSC) el 11 de julio de 2024.  Se compraron 41.975 acciones de qbeyond (ex QSC) a un precio de 0,80 euros cada una.  La acci\u00f3n de qbeyond (ex QSC) finalmente se cotiz\u00f3 a 0,80 euros en la bolsa FSE con un descuento del 0,50 por ciento.<\/p>\n<p>El documento de qbeyond (ex QSC) finalmente subi\u00f3 el d\u00eda de la publicaci\u00f3n de BaFin y subi\u00f3 un 4,30 por ciento hasta 0,82 euros en el comercio FSE.  Ese d\u00eda, un total de 3.235 acciones de qbeyond (ex QSC) cambiaron de manos.  La capitalizaci\u00f3n burs\u00e1til de qbeyond (ex QSC) asciende actualmente a 100,41 millones de euros.  Actualmente existen 124.579.000 valores en libre negociaci\u00f3n.<\/p>\n<p>Un uso de informaci\u00f3n privilegiada por parte de Rixen, Thies, fue identificado ya el 10 de julio de 2024.  En aquel momento, el ejecutivo compr\u00f3 7.880 acciones de qbeyond (ex QSC) a 0,80 euros cada una. <\/p>\n<p>  Equipo editorial finanzen.net<\/p>\n<\/div>\n<div id=\"\">\n<h2 class=\"headline headline--h4\">Productos de apalancamiento seleccionados en q.beyond (ex QSC)<\/h2>\n<p>Con los knock-outs, los inversores especulativos pueden participar desproporcionadamente en los movimientos de precios.  Simplemente seleccione la palanca que desee y le mostraremos los productos abiertos adecuados en q.beyond (ex QSC)<\/p>\n<p class=\"font-color-red display-none\" id=\"lvgCustomHandleInfo\">El apalancamiento debe estar entre 2 y 20<\/p>\n<p><span class=\"ad-hint ad-hint--right display-block\">Publicidad<\/span><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/directors-dealings-qbeyond-ex-qsc-fuehrungskraft-bewegt-aktien-13669132\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-28<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La acci\u00f3n de qbeyond (ex QSC) llam\u00f3 la atenci\u00f3n de los inversores despu\u00e9s de un acuerdo con informaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":1230996,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[668,11855,743,2786,6472,242240,242241],"class_list":["post-1274721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finanzas","tag-acciones","tag-directores","tag-ejecutivo","tag-mueve","tag-negociaciones","tag-qbeyond","tag-qsc"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1274721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1274721"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1274721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1230996"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1274721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1274721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1274721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}