{"id":1274718,"date":"2024-07-13T06:12:11","date_gmt":"2024-07-13T06:12:11","guid":{"rendered":"https:\/\/teknomers.com\/es\/sharon-stone-de-66-anos-sorprende-con-su-reveladora-lenceria-roja-mientras-recrea-la-iconica-escena-de-instinto-basico-32-anos-despues\/"},"modified":"2024-07-13T06:12:16","modified_gmt":"2024-07-13T06:12:16","slug":"sharon-stone-de-66-anos-sorprende-con-su-reveladora-lenceria-roja-mientras-recrea-la-iconica-escena-de-instinto-basico-32-anos-despues","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/sharon-stone-de-66-anos-sorprende-con-su-reveladora-lenceria-roja-mientras-recrea-la-iconica-escena-de-instinto-basico-32-anos-despues\/","title":{"rendered":"Sharon Stone, de 66 a\u00f1os, sorprende con su reveladora lencer\u00eda roja mientras recrea la ic\u00f3nica escena de Instinto B\u00e1sico 32 a\u00f1os despu\u00e9s"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>La estrella de BASIC Instinct, Sharon Stone, demuestra que todav\u00eda tiene lo que tiene al recrear su escena m\u00e1s famosa 32 a\u00f1os despu\u00e9s.<\/p>\n<p>La mujer de 66 a\u00f1os pos\u00f3 con lencer\u00eda de encaje rojo y con las piernas cruzadas para una foto publicada en l\u00ednea.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"1\"><a rel=\"nofollow\" href=\"#\"><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">2<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Sharon Stone demuestra que todav\u00eda tiene fuerza al recrear su escena m\u00e1s famosa a los 66 a\u00f1os<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"2\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Sharon en la escena original de la pel\u00edcula Instinto b\u00e1sico de 1992\" height=\"960\" width=\"688\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720851131_406_Sharon-Stone-de-66-anos-sorprende-con-su-reveladora-lenceria.jpg\" data-credit=\"Alamy\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720851131_406_Sharon-Stone-de-66-anos-sorprende-con-su-reveladora-lenceria.jpg?strip=all&amp;w=688\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">2<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Sharon en la escena original de la pel\u00edcula Instinto b\u00e1sico de 1992<\/span><span class=\"article__credit\">Cr\u00e9dito: Alamy<\/span><\/figcaption><\/figure>\n<p>Ella comparti\u00f3 el <span id=\"03a0afb0-d275-42a3-82cf-73768c42151e\" class=\"suggested-link\">quebrar<\/span>subtitulado \u201cB\u00e1sicamente\u2026 tuyo\u201d, con sus cuatro millones de seguidores en Instagram.<\/p>\n<p>Sharon sorprendi\u00f3 a los espectadores en el thriller er\u00f3tico de 1992 cuando descruz\u00f3 las piernas durante un interrogatorio policial para revelar que no llevaba bragas.<\/p>\n<p>Esta semana, Sharon, que sufri\u00f3 un derrame cerebral en 2001, dijo que le hab\u00edan robado 14 millones de libras de sus ahorros mientras se recuperaba.<\/p>\n<p>Ella dijo: \u201cLa gente se aprovech\u00f3 de m\u00ed durante ese tiempo. Cuando recuper\u00e9 mi cuenta bancaria, todo hab\u00eda desaparecido\u201d.<\/p>\n<div class=\"read-more-container theme-showbiz read-more-container--article-entry t-010-background-color\" data-widget-title=\"READ MORE ON SHARON STONE\" data-widget-article-count=\"2\">\n<h2 class=\"read-more-container_title\" data-original-text=\"READ MORE ON SHARON STONE\">LEER M\u00c1S SOBRE SHARON STONE<\/h2>\n<\/div>\n<p>Recientemente, Sharon hizo alarde de su cuerpo en Instagram mientras pintaba en topless en su estudio.<\/p>\n<p>La estrella de Casino hizo alarde de su espalda desnuda mientras estaba en topless, vistiendo \u00fanicamente una diminuta braguita de bikini azul.<\/p>\n<p>Sharon subtitul\u00f3 el <a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/p\/C9OSQKAxS9w\/\" target=\"_blank\" aria-label=\"photo (opens in a new tab)\">foto<\/a>&#8220;A veces simplemente tengo que ir de <span id=\"e93da9e9-869d-4b71-9b1c-6f71021f5e8c\" class=\"suggested-link\">piscina<\/span> &#8220;a la pintura.&#8221;<\/p>\n<p>Los fan\u00e1ticos r\u00e1pidamente corrieron a la secci\u00f3n de comentarios para decir lo bien que se ve\u00eda para su edad. <\/p>\n<p>&#8220;A los 66 a\u00f1os creo que es perfecta&#8221;, dijo un usuario de Instagram.<\/p>\n<div class=\"article-boxout\">\n<p><h3 class=\"article-boxout__headline t-s-border-color\">LAS PEL\u00cdCULAS IC\u00d3NICAS DE SHARON STONE<\/h3>\n<\/p>\n<div class=\"article-boxout__content theme__background-color-rgba-20\">\n<p class=\"article__content--intro\">Sharon Stone se hizo famosa por su papel en Instinto b\u00e1sico en 1992. A continuaci\u00f3n se muestran otras pel\u00edculas y programas en los que particip\u00f3: <\/p>\n<div>\n<p>Acci\u00f3n Jackson (1988)<\/p>\n<p>Desaf\u00edo total (1990)<\/p>\n<p>Astilla (1993)<\/p>\n<p>El especialista (1994)<\/p>\n<p>Casino (1995)<\/p>\n<p>Catwoman (2004)<\/p>\n<p>Agente X (2015)<\/p>\n<p>Mosaico (2018)<\/p>\n<p>Trinquete (2020)<\/p>\n<p>La azafata Temporada 2 (2022)<\/p>\n<p>Belleza (2022)<\/p>\n<p>\u00bfQu\u00e9 pasa con el amor? (2024)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"bc-video-6351941445112\" class=\"brightcove\"><span class=\"article__bc_video-caption\">La estrella de Basic Instinct, Sharon Stone, admite tener &#8216;demonios&#8217; mientras rompe a llorar en una nueva y emotiva entrevista<\/span><\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/tvandshowbiz\/29191365\/sharon-stone-recreates-basic-instinct-scene\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La estrella de BASIC Instinct, Sharon Stone, demuestra que todav\u00eda tiene lo que tiene al recrear su escena<\/p>\n","protected":false},"author":1,"featured_media":1274719,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[205,1334,99,755,239506,6943,26457,445,29946,619,58517,3530,83034,41108,8287,239505,25787,5459,4623],"class_list":["post-1274718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-anos","tag-basico","tag-con","tag-despues","tag-el-periodico-the-sun","tag-escena","tag-iconica","tag-instagram","tag-instinto","tag-lenceria","tag-medios-de-comunicacion-social","tag-mientras","tag-recrea","tag-reveladora","tag-roja","tag-seccion-espectaculoscelebridades","tag-sharon","tag-sorprende","tag-stone"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1274718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1274718"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1274718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1274719"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1274718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1274718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1274718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}