{"id":1274380,"date":"2024-07-12T23:29:30","date_gmt":"2024-07-12T23:29:30","guid":{"rendered":"https:\/\/teknomers.com\/es\/ataque-o-defensa-pogacar-tiene-que-decidir\/"},"modified":"2024-07-12T23:29:34","modified_gmt":"2024-07-12T23:29:34","slug":"ataque-o-defensa-pogacar-tiene-que-decidir","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/ataque-o-defensa-pogacar-tiene-que-decidir\/","title":{"rendered":"\u00bfAtaque o defensa?  Pogacar tiene que decidir"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"seitenkopf\">\n<div class=\"seitenkopf__data columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"seitenkopf__title\">\n<p>\n                <span class=\"label label--small\"><br \/>\n                    <strong>reportero de gira<\/strong><br \/>\n                <\/span>\n                <\/p>\n<p class=\"metatextline\">A partir de: 12 de julio de 2024 21:09<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n        <strong>En el final de la apasionante 13\u00aa etapa, Tadej Pogacar participa al sprint.  El deseo de correr en bicicleta y de atacar corresponde a su naturaleza.  Antes del dif\u00edcil fin de semana en los Pirineos, el esloveno debe plantearse si tambi\u00e9n podr\u00e1 defender.<\/strong>\n    <\/p>\n<div class=\"copytext-element-wrapper columns twelve\">\n<div class=\"columns twelve m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"authorline\">\n<div class=\"authorline__inner\">\n<div class=\"authorline__img-wrapper\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Tadej Pogacar dispuso de una bicicleta de contrarreloj durante los casi 100 metros entre el podio y el autob\u00fas del equipo, por alguna raz\u00f3n.  El esloveno salud\u00f3 a los espectadores detr\u00e1s de las barreras y, cuando abandon\u00f3 la zona asegurada, la gente le abri\u00f3 paso. <span lang=\"fr\">Gendarmes<\/span> y los empleados de la organizaci\u00f3n tur\u00edstica abren el camino entre la multitud.<\/p>\n<h2 id=\"Pogacar-sprintet-auf-Rang-neun\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Pogacar corre hasta la novena plaza<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Pogacar acababa de completar las tareas diarias del hombre del maillot amarillo: podio, entrevistas, rueda de prensa.  En ese momento, sus competidores ya se dirig\u00edan al hotel para recuperarse.  Ante las dificultades que se avecinan y a partir de una 13\u00aa etapa del <span lang=\"fr\">Tour de Francia<\/span>que los pilotos consideraron para la clasificaci\u00f3n general como una etapa de traslado hacia los Pirineos que ahorra mucha energ\u00eda.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>La realidad ofreci\u00f3 entonces una etapa de alta velocidad con situaciones de carrera en constante cambio, bordes de viento donde el campo se dividi\u00f3 en varias partes y un grupo m\u00e1s peque\u00f1o corriendo hacia la meta. <span lang=\"fr\">Pablo<\/span>.  Lo gan\u00f3 el belga Jasper Philipsen, pero en medio de este sprint final tambi\u00e9n se hizo visible el maillot amarillo.  Pogacar acab\u00f3 la etapa en novena posici\u00f3n.<\/p>\n<h2 id=\"Pogacar-Macht-euch-keine-Sorgen\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Pogacar: &#8220;No te preocupes&#8221;<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\"><cite>&#8220;Ten\u00eda buenas piernas, estaba en una buena posici\u00f3n y es bonito estar entre los diez primeros en una etapa al sprint&#8221;<\/cite>dijo despu\u00e9s Pogacar de buen humor, como si no hubiera corrido ning\u00fan riesgo con ello.  Oh qu\u00e9: &#8220;<cite>No te preocupes.  Siempre mantuve la calma en la final, no hab\u00eda estr\u00e9s, estaba en mi zona de seguridad, mi propia burbuja y con la cabeza despejada evit\u00e9 todas las cosas agitadas&#8221;.<\/cite><\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Pogacar sigue siendo Pogacar, un corredor por instinto.  Pero si eso siempre tiene sentido cuando se trata de ganar el Tour de Francia sigue siendo una pregunta que se responder\u00e1 en los ocho d\u00edas restantes de carreras en Francia.  La primera informaci\u00f3n estar\u00e1 disponible este fin de semana.  Luego hay dos etapas dif\u00edciles de alta monta\u00f1a, cada una con una subida final, en el men\u00fa.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Pogacar llega al fin de semana de los Pirineos con una ventaja de 1&#8217;06 minutos sobre el segundo clasificado, Remco Evenepoel.  A ocho segundos m\u00e1s est\u00e1 el ganador del a\u00f1o pasado, Jonas Vingegaard, al que el esloveno realmente teme.  As\u00ed que Pogacar puede esperar, el belga y el dan\u00e9s tienen que atacarlo para sacar la tarjeta amarilla.<\/p>\n<h2 id=\"Kann-Pogacar-der-Lust-auf-Attacke-widerstehen\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">\u00bfPodr\u00e1 Pogacar resistir las ganas de atacar?<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\"><cite>&#8220;Hasta ahora s\u00f3lo hemos tenido una verdadera etapa de monta\u00f1a&#8221;<\/cite>Pogacar se refiri\u00f3 a la 4\u00aa etapa en Pau, donde estuvo en <span lang=\"fr\">Galibier <\/span>atac\u00f3 y aument\u00f3 parte de su ventaja actual sobre los dos. <cite>&#8220;Veremos c\u00f3mo se comportan los otros equipos, pero podemos estar un poco a la defensiva, tal vez intentar ganar la etapa, pero sin gastar mucha energ\u00eda porque tenemos una c\u00f3moda ventaja&#8221;.<\/cite><\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Sin embargo, la defensa no est\u00e1 en la naturaleza de Pogacar y no est\u00e1 claro si podr\u00e1 resistir su deseo de atacar. <cite>&#8220;Le gusta conducir de manera ofensiva y atacar, pero tambi\u00e9n sabe cu\u00e1ndo atacar y cu\u00e1ndo no&#8221;.<\/cite>afirma el director del equipo de Pogacar en los Emiratos \u00c1rabes Unidos, <span lang=\"it\">Mauro Gianetti<\/span>. <cite>&#8220;Estamos en una buena posici\u00f3n para controlar la carrera&#8221;.<\/cite><\/p>\n<h2 id=\"Pogacar-verliert-wichtigen-Helfer\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Pogacar pierde un importante ayudante<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>\u00bfControlar en lugar de atacar?  Pogacar tambi\u00e9n perdi\u00f3 a un importante ayudante para la monta\u00f1a en la 13\u00aa etapa.  El espa\u00f1ol<span lang=\"es\"> Juan Ayuso<\/span>, que no estaba en pleno dominio de sus fuerzas en la dif\u00edcil 11\u00aa etapa en el Macizo Central, abandon\u00f3 la carrera por enfermedad.  Pogacar tambi\u00e9n intent\u00f3 mostrarse tranquilo en este caso.  Su equipo es realmente fuerte e incluso mejora cada d\u00eda. <cite>&#8220;No es perfecto que nos falte alguien, pero lo haremos&#8221;.<\/cite>dijo el esloveno.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Son\u00f3 un poco como un silbido en el bosque.  Aunque su equipo hab\u00eda trabajado duro recientemente en el Macizo Central para preparar a Pogacar para un ataque a sus rivales, no hubo resultado.  Al menos no pudo aumentar su ventaja sobre su rival m\u00e1s cercano.<\/p>\n<h2 id=\"Vingegaards-Terrain-kommt-jetzt\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">El terreno de Vingegaard llega ahora<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">Con su victoria de etapa all\u00ed, Jonas Vingegaard demostr\u00f3 que est\u00e1 en plena forma a pesar de su grave ca\u00edda en abril y de s\u00f3lo seis semanas de preparaci\u00f3n para el Tour.  Lo que claramente puso a Pogacar bajo presi\u00f3n.  Porque ahora llega el terreno que le conviene mucho mejor al dan\u00e9s que las cortas y explosivas subidas al Macizo Central.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>el esta calculando <cite>&#8220;con dos etapas de monta\u00f1a muy intensas&#8221;<\/cite>dijo el director deportivo de Vingegaard en el equipo <span lang=\"nl\">visma<\/span>&#8211;<span lang=\"en\">Alquilar una bicicleta<\/span>Grischa Niermann. <cite>&#8220;Y, por supuesto, esperamos que Jonas sea el m\u00e1s fuerte en las subidas muy, muy largas&#8221;.<\/cite><\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Esto tambi\u00e9n significa que el dan\u00e9s tiene que pasar a la ofensiva.  O apuesta a que, a pesar de todos los anuncios, Pogacar saltar\u00e1 demasiado r\u00e1pido cuando vea la oportunidad de atacar. <cite>&#8220;No har\u00e9 ninguna locura&#8221;<\/cite>, prometi\u00f3 el hombre del maillot amarillo en Pau.  Pero la pregunta es: \u00bfqu\u00e9 cree Pogacar que es una locura y qu\u00e9 no?<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sportschau.de\/radsport\/tourdefrance\/angriff-oder-verteidigung-pogacar-muss-sich-entscheiden,13-etappe-tour-de-france-tourreporter-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>reportero de gira A partir de: 12 de julio de 2024 21:09 En el final de la apasionante<\/p>\n","protected":false},"author":1,"featured_media":1274381,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[89836,1247,1019,13911,3275,1022,324,29940],"class_list":["post-1274380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-13a-etapa","tag-ataque","tag-ciclismo","tag-decidir","tag-defensa","tag-pogacar","tag-tiene","tag-tour-de-francia"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1274380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1274380"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1274380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1274381"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1274380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1274380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1274380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}