{"id":1273633,"date":"2024-07-12T11:22:07","date_gmt":"2024-07-12T11:22:07","guid":{"rendered":"https:\/\/teknomers.com\/es\/francois-letexier-el-arbitro-de-la-final-de-la-eurocopa-le-dio-una-bofetada-a-haaland\/"},"modified":"2024-07-12T11:22:12","modified_gmt":"2024-07-12T11:22:12","slug":"francois-letexier-el-arbitro-de-la-final-de-la-eurocopa-le-dio-una-bofetada-a-haaland","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/francois-letexier-el-arbitro-de-la-final-de-la-eurocopa-le-dio-una-bofetada-a-haaland\/","title":{"rendered":"Fran\u00e7ois Letexier: el \u00e1rbitro de la final de la Eurocopa le dio una bofetada a Haaland"},"content":{"rendered":"\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"font-bold text-18 leading-17\">Fran\u00e7ois Letexier es considerado un ni\u00f1o prodigio en el panorama arbitral y arbitrar\u00e1 la final del Campeonato de Europa.  Pero se hizo famoso abofeteando a una estrella mundial.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Desde el 9 de abril, Fran\u00e7ois Letexier puede sentirse una celebridad de Internet.  Finalmente, la escena del espectacular partido de ida de cuartos de final de la liga de Campeones entre Real Madrid y Manchester City (3-3), en la que el \u00e1rbitro franc\u00e9s roz\u00f3 accidentalmente al delantero estrella del City Erling Haaland, se convirti\u00f3 en un golpe fren\u00e9tico en el web.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">En ese momento, Letexier solo quer\u00eda explicarle una decisi\u00f3n al enojado espa\u00f1ol Dani Carvajal con los brazos al aire, cuando Haaland, que se acercaba por detr\u00e1s, recibi\u00f3 un manotazo del \u00e1rbitro al pasar y parec\u00eda bastante desconcertado.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Al menos Letexier podr\u00e1 volver a comentar la escena con Carvajal el domingo.  El \u00fanico jugador de 35 a\u00f1os arbitrar\u00e1 la final de la Eurocopa de f\u00fatbol entre Espa\u00f1a e Inglaterra (21:00 horas en el teletipo en directo de t-online).  El comit\u00e9 de \u00e1rbitros de la Uni\u00f3n Europea de F\u00fatbol (UEFA) anunci\u00f3 el jueves el sorprendente calendario de la final en el Estadio Ol\u00edmpico de Berl\u00edn.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El principal cr\u00edtico Manuel Gr\u00e4fe ve la nominaci\u00f3n de Letexier como un &#8220;gran honor inicial&#8221; y elogia a la UEFA<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Letexier ya ha entrado en acci\u00f3n en tres ocasiones en la actual fase final; ya arbitr\u00f3 a los espa\u00f1oles en la victoria de octavos de final ante Georgia (4-1).  En la final, Letexier contar\u00e1 con el apoyo de sus compatriotas Cyril Mugnier y Mehdi Rahmouni.  El polaco Szymon Marciniak act\u00faa como cuarto \u00e1rbitro.  Al igual que Letexier, el asistente de v\u00eddeo Jerome Brisard proviene de Francia.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Adem\u00e1s del partido entre Real y Manchester, Letexier disput\u00f3 otros nueve partidos de la Copa de Europa la temporada pasada.  En la final de la categor\u00eda reina disputada en el estadio londinense de Wembley, el \u00e1rbitro vio en su calidad de cuarto \u00e1rbitro la victoria del Madrid ante el Borussia Dortmund (2-0).<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Con su nombramiento para la final de Berl\u00edn, Letexier, procedente de Breta\u00f1a, por fin es considerado un genio en el panorama arbitral europeo.  Letexier celebr\u00f3 su debut en la Ligue 1 francesa en enero de 2016. S\u00f3lo dos a\u00f1os despu\u00e9s ya jugaba internacionalmente.  Forma parte de la \u00e9lite de la Uni\u00f3n Europea de F\u00fatbol (Uefa) desde hace dos a\u00f1os y medio.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El punto culminante de la carrera de Letexier hasta la fecha fue liderar la Supercopa de Europa el a\u00f1o pasado, que el City gan\u00f3 en los penaltis contra el Sevilla FC.  Eso cambiar\u00e1 el domingo, ojal\u00e1 sin una bofetada.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/fussball\/em\/id_100447434\/francois-letexier-schiri-des-em-finales-verteilte-ohrfeige-an-haaland.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fran\u00e7ois Letexier es considerado un ni\u00f1o prodigio en el panorama arbitral y arbitrar\u00e1 la final del Campeonato de<\/p>\n","protected":false},"author":1,"featured_media":1273634,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[236486,2575,20665,203197,973,51198,4145,2730,1076,10479,463,51291,143136,2734,485,241935,297,980,1288,460,158],"class_list":["post-1273633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-236486","tag-arbitro","tag-bofetada","tag-campeonato-de-europa-de-futbol","tag-ciudad-de-manchester","tag-dani-carvajal","tag-dio","tag-erling-haaland","tag-espana","tag-eurocopa","tag-final","tag-final-del-juego","tag-francois","tag-haaland","tag-inglaterra","tag-letexier","tag-liga-de-campeones","tag-manchester","tag-real-madrid","tag-uefa","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1273633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1273633"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1273633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1273634"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1273633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1273633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1273633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}