{"id":1273094,"date":"2024-07-12T01:39:26","date_gmt":"2024-07-12T01:39:26","guid":{"rendered":"https:\/\/teknomers.com\/es\/kesha-posa-en-bikini-comentando-sobre-la-paz-corporal\/"},"modified":"2024-07-12T01:39:31","modified_gmt":"2024-07-12T01:39:31","slug":"kesha-posa-en-bikini-comentando-sobre-la-paz-corporal","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/kesha-posa-en-bikini-comentando-sobre-la-paz-corporal\/","title":{"rendered":"Kesha posa en bikini &#8211; Comentando sobre la paz corporal"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>Kesha responde al odio al cuerpo en Instagram.<\/p>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">La cantante Kesha public\u00f3 una actualizaci\u00f3n en Instagram donde coment\u00f3 comentarios desagradables sobre su cuerpo.<\/p>\n<p class=\"paragraph\">&#8211; No sab\u00eda que en 2024 la gente todav\u00eda romper\u00eda la paz del cuerpo, coment\u00f3 Kesha.<\/p>\n<p class=\"paragraph\">Escribe que est\u00e1 orgullosa de su cuerpo, que ha soportado mucho.<\/p>\n<p class=\"paragraph\">&#8211; Me romp\u00ed la clav\u00edcula en el escenario y arrastr\u00e9 la actuaci\u00f3n hasta el final.  He mantenido mi coraz\u00f3n roto unido, escribe.<\/p>\n<p class=\"paragraph\">&#8211; T\u00fa que intentas desacreditarme me haces sentir muy fuerte, afirma Kesha.<\/p>\n<p class=\"paragraph\">Ella anima a la gente a no menospreciar a otras mujeres.<\/p>\n<p class=\"paragraph\">Si la publicaci\u00f3n no est\u00e1 visible, puedes visualizarla. <a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/p\/C9IQCqdu_FV\/?img_index=1\" target=\"_blank\">desde este enlace<\/a>.<\/p>\n<p class=\"paragraph\">En su foto de Instagram, Kesha est\u00e1 tumbada en la playa en bikini.  Su gran tatuaje es visible en el costado.<\/p>\n<p class=\"paragraph\">La publicaci\u00f3n de Kesha ha obtenido sus comentarios de apoyo y admiraci\u00f3n.<\/p>\n<p class=\"paragraph\">&#8211; \u00bfC\u00f3mo puede alguien odiarlo?, coment\u00f3 un usuario en Instagram.<\/p>\n<p class=\"paragraph\">&#8211; \u00a1Eres hermoso!  Hermosa persona, hermoso cuerpo y hermosa alma.  Los que odian odian porque est\u00e1n celosos.  Iluminas este mundo, escribe otro usuario.<\/p>\n<p class=\"paragraph\">&#8211; Lamentablemente, algunas personas no aprenden a ocuparse de sus propios asuntos.  Es realmente triste.  \u00a1Sigue brillando!  uno coment\u00f3.<\/p>\n<h3 class=\"subheadline\">Batalla legal por<\/h3>\n<p class=\"paragraph\">El a\u00f1o pasado, Kesha resolvi\u00f3 una disputa legal de una d\u00e9cada con el productor musical Dr. Luke, nombre real. <strong>por Lukasz Gottwald<\/strong> con.<\/p>\n<p class=\"paragraph\">La batalla legal comenz\u00f3 en 2014, cuando Kesha demand\u00f3 al hombre y dijo que Gottwald la hab\u00eda violado cuando era m\u00e1s joven.  Gottwald luego demand\u00f3 a Kesha por difamaci\u00f3n, acusando a la cantante de inventar las acusaciones para rescindir su contrato discogr\u00e1fico.<\/p>\n<p class=\"paragraph\">Kesha coment\u00f3 el asunto en un comunicado de prensa, donde ambas partes compartieron sus puntos de vista al respecto.<\/p>\n<p class=\"paragraph\">&#8211; S\u00f3lo Dios sabe lo que pas\u00f3 esa noche.  Como siempre he dicho, no recuerdo todo lo que pas\u00f3.  Espero cerrar este cap\u00edtulo en mi vida y comenzar uno nuevo.  S\u00f3lo deseo paz para todas las partes implicadas, afirma Kesha en el comunicado de prensa.<\/p>\n<p class=\"paragraph\">Kesha es conocida, por ejemplo, por su \u00e9xito de 2009. <em>Tik Tok<\/em>producido por Dr. Luke y Benny Blanco.<\/p>\n<div class=\"article-image gallery center\" itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:74.95%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720748366_55_Kesha-posa-en-bikini-Comentando-sobre-la-paz-corporal.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720748366_55_Kesha-posa-en-bikini-Comentando-sobre-la-paz-corporal.jpg\"\/><meta itemprop=\"width\" content=\"2000\"\/><meta itemprop=\"height\" content=\"1499\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Kesha valkoisessa mekossa vuonna 2024.\"\/><span class=\"caption-text\" itemprop=\"description\">Kesha con un vestido blanco en 2024.<!-- --> <\/span><span class=\"media-source\">DOP<\/span><\/p>\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/musiikki\/a\/b5abf6ca-a63c-47b5-9264-ed1f907f19c6\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-50<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kesha responde al odio al cuerpo en Instagram. La cantante Kesha public\u00f3 una actualizaci\u00f3n en Instagram donde coment\u00f3<\/p>\n","protected":false},"author":1,"featured_media":1273095,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[84803,128,5621,60499,5308,3412,49471,125,390,1934,35828,3918,131],"class_list":["post-1273094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-24-horas","tag-audio","tag-bikini","tag-comentando","tag-corporal","tag-expresion-artistica-y-medios","tag-kesha","tag-musica","tag-musicos-y-bandas","tag-paz","tag-posa","tag-sexo","tag-sobre"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1273094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1273094"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1273094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1273095"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1273094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1273094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1273094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}