{"id":1273008,"date":"2024-07-12T00:01:27","date_gmt":"2024-07-12T00:01:27","guid":{"rendered":"https:\/\/teknomers.com\/es\/antagonico-hermoso-profundo-visceral-simplemente-abre-tus-juegos-mentales-john-lennon-ha-vuelto\/"},"modified":"2024-07-12T00:01:31","modified_gmt":"2024-07-12T00:01:31","slug":"antagonico-hermoso-profundo-visceral-simplemente-abre-tus-juegos-mentales-john-lennon-ha-vuelto","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/antagonico-hermoso-profundo-visceral-simplemente-abre-tus-juegos-mentales-john-lennon-ha-vuelto\/","title":{"rendered":"Antag\u00f3nico, hermoso, profundo, visceral: simplemente abre tus juegos mentales\u2026 John Lennon ha vuelto"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>PIENSE en el nivel de creatividad alcanzado por The Beatles en su relativamente breve pero estelar carrera discogr\u00e1fica.<\/p>\n<p>Uno podr\u00eda \u201cimaginar\u201d que John Lennon necesitaba descansar un buen rato en una habitaci\u00f3n oscura despu\u00e9s de que los Fab Four tomaron caminos separados en 1970.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"1\"><a rel=\"nofollow\" href=\"#\"><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Tras el fin de The Beatles, John Lennon emprendi\u00f3 su carrera en solitario a toda velocidad.<\/span><span class=\"article__credit\">Cr\u00e9dito: suministrado<\/span><\/figcaption><\/figure>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"2\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Antes de escribir el \u00e1lbum en solitario Mind Games, Lennon estaba a punto de entrar en un per\u00edodo de separaci\u00f3n de 18 meses de Yoko Ono.\" height=\"574\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720742486_170_Antagonico-hermoso-profundo-visceral-simplemente-abre-tus-juegos-mentales\u2026-John.jpg\" data-credit=\"Supplied\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720742486_170_Antagonico-hermoso-profundo-visceral-simplemente-abre-tus-juegos-mentales\u2026-John.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Antes de escribir el \u00e1lbum en solitario Mind Games, Lennon estaba a punto de entrar en un per\u00edodo de separaci\u00f3n de 18 meses de Yoko Ono.<\/span><span class=\"article__credit\">Cr\u00e9dito: suministrado<\/span><\/figcaption><\/figure>\n<p>Pero lejos de eso, emprendi\u00f3 su carrera en solitario a un ritmo fren\u00e9tico.<\/p>\n<p>Liberado de las limitaciones de estar en LA banda, las composiciones libres de Lennon incluyeron sus temas permanentes de paz y amor, as\u00ed como reflexiones apasionadas sobre pol\u00edtica, clase, injusticia y religi\u00f3n.<\/p>\n<p>Intransigente, visceral, aut\u00e9ntico, bello, antag\u00f3nico, profundo, experimental.<\/p>\n<p>Todas estas palabras se aplican en diversos puntos del conjunto de la obra que estaba reuniendo.<\/p>\n<p>Sus tres primeros \u00e1lbumes fueron lanzados con 18 meses de diferencia entre s\u00ed: John Lennon\/Plastic Ono Band (1970), Imagine (1971) y Sometime In New York City (1972 con Yoko Ono), sin duda el trabajo de un hombre apurado.<\/p>\n<p>Pero en 1973, la vida de Lennon lleg\u00f3 a una encrucijada.<\/p>\n<p>A los 33 a\u00f1os, se enfrent\u00f3 a la deportaci\u00f3n de los EE. UU. por su postura de alto perfil contra la guerra de Vietnam y el presidente en ejercicio, Richard Nixon.<\/p>\n<p>En casa, su relaci\u00f3n aparentemente inquebrantable con Yoko Ono estaba a punto de entrar en una separaci\u00f3n de 18 meses que inclu\u00eda su legendario \u201cfin de semana perdido\u201d.<\/p>\n<p>Fue en este contexto de incertidumbre que Lennon se aventur\u00f3 a Record Plant de la ciudad de Nueva York para grabar su cuarto \u00e1lbum en solitario, Mind Games.<\/p>\n<p>Decidi\u00f3 utilizar los mismos m\u00fasicos de sesi\u00f3n del \u00e1lbum Feeling The Space de Yoko.<\/p>\n<div id=\"bc-video-6353949261112\" class=\"brightcove\"><span class=\"article__bc_video-caption\">Encuentran y venden en subasta la guitarra perdida de John Lennon<\/span><\/div>\n<p>A medida que se desarrollaba como un m\u00fasico visionario por derecho propio, Yoko hab\u00eda reclutado a un grupo m\u00e1s experimentado que la banda de improvisaci\u00f3n informal Elephant&#8217;s Memory, involucrada en Sometime In New York City.<\/p>\n<p>Esto, a su vez, inspir\u00f3 a Lennon a grabar un \u00e1lbum m\u00e1s comercial con el mismo equipo, al que llam\u00f3 Plastic UFOno Band.<\/p>\n<p>Entre ellos se encontraba su amigo y baterista de sesi\u00f3n Jim Keltner (actualmente de gira con Bob Dylan), el guitarrista David Spinozza y otros que aportaban bajo, pedal steel, piano y saxof\u00f3n.<\/p>\n<p>Tambi\u00e9n a bordo para proporcionar los sensuales coros del \u00e1lbum estaba el grupo femenino Something Different.<\/p>\n<p>Fundamentalmente, este fue el primer LP autoproducido por Lennon y el primero sin Phil \u201cWall Of Sound\u201d Spector al mando.<\/p>\n<p>En las d\u00e9cadas transcurridas desde su lanzamiento, Mind Games ha sido considerado como uno de los logros menores de Lennon, aunque es conocido por su sublime canci\u00f3n principal, el humor peculiar de Bring On The Lucie (Freda People) y un par de baladas hermosas, Out Of The Blue y One Day (At A Time).<\/p>\n<p>Muchas de las otras canciones han pasado desapercibidas para los oyentes; tal vez la gente no se dio cuenta de lo personales que son y de lo mucho que revelan sobre el estado mental de Lennon.<\/p>\n<p>Ahora, 50 a\u00f1os despu\u00e9s, el \u00e1lbum merece desde hace tiempo una reevaluaci\u00f3n.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"3\"><a rel=\"nofollow\" href=\"#\"><img loading=\"lazy\" decoding=\"async\" alt=\"Mind Games fue el cuarto \u00e1lbum en solitario de John\" height=\"640\" width=\"960\" class=\"lazyload\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720742487_635_Antagonico-hermoso-profundo-visceral-simplemente-abre-tus-juegos-mentales\u2026-John.jpg\" data-credit=\"Supplied\" data- data-img=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720742487_635_Antagonico-hermoso-profundo-visceral-simplemente-abre-tus-juegos-mentales\u2026-John.jpg?strip=all&amp;w=960\"  role=\"img\"\/><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">3<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Mind Games fue el cuarto \u00e1lbum en solitario de John<\/span><span class=\"article__credit\">Cr\u00e9dito: suministrado<\/span><\/figcaption><\/figure>\n<p>Entonces, John Lennon Estate y Universal Music est\u00e1n lanzando ediciones Ultimate Collection de Mind Games que incluyen varios remixes, tomas in\u00e9ditas y temas instrumentales.<\/p>\n<p>Las mezclas de estudio en bruto son especialmente efectivas, como estar en el estudio con el gran hombre en persona.<\/p>\n<p>La colecci\u00f3n est\u00e1 autorizada por Yoko y producida por el \u00fanico hijo que tuvo con John, Sean Ono Lennon.<\/p>\n<p>Yoko, que ahora tiene 91 a\u00f1os, reflexiona sobre la canci\u00f3n principal del \u00e1lbum m\u00e1s subestimado de su difunto esposo: \u201cJohn estaba tratando de transmitir el mensaje de que todos jugamos juegos mentales.<\/p>\n<p>\u201cPero si podemos jugar a juegos mentales, \u00bfpor qu\u00e9 no crear un futuro positivo con ellos, para que sean un juego mental positivo?<\/p>\n<p>\u201cMind Games es una canci\u00f3n incre\u00edblemente fuerte. <\/p>\n<p>\u201cEn aquel momento, la gente no entendi\u00f3 bien el mensaje porque era algo prematuro. <\/p>\n<p>\u201cAhora la gente lo entender\u00e1.<\/p>\n<p>\u201cEn aquella \u00e9poca, no creo que la gente supiera que, de todos modos, estaban jugando juegos mentales\u201d.<\/p>\n<p>En una nueva entrevista con la revista Uncut, Sean dice que el \u00e1lbum fue el sonido de &#8220;mi padre volviendo al buen camino, despu\u00e9s de un per\u00edodo muy experimental y vol\u00e1til.<\/p>\n<p>\u201cCrec\u00ed escuch\u00e1ndolo sin darme cuenta de que, hasta cierto punto, hab\u00eda sido pasado por alto cuando sali\u00f3. <\/p>\n<p>\u201cPara m\u00ed siempre ha sido uno de sus discos m\u00e1s fuertes\u201d.<\/p>\n<p>Dependiendo de su nivel de inter\u00e9s en Lennon, las distintas ediciones nuevas ofrecen algo para todos, desde los obsesivos hasta los curiosos casuales.<\/p>\n<p>As\u00ed que es hora de escuchar Mind Games nuevamente, con la mente abierta.<\/p>\n<p>\u201cAs\u00ed que sigan jugando esos juegos mentales juntos\/Fe en el futuro, fuera del ahora\u201d.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/tvandshowbiz\/29153906\/john-lennon-solo-album-mind-games-beatles\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PIENSE en el nivel de creatividad alcanzado por The Beatles en su relativamente breve pero estelar carrera discogr\u00e1fica.<\/p>\n","protected":false},"author":1,"featured_media":1273009,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[1761,242015,213467,239506,4226,5538,538,97396,77,41174,4431,24899,97395,39033,48123,242014,16021,239922,240756,1618,383,116650,8410],"class_list":["post-1273008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-abre","tag-antagonico","tag-cola-larga","tag-el-periodico-the-sun","tag-estados-unidos","tag-hermoso","tag-john","tag-john-lennon","tag-juegos","tag-la-musica-rock","tag-lennon","tag-los-angeles","tag-los-beatles","tag-mentales","tag-musica-pop","tag-neil-lennon","tag-profundo","tag-relaciones-y-rupturas-entre-famosos","tag-seccion-showbizmusica","tag-simplemente","tag-tus","tag-visceral","tag-vuelto"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1273008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1273008"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1273008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1273009"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1273008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1273008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1273008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}