{"id":1273005,"date":"2024-07-11T23:59:23","date_gmt":"2024-07-11T23:59:23","guid":{"rendered":"https:\/\/teknomers.com\/es\/demanda-contra-mia-goth-violenta-en-el-set-de-filmacion-de-maxxxine-2\/"},"modified":"2024-07-11T23:59:31","modified_gmt":"2024-07-11T23:59:31","slug":"demanda-contra-mia-goth-violenta-en-el-set-de-filmacion-de-maxxxine-2","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/demanda-contra-mia-goth-violenta-en-el-set-de-filmacion-de-maxxxine-2\/","title":{"rendered":"Demanda contra Mia Goth: \u00bfViolenta en el set de filmaci\u00f3n de \u201cMaXXXine\u201d?"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Mia Goth, actriz y esposa de Shia LaBeouf, enfrenta serias acusaciones.<\/p>\n<p>Seg\u00fan informes de los medios, ella pate\u00f3 intencionalmente a un extra en la cabeza durante el rodaje de \u201cMaXXXine\u201d, lo que le provoc\u00f3 una conmoci\u00f3n cerebral y lo oblig\u00f3 a dejar de trabajar en el set antes de tiempo.<\/p>\n<p>En lugar de disculparse, se dice que Goth incluso humill\u00f3 al hombre despu\u00e9s.  Estas acusaciones han dado lugar a acciones legales que involucran al director Ti West y al estudio de cine A24.<\/p>\n<p>La pol\u00e9mica comenz\u00f3 con una demanda presentada por James Hunter, el extra implicado.  Hunter afirma que Goth lo atac\u00f3 intencionalmente durante una escena.  Seg\u00fan su demanda, Goth no solo lo atac\u00f3 f\u00edsicamente, sino que tambi\u00e9n se burl\u00f3 verbalmente.<\/p>\n<h2>Terror en el set<\/h2>\n<p>Durante una grabaci\u00f3n, Mia Goth casi pis\u00f3 la cabeza del hombre, dice la demanda.  Seg\u00fan los informes, a Goth le dijeron que tuviera cuidado.  Durante la siguiente grabaci\u00f3n, Goth dijo que intencionalmente pate\u00f3 al demandante en la cabeza con su bota.<\/p>\n<p>Seg\u00fan su propia declaraci\u00f3n, el incidente dej\u00f3 cicatrices f\u00edsicas y emocionales en la presunta v\u00edctima, oblig\u00e1ndola a abandonar el set.<\/p>\n<p>En una entrevista con el sitio de pel\u00edculas de terror Dread Central, Hunter describi\u00f3 c\u00f3mo Goth lo persigui\u00f3 para enfrentarlo despu\u00e9s de un incidente en el ba\u00f1o.<\/p>\n<p>Ella supuestamente le dijo: \u201cNadie te creer\u00e1 porque no eres nada.  L\u00e1rgate de mi set, beb\u00e9 gigante.<\/p>\n<p>Al d\u00eda siguiente, su agencia le inform\u00f3 que ya no era necesario para la producci\u00f3n, lo que puso a prueba a\u00fan m\u00e1s su situaci\u00f3n profesional.<\/p>\n<h2>La contraofensiva<\/h2>\n<p>Goth, West y el estudio de cine A24 rechazaron en\u00e9rgicamente las acusaciones de Hunter.  Destacan que defender\u00e1n con vehemencia a Goth y a todo el equipo de filmaci\u00f3n contra estas acusaciones.<\/p>\n<p>Una declaraci\u00f3n oficial de A24 describi\u00f3 las acusaciones de Hunter como &#8220;simplemente falsas&#8221; y cit\u00f3 la batalla legal en curso como una raz\u00f3n para no revelar m\u00e1s detalles.<\/p>\n<p>A pesar de la controversia, \u201cMaXXXine\u201d se estren\u00f3 con \u00e9xito, recaudando 6,7 millones de d\u00f3lares en sus primeros tres d\u00edas.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.musikexpress.de\/klage-gegen-mia-goth-gewalttaetig-am-maxxxine-filmset-2727253\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-29<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mia Goth, actriz y esposa de Shia LaBeouf, enfrenta serias acusaciones. Seg\u00fan informes de los medios, ella pate\u00f3<\/p>\n","protected":false},"author":1,"featured_media":1273006,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[241944,233365,110,3665,17357,350,94188,109919,29990,241945,13786,241946,239753,7076],"class_list":["post-1273005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-abuso-de-poder","tag-accion-legal","tag-contra","tag-demanda","tag-filmacion","tag-fuerza","tag-goth","tag-maxxxine","tag-mia","tag-mia-gotica","tag-set","tag-set-de-filmacion","tag-shia-labeouf","tag-violenta"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1273005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1273005"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1273005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1273006"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1273005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1273005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1273005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}