{"id":1272822,"date":"2024-07-11T21:01:08","date_gmt":"2024-07-11T21:01:08","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-principe-harry-aparece-en-un-nuevo-documental-dispuesto-a-hablar-con-la-boca-limpia\/"},"modified":"2024-07-11T21:01:12","modified_gmt":"2024-07-11T21:01:12","slug":"el-principe-harry-aparece-en-un-nuevo-documental-dispuesto-a-hablar-con-la-boca-limpia","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-principe-harry-aparece-en-un-nuevo-documental-dispuesto-a-hablar-con-la-boca-limpia\/","title":{"rendered":"El pr\u00edncipe Harry aparece en un nuevo documental: dispuesto a hablar con la boca limpia"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>El pr\u00edncipe Harry ha presentado un total de seis demandas contra los medios de comunicaci\u00f3n en los \u00faltimos a\u00f1os.<\/p>\n<div itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:76.13333333333333%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720731668_825_El-principe-Harry-aparece-en-un-nuevo-documental-dispuesto-a.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720731668_825_El-principe-Harry-aparece-en-un-nuevo-documental-dispuesto-a.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2284\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Prinssi Harry aikoo avata suunsa tuoreessa dokumentissa. \"\/><span class=\"caption-text\" itemprop=\"description\">El pr\u00edncipe Harry va a abrir la boca en un nuevo documental. <!-- --> <\/span><span class=\"media-source\">DOP<\/span><\/p>\n<\/div>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">El pr\u00edncipe Harry aparece en un nuevo documental donde planea hablar sobre el pirateo de su tel\u00e9fono y otras actividades consideradas ilegales por los tabloides brit\u00e1nicos.<\/p>\n<p class=\"paragraph\">documental de noticias <em>Tabloides a prueba<\/em> Se publicar\u00e1 el 25 de julio.<\/p>\n<p class=\"paragraph\">El duque de Sussex ha estado en guerra con los medios brit\u00e1nicos mucho antes de que \u00e9l y su esposa Meghan renunciaran a sus deberes reales en la corte en 2020. El pr\u00edncipe Harry ha presentado un total de seis demandas contra los medios en los \u00faltimos a\u00f1os.<\/p>\n<p class=\"paragraph\">Ha acusado a los tabloides brit\u00e1nicos de invadir su vida privada y acosar a su esposa y a la fallecida princesa Diana.  Tambi\u00e9n ha acusado a la prensa y al gobierno de parcialidad y corrupci\u00f3n.<\/p>\n<p class=\"paragraph\">La familia real brit\u00e1nica ha librado una guerra, entre otros, contra la empresa de medios Mirror Group Newspapers.  El a\u00f1o pasado, Harry dijo en un comunicado que debe revelar comportamiento ilegal porque no quiere que nadie m\u00e1s se encuentre en una situaci\u00f3n similar.<\/p>\n<p class=\"paragraph\">Harry ha considerado a la empresa de medios culpable de m\u00e9todos ilegales, como escuchas ilegales, en su adquisici\u00f3n de informaci\u00f3n.  El pr\u00edncipe Harry gan\u00f3 esa demanda el a\u00f1o pasado, cuando la Corte Suprema brit\u00e1nica determin\u00f3 que la compa\u00f1\u00eda hab\u00eda pirateado la informaci\u00f3n de Harry a lo largo de los a\u00f1os.<\/p>\n<p class=\"paragraph\">&#8211; En mi opini\u00f3n, para salvar el periodismo, los periodistas deben denunciar a aquellos medios que han usurpado los privilegios y el poder de la prensa y han utilizado medios ilegales para obtener ganancias, escribi\u00f3 el pr\u00edncipe en su declaraci\u00f3n.<\/p>\n<p class=\"paragraph\">Tambi\u00e9n aleg\u00f3 que la prensa brit\u00e1nica y el gobierno est\u00e1n &#8220;en el fondo&#8221;.  En 2021, en una entrevista con Oprah Winfrey, Harry argument\u00f3 que si una fuente de informaci\u00f3n es corrupta, sesgada o racista, afecta a toda la sociedad.<\/p>\n<p class=\"paragraph\">Fuente: <a rel=\"noopener nofollow\" href=\"https:\/\/www.express.co.uk\/news\/royal\/1921498\/prince-harry-itv-documentary-phone-hacking\" target=\"_blank\">Expresar<\/a>.<\/p>\n<div class=\"iltv-embed\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/VideoObject\"><meta itemprop=\"name\" content=\"Videolla ote prinssi Harryn aiemmasta kohuhaastattelusta.\"\/><meta itemprop=\"caption\" content=\"Videolla ote prinssi Harryn aiemmasta kohuhaastattelusta.\"\/><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/cdn.jwplayer.com\/v2\/media\/NNxftWtI\/poster.jpg?width=720\"\/><meta itemprop=\"uploadDate\" content=\"2024-07-11T19:49:38+03:00\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Videolla ote prinssi Harryn aiemmasta kohuhaastattelusta.\"\/><span class=\"caption-text\" itemprop=\"description\">En el v\u00eddeo, un extracto de la entrevista anterior del Pr\u00edncipe Harry.<!-- --> <\/span><span class=\"media-source\"\/><\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/kuninkaalliset\/a\/8f29bd58-636f-461f-a7a1-9dafc68afd58\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-50<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00edncipe Harry ha presentado un total de seis demandas contra los medios de comunicaci\u00f3n en los \u00faltimos<\/p>\n","protected":false},"author":1,"featured_media":1272823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[84803,9229,6521,99,3688,10728,26776,1009,202303,2592,315,4567,13755,20031,480,2091,8108],"class_list":["post-1272822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-24-horas","tag-aparece","tag-boca","tag-con","tag-delincuente","tag-derecho","tag-dispuesto","tag-documental","tag-familias-de-celebridades","tag-famosos","tag-hablar","tag-harry","tag-justicia-y-crimen","tag-limpia","tag-nuevo","tag-principe","tag-realeza"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1272822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1272822"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1272822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1272823"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1272822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1272822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1272822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}