{"id":1272720,"date":"2024-07-11T19:30:09","date_gmt":"2024-07-11T19:30:09","guid":{"rendered":"https:\/\/teknomers.com\/es\/bono-psicologo-2024-llegan-los-rankings-inps-aqui-se-explica-como-comprobar-si-la-solicitud-ha-sido-aceptada\/"},"modified":"2024-07-11T19:30:14","modified_gmt":"2024-07-11T19:30:14","slug":"bono-psicologo-2024-llegan-los-rankings-inps-aqui-se-explica-como-comprobar-si-la-solicitud-ha-sido-aceptada","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/bono-psicologo-2024-llegan-los-rankings-inps-aqui-se-explica-como-comprobar-si-la-solicitud-ha-sido-aceptada\/","title":{"rendered":"Bono psic\u00f3logo 2024, llegan los rankings INPS: aqu\u00ed se explica c\u00f3mo comprobar si la solicitud ha sido aceptada"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>Escuche la versi\u00f3n en audio del art\u00edculo.<\/button><\/p>\n<p class=\"atext\">Una vez concluida la investigaci\u00f3n preliminar sobre las solicitudes para 2024 (relativas a la asignaci\u00f3n de fondos para 2023) para la provisi\u00f3n de la contribuci\u00f3n para cubrir los gastos relacionados con las sesiones de psicoterapia (el llamado &#8220;Bono Psic\u00f3logo&#8221;), el INPS informa que ha elaborado el ranking, desglosado por Comunidades y Provincias aut\u00f3nomas de residencia.  Los beneficiarios, explica la instituci\u00f3n de seguridad social en <b>mensaje 2584<\/b> del jueves 11 de julio, fueron identificadas teniendo en cuenta el valor del indicador de situaci\u00f3n econ\u00f3mica equivalente m\u00e1s bajo (Isee) y, con el mismo valor ISEE, el orden cronol\u00f3gico de presentaci\u00f3n de las solicitudes, dentro de los l\u00edmites del monto de los recursos.  El apoyo fue establecido por la ley 15 de 2022.<\/p>\n<p><h2 id=\"U12748324422uXp\">C\u00f3mo comprobar si se ha aceptado la solicitud del bono psic\u00f3logo<\/h2>\n<\/p>\n<p class=\"atext\">\u00bfC\u00f3mo comprobar si se ha aceptado la solicitud del bono psic\u00f3logo?  Desde la p\u00e1gina de inicio del sitio web del INPS es posible acceder a la p\u00e1gina dedicada al servicio escribiendo las palabras &#8220;bono de psic\u00f3logo&#8221; en el campo de b\u00fasqueda de texto y luego seleccionando el servicio &#8220;Contribuci\u00f3n para cubrir los costos de las sesiones de psicoterapia &#8211; Bono de psic\u00f3logo&#8221; .  En esta p\u00e1gina, explica la instituci\u00f3n de seguridad social en la ponderaci\u00f3n, est\u00e1n disponibles: la ficha informativa de la medida, los tutoriales para el ciudadano y para el profesional que participa en la iniciativa y el enlace para acceder al servicio (&#8220;Usar el servicio &#8220;), para lo cual se requiere autenticaci\u00f3n con su identidad digital, SPID nivel 2 o superior, C\u00e9dula de Identidad Electr\u00f3nica (CIE) 3.0 o Tarjeta de Servicios Nacionales (CNS);  una vez autenticados, los solicitantes pueden consultar el resultado de la solicitud y, en caso de resultado positivo, el importe de la aportaci\u00f3n reconocida y el c\u00f3digo \u00fanico asignado para beneficiarse de las sesiones de psicoterapia.<\/p>\n<p><h2 id=\"U06815248176HSa\">Para aprovechar el bono 270 d\u00edas a partir del 11 de julio <\/h2>\n<\/p>\n<p class=\"atext\">En el documento, el INPS recuerda que el beneficiario dispone de 270 d\u00edas a partir de la fecha de publicaci\u00f3n del mensaje, y por tanto a partir del 11 de julio, para beneficiarse de la aportaci\u00f3n de apoyo a las sesiones de psicoterapia.  Pasado este plazo, el c\u00f3digo \u00fanico asignado queda autom\u00e1ticamente cancelado.<\/p>\n<p><h2 id=\"U47363251063cfo\">Un m\u00e1ximo de 50 euros por cada sesi\u00f3n de psicoterapia. <\/h2>\n<\/p>\n<p class=\"atext\">La bonificaci\u00f3n se reconoce por un importe m\u00e1ximo de 50 euros por cada sesi\u00f3n de psicoterapia y se abona hasta el importe m\u00e1ximo asignado, vinculado a los valores ISEE.<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"row row--dotted\">\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/consigli24.ilsole24ore.com\/2024\/06\/27\/prime-day-2024\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/tariffe.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/06\/Decreto-de-cohesion-solicitud-bipartidista-para-liberar-inmediatamente-la-cofinanciacion.png\" alt=\"Saber m\u00e1s\"\/><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/bonus-psicologo-2024-arrivano-graduatorie-inps-ecco-come-controllare-se-domanda-e-stata-accettata-AFN0sqlC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escuche la versi\u00f3n en audio del art\u00edculo. Una vez concluida la investigaci\u00f3n preliminar sobre las solicitudes para 2024<\/p>\n","protected":false},"author":1,"featured_media":1272721,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[39467,303,2905,440,69858,1149,43721,8614,36,12360,116468,1382,1178],"class_list":["post-1272720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-aceptada","tag-aqui","tag-bono","tag-como","tag-comprobar","tag-explica","tag-inps","tag-llegan","tag-los","tag-psicologo","tag-rankings","tag-sido","tag-solicitud"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1272720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1272720"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1272720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1272721"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1272720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1272720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1272720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}