{"id":1272680,"date":"2024-07-11T18:48:07","date_gmt":"2024-07-11T18:48:07","guid":{"rendered":"https:\/\/teknomers.com\/es\/jurgen-klopp-rechaza-oferta-de-trabajo-el-exitoso-entrenador-rechaza-ee-uu\/"},"modified":"2024-07-11T18:48:11","modified_gmt":"2024-07-11T18:48:11","slug":"jurgen-klopp-rechaza-oferta-de-trabajo-el-exitoso-entrenador-rechaza-ee-uu","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/jurgen-klopp-rechaza-oferta-de-trabajo-el-exitoso-entrenador-rechaza-ee-uu\/","title":{"rendered":"J\u00fcrgen Klopp rechaza oferta de trabajo: el exitoso entrenador rechaza EE.UU."},"content":{"rendered":"\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"font-bold text-18 leading-17\">Las cosas se han calmado en torno a J\u00fcrgen Klopp.  Pero ahora Estados Unidos revivi\u00f3 su nombre y recibi\u00f3 el rechazo.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">J\u00fcrgen Klopp no \u200b\u200bser\u00e1 el seleccionador nacional de Estados Unidos.  Como informa el informado periodista de &#8220;The Athletic&#8221; David Ornstein, el exitoso entrenador alem\u00e1n cancel\u00f3 la sede del Mundial de 2026.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El peri\u00f3dico \u201cThe Independent\u201d ya hab\u00eda informado anteriormente de que se hab\u00edan producido contactos desde Estados Unidos.  Dos a\u00f1os antes del Mundial en casa, el equipo del jugador estrella Christian Pulisic ya hab\u00eda sido eliminado en la fase de grupos de la Copa Am\u00e9rica y se separ\u00f3 del entrenador Gregg Berhalter.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Berhalter fue entrenador de Estados Unidos durante seis a\u00f1os e incluso gan\u00f3 la \u201cCopa de Oro\u201d, el Campeonato de Am\u00e9rica del Norte y Central, en 2021.  Pero la bochornosa salida en la fase de grupos de la actual Copa Am\u00e9rica sell\u00f3 su destituci\u00f3n.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Al parecer, la asociaci\u00f3n pens\u00f3 en Klopp para el gran proyecto de devolver a Estados Unidos al camino del \u00e9xito.  Pero no se dej\u00f3 disuadir de su plan de tomarse al menos un a\u00f1o de descanso tras su dimisi\u00f3n del Liverpool FC.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Klopp explic\u00f3 en enero: &#8220;Es como si me estuviera quedando sin energ\u00eda. Obviamente no tengo ning\u00fan problema en este momento. Sab\u00eda desde hace tiempo que tendr\u00eda que anunciarlo en alg\u00fan momento, pero ahora todo est\u00e1 bien&#8221;. completamente bien. Pero s\u00e9 que no puedo hacer el trabajo una y otra vez y otra y otra vez&#8221;.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">El hombre de 57 a\u00f1os incluso se mostr\u00f3 dispuesto a poner fin a su carrera por completo.  Sin embargo, los funcionarios estadounidenses esperaban una excepci\u00f3n, pero ahora tienen que adoptar un enfoque diferente.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/fussball\/international\/id_100446684\/juergen-klopp-lehnt-jobangebot-ab-erfolgstrainer-gibt-usa-einen-korb.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las cosas se han calmado en torno a J\u00fcrgen Klopp. Pero ahora Estados Unidos revivi\u00f3 su nombre y<\/p>\n","protected":false},"author":1,"featured_media":1272352,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[102204,238433,1289,47591,752,942,132340,11491,4041,9329,1817,235033,11630,1602],"class_list":["post-1272680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-christian-pulisic","tag-david-ornstein","tag-ee-uu","tag-el-atletico","tag-entrenador","tag-exitoso","tag-gregg-berhalter","tag-jurgen","tag-jurgen-klopp","tag-klopp","tag-oferta","tag-oferta-de-trabajo","tag-rechaza","tag-trabajo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1272680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1272680"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1272680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1272352"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1272680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1272680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1272680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}