{"id":1272601,"date":"2024-07-11T17:32:27","date_gmt":"2024-07-11T17:32:27","guid":{"rendered":"https:\/\/teknomers.com\/es\/informes-el-traslado-de-kamara-a-furth-fracaso-ya-estaba-de-camino-al-control-medico\/"},"modified":"2024-07-11T17:32:32","modified_gmt":"2024-07-11T17:32:32","slug":"informes-el-traslado-de-kamara-a-furth-fracaso-ya-estaba-de-camino-al-control-medico","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/informes-el-traslado-de-kamara-a-furth-fracaso-ya-estaba-de-camino-al-control-medico\/","title":{"rendered":"Informes: El traslado de Kamara a F\u00fcrth fracas\u00f3; ya estaba de camino al control m\u00e9dico"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>debe ser vendido <\/p>\n<div class=\"newsBild\">\n<p>\n                                       <span>\u00a9IMAGO<\/span>\n                                    <\/p>\n<\/p><\/div>\n<p>El traspaso de Abdoulaye Kamara al SpVgg Greuther F\u00fcrth fracas\u00f3 en la recta final.  El joven de 19 a\u00f1os del Borussia Dortmund ya estaba camino a un control m\u00e9dico, pero seg\u00fan informes constantes tuvo que dar marcha atr\u00e1s.  A diferencia de Serhou Guirassy, \u200b\u200blos motivos no fueron de car\u00e1cter m\u00e9dico.  Seg\u00fan los informes, los dos clubes no llegaron a un acuerdo en las conversaciones finales, probablemente por motivos econ\u00f3micos.<\/p>\n<p><\/p>\n<p>Ingo Preu\u00df, director deportivo del filial de Dortmund, pregunt\u00f3 a &#8220;Ruhr Nachrichten&#8221; que no hab\u00eda ninguna lesi\u00f3n y que Kamara estaba al 100 por ciento.  El centrocampista defensivo, que lleg\u00f3 procedente del Par\u00eds Saint-Germain en 2021 y desde entonces ha estado esperando en vano su avance, ahora ha regresado a la concentraci\u00f3n del equipo de tercera divisi\u00f3n en los Alpes de Kitzb\u00fchel.<\/p>\n<p><\/p>\n<p>La salida de Kamara todav\u00eda se considera muy posible.  Un a\u00f1o antes de que finalice el contrato, los responsables del Dortmund quieren acabar con el personal y cobrar una peque\u00f1a suma por el traspaso.  El franc\u00e9s de origen guineano no jug\u00f3 un solo partido con los profesionales; con el segundo equipo apareci\u00f3 47 veces (un gol, cuatro asistencias).<\/p>\n<p><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.transfermarkt.de\/furth-transfer-von-kamara-geplatzt-bvb-talent-war-schon-auf-dem-weg-zum-medizincheck\/view\/news\/440556\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-38<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>debe ser vendido \u00a9IMAGO El traspaso de Abdoulaye Kamara al SpVgg Greuther F\u00fcrth fracas\u00f3 en la recta final.<\/p>\n","protected":false},"author":1,"featured_media":1272602,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[201084,1705,241648,3480,1706,614,2343,4114,6567,8664,2932,22404,3435,9163,1438],"class_list":["post-1272601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-2-a-bundesliga","tag-3ra-liga","tag-abdoulaye-kamara","tag-borussia-dortmund","tag-borussia-dortmund-ii","tag-camino","tag-control","tag-estaba","tag-fracaso","tag-furth","tag-informes","tag-kamara","tag-medico","tag-spvgg-greuther-furth","tag-traslado"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1272601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1272601"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1272601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1272602"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1272601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1272601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1272601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}