{"id":1271702,"date":"2024-07-11T02:37:14","date_gmt":"2024-07-11T02:37:14","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-sensacion-de-las-redes-sociales-chinas-xiaohongshu-obtiene-un-importante-respaldo-de-capital-de-riesgo-extranjero\/"},"modified":"2024-07-11T02:37:18","modified_gmt":"2024-07-11T02:37:18","slug":"la-sensacion-de-las-redes-sociales-chinas-xiaohongshu-obtiene-un-importante-respaldo-de-capital-de-riesgo-extranjero","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-sensacion-de-las-redes-sociales-chinas-xiaohongshu-obtiene-un-importante-respaldo-de-capital-de-riesgo-extranjero\/","title":{"rendered":"La sensaci\u00f3n de las redes sociales chinas Xiaohongshu obtiene un importante respaldo de capital de riesgo extranjero"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Desbloquea el Editor&#8217;s Digest gratis<\/p>\n<p class=\"article__content-sign-up-topic-description\"><span>Roula Khalaf, editora del FT, selecciona sus historias favoritas en este bolet\u00edn semanal.<\/span><\/p>\n<p><iframe class=\"article__content-sign-up-iframe close\" scrolling=\"no\" id=\"signUpIframe\" data-prev-url=\"\/register\/in-article-sign-up?ft-content-uuid=2d5f515f-d341-41c8-ace5-16a16cb33e35\"><\/iframe><\/div>\n<div id=\"article-body\">\n<p>Xiaohongshu, la plataforma de redes sociales de m\u00e1s r\u00e1pido crecimiento de China, ha obtenido el respaldo de la firma de capital de riesgo DST Global en un raro ejemplo de inversores extranjeros que ponen dinero en un sector tecnol\u00f3gico que ha rechazado en gran medida desde la ofensiva de Beijing. <\/p>\n<p>La plataforma para compartir fotograf\u00edas y videos, muy popular entre las mujeres que viven en las ciudades, organiz\u00f3 ventas de participaciones de acciones existentes en las \u00faltimas semanas a inversores actuales y nuevos que valoraron la empresa en 17.000 millones de d\u00f3lares, seg\u00fan tres personas con conocimiento del asunto. <\/p>\n<p>DST, fundada por el empresario tecnol\u00f3gico israel\u00ed nacido en Mosc\u00fa Yuri Milner y ex inversor de Facebook, particip\u00f3 en la ronda junto con HongShan, con sede en Hong Kong, anteriormente Sequoia China, que aument\u00f3 su participaci\u00f3n existente. Las firmas de capital privado chinas Hillhouse Investment, Boyu Capital y Citic Capital tambi\u00e9n invirtieron. No se pudo determinar el tama\u00f1o de la inversi\u00f3n de DST.<\/p>\n<p>Xiaohongshu, DST, HongShan y Citic declinaron hacer comentarios. Hillhouse y Boyu no respondieron a las solicitudes de comentarios. <\/p>\n<p>El voto de confianza llega despu\u00e9s de que Xiaohongshu, que se traduce como &#8220;peque\u00f1o libro rojo&#8221; y que tambi\u00e9n cuenta con el respaldo de la firma de capital riesgo GSR Ventures y el inversor estatal de Singapur Temasek, se volviera rentable en 2023. El a\u00f1o pasado obtuvo un beneficio neto de 500 millones de d\u00f3lares sobre unos ingresos de 3.700 millones de d\u00f3lares, seg\u00fan inform\u00f3 anteriormente el Financial Times. Por el contrario, en 2022 registr\u00f3 una p\u00e9rdida de 200 millones de d\u00f3lares sobre unos ingresos de unos 2.000 millones de d\u00f3lares.<\/p>\n<p>De manera inusual, Xiaohongshu tambi\u00e9n cuenta con el respaldo de los gigantes chinos de Internet Tencent y Alibaba, y las empresas emergentes generalmente tienen que elegir entre ellos para invertir. El apoyo de ambas partes significa que es poco probable que sea un objetivo de adquisici\u00f3n para cualquiera de los dos grupos, dado su veto efectivo sobre una venta a un rival, seg\u00fan personas familiarizadas con el asunto. <\/p>\n<p>Los inversores apuestan a que Xiaohongshu forma parte de un peque\u00f1o grupo de unicornios tecnol\u00f3gicos chinos que pueden esperar una oferta p\u00fablica inicial de gran \u00e9xito despu\u00e9s de registrar un fuerte crecimiento.<\/p>\n<p>Xiaohongshu alcanz\u00f3 312 millones de usuarios activos mensuales en 2023, un aumento del 20 por ciento respecto al a\u00f1o anterior, lo que la convirti\u00f3 en la plataforma de redes sociales de mayor crecimiento en China el a\u00f1o pasado, seg\u00fan un c\u00e1lculo del Financial Times.<\/p>\n<p>En el momento \u00e1lgido de las valoraciones de las empresas emergentes de Internet chinas en 2021, Xiaohongshu fue valorada en 20.000 millones de d\u00f3lares en una ronda de financiaci\u00f3n que incluy\u00f3 a Temasek. Esta cifra cay\u00f3 a 14.000 millones de d\u00f3lares a finales del a\u00f1o pasado, en dos operaciones separadas en las que la empresa de capital riesgo Gaorong Capital, con sede en Pek\u00edn, y HongShan compraron participaciones de Genesis Capital, con sede en China, y Granite Asia, antes conocida como GGV, respectivamente, seg\u00fan personas con conocimiento del asunto. <\/p>\n<p>Genesis Capital, Gaorong Capital y Granite Asia no respondieron a las solicitudes de comentarios. <\/p>\n<p>\u201cXiaohongshu alcanz\u00f3 una valoraci\u00f3n de 20.000 millones de d\u00f3lares durante el pico de inversi\u00f3n de capital riesgo en tecnolog\u00eda. Pero a diferencia de muchas otras empresas emergentes que se ven obligadas a realizar sucesivas rondas de inversi\u00f3n o a cerrar, est\u00e1 creciendo dentro de su valoraci\u00f3n\u201d, dijo un inversor de capital riesgo en Shangh\u00e1i. <\/p>\n<p>La confianza de los inversores en Xiaohongshu se ha visto reforzada por sus s\u00f3lidos resultados financieros y ha reavivado las esperanzas de que Pek\u00edn vuelva a ver con buenos ojos la salida a bolsa de grandes empresas tecnol\u00f3gicas en el extranjero. Han pasado tres a\u00f1os desde la desastrosa salida a Bolsa en Nueva York del grupo de transporte de pasajeros DiDi, que m\u00e1s tarde se retir\u00f3 de la bolsa al convertirse en una de las v\u00edctimas de una ofensiva m\u00e1s amplia de Pek\u00edn contra los gigantes tecnol\u00f3gicos del pa\u00eds.<\/p>\n<aside aria-labelledby=\"aside-label\" class=\"n-content-recommended--single-story n-content-recommended--inset\" data-component=\"recommended\">\n<p class=\"n-content-recommended__title\">Recomendado<\/p>\n<div class=\"o-teaser o-teaser--article o-teaser--small o-teaser--stacked o-teaser--has-image js-teaser\" data-id=\"aa8f30f4-d3ef-4188-b64d-82bab354f187\">\n<div class=\"o-teaser__image-container js-teaser-image-container\">\n<div class=\"o-teaser__image-placeholder\" style=\"aspect-ratio:2289\/1287\"><\/div>\n<\/div>\n<\/div>\n<\/aside>\n<p>Un inversor advirti\u00f3 que la riqueza de informaci\u00f3n sobre consumidores de Xiaohongshu podr\u00eda complicar cualquier plan potencial de lanzar una IPO en el extranjero, dadas las restricciones de Beijing al intercambio transfronterizo de datos. <\/p>\n<p>Xiaohongshu es un manual de referencia para los viajeros chinos internacionales que buscan consejos sobre restaurantes y tiendas. La empresa ha estado ampliando su equipo de desarrollo comercial en el extranjero para explorar los mercados populares entre los turistas chinos y atraer a m\u00e1s anunciantes a la plataforma, seg\u00fan una persona con conocimiento del tema. <\/p>\n<p>Xiaohongshu tambi\u00e9n se ha vuelto importante para los minoristas que buscan aumentar sus audiencias y ha estado ofreciendo promover nuevas empresas de inteligencia artificial en su plataforma a cambio de capital, inform\u00f3 FT anteriormente. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ft.com\/content\/2d5f515f-d341-41c8-ace5-16a16cb33e35\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-56<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desbloquea el Editor&#8217;s Digest gratis Roula Khalaf, editora del FT, selecciona sus historias favoritas en este bolet\u00edn semanal.<\/p>\n","protected":false},"author":1,"featured_media":1271703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3775,14087,50,2001,246,11660,253,20020,4578,1753,254,126646],"class_list":["post-1271702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-capital","tag-chinas","tag-extranjero","tag-importante","tag-las","tag-obtiene","tag-redes","tag-respaldo","tag-riesgo","tag-sensacion","tag-sociales","tag-xiaohongshu"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1271702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1271702"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1271702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1271703"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1271702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1271702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1271702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}